{"id":46329,"date":"2015-01-20T12:07:43","date_gmt":"2015-01-20T11:07:43","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/cmc-italia-coach-professionisti-della-mente\/"},"modified":"2020-08-10T01:03:05","modified_gmt":"2020-08-09T23:03:05","slug":"cmc-italia-coach-professionisti-della-mente","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/cmc-italia-coach-professionisti-della-mente\/","title":{"rendered":"CMC Italia Coach: professionisti della mente"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"\/uploads\/images\/u_41022\/thumb_CMCItaliaCoach.gif\" border=\"0\" width=\"224\" height=\"224\" \/> I <a href=\"http:\/\/www.corso-mental-coaching.it\/albo-coach\/\" target=\"_blank\" title=\"CMC Italia Coach\" rel=\"noopener noreferrer\"><strong>CMC Italia Coach<\/strong><\/a> sono persone pronte a dedicare tempo e risorse per aiutare le persone a credere in se stessi e raggiungere traguardi importanti.<br \/>Ad oggi i <strong>Coach CMC Italia<\/strong> a cui &egrave; stata rilasciata la qualifica di Certified Mental Coach, dopo aver preso parte al percorso di formazione e superato un esame che attestasse le competenze raggiunte, sono oltre 30.<br \/>I <strong>CMC Italia Coach<\/strong> sono diversi tra loro, non esiste un prototipo ideale di coach, anzi la diversit&agrave; &egrave; apprezzata e considerata molto stimolante perch&eacute; permette di <em>creare un percorso basato sull&rsquo;esigenze del singolo individuo<\/em>, facendolo sentire unico e speciale. Qualsiasi individuo dotato di seriet&agrave;, desiderio di mettersi in gioco e di aiutare le persone a migliorare la propria vita, pu&ograve; aspirare a diventare un <strong>CMC Italia Coach<\/strong>.<\/p>\n<p>Sostanzialmente i <strong>CMC Italia coach<\/strong> si suddividono in tre grandi categorie <strong>Business, Life e Sport<\/strong>, a seconda generalmente della professione che svolgono e per la quale essere in possesso di una <strong>certificazione di mental coaching<\/strong> risulta essere un <strong>valore aggiunto alla propria persona<\/strong> nonch&eacute; un ottimo <strong>strumento per migliorare la proprie ed altrui performance, <\/strong>per <strong>lavorare su se stessi <\/strong>ma anche <strong>trovare clienti a cui offrire i loro servizi professionali da coach<\/strong>. Ovviamente specializzarsi in uno di questi tre campi non esclude la possibilit&agrave; di conseguirne una seconda, se non addirittura una terza; la met&agrave; dei nostri <strong>CMC Italia Coach<\/strong> &egrave;, infatti, in possesso di una <strong>doppia qualifica<\/strong>, fortemente voluta per essere di ulteriore <em>aiuto ai propri coachee<\/em>, essere <em>preparati su pi&ugrave; fronti<\/em> e avere <em>pi&ugrave; opportunit&agrave; in termini di lavoro<\/em>.<br \/>&Egrave; doveroso sottolineare come i <strong>CMC Italia Coach sportivi<\/strong> siano, rispetto alle altre due aree, in <strong>netta superiorit&agrave;<\/strong>, dovuta forse al fatto che nel mondo dello sport il fattore mente ha preso sempre pi&ugrave; piede in questi ultimi anni, arrivando a considerare l&rsquo;allenamento mentale importante quanto quello fisico.<br \/>Ecco l&rsquo;elenco completo dei nostri <strong>CMC Italia Coach<\/strong>, suddivisi in categorie:<\/p>\n<p><strong>CMC Italia Coach Business<\/strong>:<br \/>Appartengono al mondo degli affari, sono dunque consapevoli di come funzionino le complicate dinamiche lavorative di questo settore e si offrono di aiutare il proprio cliente ad acquisire maggiore sicurezza dei propri mezzi nel caso quest&rsquo;ultimo sia una persona timida, imparare a delegare se l&rsquo;uomo in questione risulta essere un dirigente troppo concentrato sul proprio lavoro e poco su tutto il resto, vita privata in primis, a diventare un leader carismatico qualora il coachee desiderasse fare il salto di qualit&agrave; e diventare un manager di successo.<\/p>\n<ul>\n<\/p>\n<li>Anghelone Antonio<\/li>\n<p><\/p>\n<li>Cerato Sandro<\/li>\n<p><\/p>\n<li>Moltoni Maurizia<\/li>\n<p><\/p>\n<li>Zucchi Gianzelio<\/li>\n<p> \n<\/ul>\n<p><strong>CMC Italia Coach Life<\/strong>:<br \/>Sono professionisti il cui obiettivo &egrave; andare a migliorare la vita quotidiana dei clienti, hanno quindi un margine d&rsquo;azione molto largo perch&eacute; possono intervenire su diverse problematiche, tra cui studenti che non si sentono motivati e hanno difficolt&agrave; di concentrazione a scuola, genitori che non si sentono all&rsquo;altezza del proprio ruolo, professori che vorrebbero essere di ulteriore supporto ai propri allievi.<\/p>\n<ul>\n<\/p>\n<li>Cassini Antonio<\/li>\n<p><\/p>\n<li>Cesaroni Roberta<\/li>\n<p><\/p>\n<li>Marchiorello Silvia<\/li>\n<p> \n<\/ul>\n<p><strong>CMC Italia Coach Sport<\/strong>:<br \/>In questo campo &egrave; una qualifica che risulta essere molto apprezzata, soprattutto perch&eacute; generalmente sono in primis degli allenatori o hanno avuto un passato da giocatori. Essere dotati di competenze tecniche e allo stesso tempo possedere la capacit&agrave; di analizzare la mente dei propri atleti, insegnandoli a gestire situazioni caratterizzate da forte stress, a credere in loro stessi e motivandoli nella giusta maniera, aumenter&agrave; indubbiamente la possibilit&agrave; di ottenere una grande performance e raggiungere l&rsquo;esito sperato.<\/p>\n<ul>\n<\/p>\n<li>Amendola Paolo<\/li>\n<p><\/p>\n<li>Barba Stefano<\/li>\n<p><\/p>\n<li>Cavalieri Nicol&ograve;<\/li>\n<p><\/p>\n<li>D&rsquo;Attile Sonia<\/li>\n<p><\/p>\n<li>Iozzia Giuseppe<\/li>\n<p><\/p>\n<li>Magnani Tommaso<\/li>\n<p><\/p>\n<li>Masu Arianna<\/li>\n<p><\/p>\n<li>Milano Giulia<\/li>\n<p><\/p>\n<li>Morales Massimo<\/li>\n<p><\/p>\n<li>Pietro Pepe<\/li>\n<p><\/p>\n<li>Scarpato Gippo<\/li>\n<p> \n<\/ul>\n<p><strong>CMC Italia Coach Business &amp; Sport<\/strong>:<\/p>\n<ul>\n<\/p>\n<li>Binelli Massimo<\/li>\n<p><\/p>\n<li>Bredice Marcello<\/li>\n<p><\/p>\n<li>Dallafina Stefano<\/li>\n<p> \n<\/ul>\n<p><strong>CMC Italia Coach Sport &amp; Life<\/strong>:<\/p>\n<ul>\n<\/p>\n<li>Canzi Mario<\/li>\n<p><\/p>\n<li>Fasoli Camilla<\/li>\n<p><\/p>\n<li>Fusco Salvatore<\/li>\n<p><\/p>\n<li>Kharwb Mohamed<\/li>\n<p><\/p>\n<li>Lumbau Paola<\/li>\n<p><\/p>\n<li>Ugolini Francesco<\/li>\n<p> \n<\/ul>\n<p><strong>CMC Italia Coach Life &amp; Business<\/strong>:<\/p>\n<ul>\n<\/p>\n<li>Della Puppa Cristina<\/li>\n<p><\/p>\n<li>Farioli Andrea<\/li>\n<p><\/p>\n<li>Giachini Matteo<\/li>\n<p><\/p>\n<li>Gritti Giovanni<\/li>\n<p><\/p>\n<li>Jaramillo Silvia<\/li>\n<p><\/p>\n<li>Vanzanelli Daniele<\/li>\n<p> \n<\/ul>\n<p><strong>CMC Italia Coach Sport, Life &amp; Business:<\/strong><br \/>Ad oggi &egrave; l&rsquo;unico con una tripla specializzazione.<\/p>\n<ul>\n<\/p>\n<li>Campomori Franco<\/li>\n<p> \n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Ecco chi sono i CMC Italia Coach: i professionisti italiani del Mental Coaching.<br \/>I CMC Italia Coach sono persone pronte a dedicare tempo e risorse per aiutare le persone a credere in se stessi e raggiungere traguardi importanti.<\/p>\n<p>Ad oggi i Coach CMC Italia a cui \u00e8 stata rilasciata la qualifica di Certified Mental Coach, dopo aver preso parte al percorso di formazione e superato un esame che attestasse le competenze raggiunte, sono oltre 30.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[429],"tags":[49799,50264],"class_list":["post-46329","post","type-post","status-publish","format-standard","hentry","category-professionisti","tag-cmc-italia","tag-cmc-italia-coach"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CMC Italia Coach: professionisti della mente - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/cmc-italia-coach-professionisti-della-mente\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CMC Italia Coach: professionisti della mente - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Ecco chi sono i CMC Italia Coach: i professionisti italiani del Mental Coaching.I CMC Italia Coach sono persone pronte a dedicare tempo e risorse per aiutare le persone a credere in se stessi e raggiungere traguardi importanti.Ad oggi i Coach CMC Italia a cui \u00e8 stata rilasciata la qualifica di Certified Mental Coach, dopo aver preso parte al percorso di formazione e superato un esame che attestasse le competenze raggiunte, sono oltre 30.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/cmc-italia-coach-professionisti-della-mente\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2015-01-20T11:07:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-09T23:03:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.article-marketing.eu\/uploads\/images\/u_41022\/thumb_CMCItaliaCoach.gif\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/cmc-italia-coach-professionisti-della-mente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/cmc-italia-coach-professionisti-della-mente\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"CMC Italia Coach: professionisti della mente\",\"datePublished\":\"2015-01-20T11:07:43+00:00\",\"dateModified\":\"2020-08-09T23:03:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/cmc-italia-coach-professionisti-della-mente\\\/\"},\"wordCount\":702,\"commentCount\":0,\"keywords\":[\"cmc italia\",\"cmc italia coach\"],\"articleSection\":[\"Professionisti\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/cmc-italia-coach-professionisti-della-mente\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/cmc-italia-coach-professionisti-della-mente\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/cmc-italia-coach-professionisti-della-mente\\\/\",\"name\":\"CMC Italia Coach: professionisti della mente - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2015-01-20T11:07:43+00:00\",\"dateModified\":\"2020-08-09T23:03:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/cmc-italia-coach-professionisti-della-mente\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/cmc-italia-coach-professionisti-della-mente\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/cmc-italia-coach-professionisti-della-mente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CMC Italia Coach: professionisti della mente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CMC Italia Coach: professionisti della mente - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/cmc-italia-coach-professionisti-della-mente\/","og_locale":"it_IT","og_type":"article","og_title":"CMC Italia Coach: professionisti della mente - Article Marketing","og_description":"Ecco chi sono i CMC Italia Coach: i professionisti italiani del Mental Coaching.I CMC Italia Coach sono persone pronte a dedicare tempo e risorse per aiutare le persone a credere in se stessi e raggiungere traguardi importanti.Ad oggi i Coach CMC Italia a cui \u00e8 stata rilasciata la qualifica di Certified Mental Coach, dopo aver preso parte al percorso di formazione e superato un esame che attestasse le competenze raggiunte, sono oltre 30.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/cmc-italia-coach-professionisti-della-mente\/","og_site_name":"Article Marketing","article_published_time":"2015-01-20T11:07:43+00:00","article_modified_time":"2020-08-09T23:03:05+00:00","og_image":[{"url":"https:\/\/www.article-marketing.eu\/uploads\/images\/u_41022\/thumb_CMCItaliaCoach.gif","type":"","width":"","height":""}],"author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/cmc-italia-coach-professionisti-della-mente\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/cmc-italia-coach-professionisti-della-mente\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"CMC Italia Coach: professionisti della mente","datePublished":"2015-01-20T11:07:43+00:00","dateModified":"2020-08-09T23:03:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/cmc-italia-coach-professionisti-della-mente\/"},"wordCount":702,"commentCount":0,"keywords":["cmc italia","cmc italia coach"],"articleSection":["Professionisti"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/cmc-italia-coach-professionisti-della-mente\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/cmc-italia-coach-professionisti-della-mente\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/cmc-italia-coach-professionisti-della-mente\/","name":"CMC Italia Coach: professionisti della mente - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2015-01-20T11:07:43+00:00","dateModified":"2020-08-09T23:03:05+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/cmc-italia-coach-professionisti-della-mente\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/cmc-italia-coach-professionisti-della-mente\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/cmc-italia-coach-professionisti-della-mente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"CMC Italia Coach: professionisti della mente"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/46329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=46329"}],"version-history":[{"count":1,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/46329\/revisions"}],"predecessor-version":[{"id":66881,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/46329\/revisions\/66881"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=46329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=46329"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=46329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}