{"id":46332,"date":"2015-01-20T12:41:06","date_gmt":"2015-01-20T11:41:06","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/vestire-uomo-corso-consulenza-abbigliamento-maschile\/"},"modified":"2018-10-25T23:10:28","modified_gmt":"2018-10-25T21:10:28","slug":"vestire-uomo-corso-consulenza-abbigliamento-maschile","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/abbigliamento\/vestire-uomo-corso-consulenza-abbigliamento-maschile\/","title":{"rendered":"VESTIRE UOMO: Corso Consulenza Abbigliamento Maschile"},"content":{"rendered":"<p><em style=\"mso-bidi-font-style: normal;\">Vestire gli uomini richiede competenze profonde e articolate possedute oggi solo da pochi esperti. Con la serie di corsi &ldquo;Vestire Uomo&rdquo;,Fainomai e Camicia&amp;Cravatta formeranno e aggiorneranno le competenze di operatori e professionisti italiani del settore <\/em><br \/>\n<em style=\"mso-bidi-font-style: normal;\"><\/em> <strong style=\"mso-bidi-font-weight: normal;\"> <\/strong> <strong style=\"mso-bidi-font-weight: normal;\">Bergamo, <\/strong>15 gennaio 2015. <strong style=\"mso-bidi-font-weight: normal;\">Fainomai<\/strong>, specialista nella formazione alla comunicazione visiva, in collaborazione con <strong style=\"mso-bidi-font-weight: normal;\">Camicia&amp;Cravatta<\/strong>, blog leader nel settore dell&rsquo;immagine e stile maschile, presenta &ldquo;<strong style=\"mso-bidi-font-weight: normal;\">Vestire Uomo<\/strong>&rdquo;, un ampio programma di corsi di consulenza per l&rsquo;abbigliamento maschile. <br \/> I corsi, strutturati su due livelli e che copriranno tutto il territorio nazionale, sono rivolti a <strong style=\"mso-bidi-font-weight: normal;\">consulenti d&rsquo;immagine<\/strong>, <strong style=\"mso-bidi-font-weight: normal;\">personal shopper<\/strong>, <strong style=\"mso-bidi-font-weight: normal;\">stylist<\/strong>, <strong style=\"mso-bidi-font-weight: normal;\">wedding planner<\/strong>, <strong style=\"mso-bidi-font-weight: normal;\">sale manager<\/strong> e <strong style=\"mso-bidi-font-weight: normal;\">sale assistant<\/strong> di negozi d&rsquo;abbigliamento che desiderino espandere la loro conoscenza e aumentare la gamma e la qualit&agrave; dei propri servizi. Potranno ovviamente partecipare anche a tutti gli interessati a intraprendere queste professioni in piena espansione, apprendendone i segreti da tutor e formatori specializzati nel curare l&rsquo;immagine maschile e attivi in questo affascinante campo da quasi un decennio. Organizzati con la tecnica del roadshow, i corsi copriranno tutta Italia con le tappe di <strong style=\"mso-bidi-font-weight: normal;\">Milano<\/strong>, <strong style=\"mso-bidi-font-weight: normal;\">Firenze<\/strong>, <strong style=\"mso-bidi-font-weight: normal;\">Roma<\/strong> e <strong style=\"mso-bidi-font-weight: normal;\">Lecce<\/strong>, per valicare infine il confine con la tappa conclusiva di <strong style=\"mso-bidi-font-weight: normal;\">Lugano, <\/strong>e saranno articolati in due week&ndash;end full immersion, nel corso dei quali i partecipanti impareranno i fondamenti e le tecniche per gestire al meglio l&rsquo;immagine dell&rsquo;uomo tramite la conoscenza di tutte le varie e complesse componenti che riguardano il suo abbigliamento. In particolare, nel corso del primo week end (Modulo Base) verranno insegnate le tecniche necessarie per vestire l&rsquo;uomo in maniera coerente e valorizzante mentre nel secondo weekend (Modulo Pro) verr&agrave; approfondita la conoscenza dei singoli capi di abbigliamento maschile insegnando ai partecipanti come compiere scelte di buon gusto ed eleganza in funzione di bisogni, desideri contesti e stili di vita. Il grado di dettaglio dei contenuti sar&agrave; estremamente marcato e per ogni capo esaminato verranno analizzati modelli, tessuti\/materiali, colori, dettagli e il suo corretto utilizzo nei vari contesti. &ldquo;L&rsquo;idea di questi corsi nasce dalla riflessione che la consulenza per l&rsquo;abbigliamento maschile in passato era una professione che richiedeva profonde conoscenze e competenze di rilievo specifico. Poi il mondo della moda e dell&rsquo;abbigliamento femminile hanno preso il sopravvento accentrando l&rsquo;attenzione di tutti gli operatori e portando erroneamente a credere che quello fosse l&rsquo;unico ambito con necessit&agrave; di know how e competenze specifiche, e che chiunque fosse invece in grado di vestire gli uomini. In realt&agrave; questo &egrave; stato un grande equivoco, che ha generato gravissime lacune nella formazione degli addetti ai lavori, danneggiando per conseguenza l&rsquo;intero comparto del business della moda maschile.&rdquo; sottolineano la dottoressa Teresa Rota, presidente di Fainomai, azienda impegnata nel campo della consulenza d&#8217;immagine personale e aziendale, e Simonetta Zamperlini, che svolge con passione e profonda padronanza del mestiere, l&rsquo;attivit&agrave; di personal styling maschile, autrice di diversi manuali sull&rsquo;argomento e fondatrice di &ldquo;Camicia e Cravatta&rdquo;, blog punto di riferimento per tutti gli uomini che, desiderano, per la vita sociale e professionale, migliorare la propria immagine in termini di comunicazione. <strong style=\"mso-bidi-font-weight: normal;\"> <\/strong> <strong style=\"mso-bidi-font-weight: normal;\">Vestire Uomo &#8211; Corso di abbigliamento maschile &ndash; <\/strong> <strong style=\"mso-bidi-font-weight: normal;\">Sedi e date<\/strong> <strong style=\"mso-bidi-font-weight: normal;\"> <\/strong> <strong style=\"mso-bidi-font-weight: normal;\"> <\/strong> <strong style=\"mso-bidi-font-weight: normal;\">Milano<\/strong> 14 e 15 febbraio 28 febbraio e 1 marzo 2015 <strong style=\"mso-bidi-font-weight: normal;\">Firenze<\/strong> 14 e 15 marzo 28 e 29 marzo 2015 <strong style=\"mso-bidi-font-weight: normal;\"><\/strong> <strong style=\"mso-bidi-font-weight: normal;\">Roma<\/strong> 18 e 19 aprile 9 e 10 maggio 2015 <strong style=\"mso-bidi-font-weight: normal;\"><\/strong> <strong style=\"mso-bidi-font-weight: normal;\">Lugano<\/strong> 23 e 24 maggio 6 e 7 giugno 2015 <strong style=\"mso-bidi-font-weight: normal;\"><\/strong> <strong style=\"mso-bidi-font-weight: normal;\">Lecce<\/strong> 20 e 21 giugno 27 e 28 giugno 2015 <strong style=\"mso-bidi-font-weight: normal;\"><\/strong> <strong style=\"mso-bidi-font-weight: normal;\">FAINOMAI<\/strong> (www.fainomai.it), che deriva il suo nome dal greco antico &ldquo;apparire, mostrarsi&rdquo;, trova il proprio core business nella formazione professionale alla comunicazione non verbale attraverso il canale visivo. Insegnando le tecniche di valorizzazione dell&rsquo;immagine in tutte le sue forme, Fainomai forma imprenditori, manager, professionisti e politici a porsi nel modo migliore in ogni contesto. <strong style=\"mso-bidi-font-weight: normal;\">Immagine personale <\/strong>&ndash; Formazione al sapersi mostrare, per dare il meglio di s&eacute; in ogni contesto fin dalla prima impressione e sentirsi sempre in armonia con se stessi e con chi sta attorno <strong style=\"mso-bidi-font-weight: normal;\">Immagine aziendale <\/strong>&ndash; Formazione all&rsquo;arte di emergere, farsi notare e scegliere nel mondo del lavoro, attraverso un aspetto professionale distintivo e identificante <strong style=\"mso-bidi-font-weight: normal;\">Seminari e workshop<\/strong> &ndash; Eventi per piccoli gruppi su argomenti legati all&rsquo;immagine personale e al mondo del lavoro <strong style=\"mso-bidi-font-weight: normal;\"><\/strong> <strong style=\"mso-bidi-font-weight: normal;\">CAMICIA&amp;CRAVATTA<\/strong> (http:\/\/camiciaecravatta.com) Blog con la missione di &ldquo;<em style=\"mso-bidi-font-style: normal;\">Aiutare gli uomini a vestire bene per diventare pi&ugrave; sicuri di s&eacute;<\/em>&rdquo; e usare la propria immagine come spinta verso il successo personale e sociale. Fondato nel 2010, &egrave; stato il primo blog a trattare professionalmente l&rsquo;abbigliamento classico maschile in modo divulgativo, semplice e accessibile a tutti ed a istituire corsi online rivolti a uomini in cerca della soluzione pi&ugrave; giusta per il proprio guardaroba. Vanta migliaia di contatti quotidiani altamente profilati con uomini attenti a migliorare il proprio loro stile Per maggiori informazioni <strong style=\"mso-bidi-font-weight: normal;\">Camicia&amp;Cravatta<\/strong> <em style=\"mso-bidi-font-style: normal;\">camiciaecravatta.com <\/em> contatto@camiciaecravatta.com <strong style=\"mso-bidi-font-weight: normal;\">Fainomai<\/strong> www.fainomai.it Via Pietro Ruggieri da Stabello, 26 24123 Bergamo Tel: +39 335 7898710 info@fainomai.it<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vestire gli uomini richiede competenze profonde e articolate possedute oggi solo da pochi esperti. Con la serie di corsi \u201cVestire Uomo\u201d,Fainomai e Camicia&#038;Cravatta formeranno e aggiorneranno le competenze di operatori e professionisti italiani del settore<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[3429],"tags":[1007,50266,50265,3368,5000,309,85,19106,4635],"class_list":["post-46332","post","type-post","status-publish","format-standard","hentry","category-abbigliamento","tag-abbigliamento","tag-bespoke","tag-consuleza","tag-lusso","tag-manager","tag-moda","tag-politica","tag-sartoria","tag-uomo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>VESTIRE UOMO: Corso Consulenza Abbigliamento Maschile - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/societa\/abbigliamento\/vestire-uomo-corso-consulenza-abbigliamento-maschile\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VESTIRE UOMO: Corso Consulenza Abbigliamento Maschile - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Vestire gli uomini richiede competenze profonde e articolate possedute oggi solo da pochi esperti. Con la serie di corsi \u201cVestire Uomo\u201d,Fainomai e Camicia&amp;Cravatta formeranno e aggiorneranno le competenze di operatori e professionisti italiani del settore\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/societa\/abbigliamento\/vestire-uomo-corso-consulenza-abbigliamento-maschile\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2015-01-20T11:41:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-25T21:10:28+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/abbigliamento\\\/vestire-uomo-corso-consulenza-abbigliamento-maschile\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/abbigliamento\\\/vestire-uomo-corso-consulenza-abbigliamento-maschile\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"VESTIRE UOMO: Corso Consulenza Abbigliamento Maschile\",\"datePublished\":\"2015-01-20T11:41:06+00:00\",\"dateModified\":\"2018-10-25T21:10:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/abbigliamento\\\/vestire-uomo-corso-consulenza-abbigliamento-maschile\\\/\"},\"wordCount\":844,\"commentCount\":0,\"keywords\":[\"abbigliamento\",\"bespoke\",\"consuleza\",\"lusso\",\"manager\",\"moda\",\"politica\",\"sartoria\",\"uomo\"],\"articleSection\":[\"Abbigliamento e accessori\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/abbigliamento\\\/vestire-uomo-corso-consulenza-abbigliamento-maschile\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/abbigliamento\\\/vestire-uomo-corso-consulenza-abbigliamento-maschile\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/abbigliamento\\\/vestire-uomo-corso-consulenza-abbigliamento-maschile\\\/\",\"name\":\"VESTIRE UOMO: Corso Consulenza Abbigliamento Maschile - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2015-01-20T11:41:06+00:00\",\"dateModified\":\"2018-10-25T21:10:28+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/abbigliamento\\\/vestire-uomo-corso-consulenza-abbigliamento-maschile\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/abbigliamento\\\/vestire-uomo-corso-consulenza-abbigliamento-maschile\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/abbigliamento\\\/vestire-uomo-corso-consulenza-abbigliamento-maschile\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"VESTIRE UOMO: Corso Consulenza Abbigliamento Maschile\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VESTIRE UOMO: Corso Consulenza Abbigliamento Maschile - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/abbigliamento\/vestire-uomo-corso-consulenza-abbigliamento-maschile\/","og_locale":"it_IT","og_type":"article","og_title":"VESTIRE UOMO: Corso Consulenza Abbigliamento Maschile - Article Marketing","og_description":"Vestire gli uomini richiede competenze profonde e articolate possedute oggi solo da pochi esperti. Con la serie di corsi \u201cVestire Uomo\u201d,Fainomai e Camicia&Cravatta formeranno e aggiorneranno le competenze di operatori e professionisti italiani del settore","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/abbigliamento\/vestire-uomo-corso-consulenza-abbigliamento-maschile\/","og_site_name":"Article Marketing","article_published_time":"2015-01-20T11:41:06+00:00","article_modified_time":"2018-10-25T21:10:28+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/abbigliamento\/vestire-uomo-corso-consulenza-abbigliamento-maschile\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/abbigliamento\/vestire-uomo-corso-consulenza-abbigliamento-maschile\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"VESTIRE UOMO: Corso Consulenza Abbigliamento Maschile","datePublished":"2015-01-20T11:41:06+00:00","dateModified":"2018-10-25T21:10:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/abbigliamento\/vestire-uomo-corso-consulenza-abbigliamento-maschile\/"},"wordCount":844,"commentCount":0,"keywords":["abbigliamento","bespoke","consuleza","lusso","manager","moda","politica","sartoria","uomo"],"articleSection":["Abbigliamento e accessori"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/societa\/abbigliamento\/vestire-uomo-corso-consulenza-abbigliamento-maschile\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/abbigliamento\/vestire-uomo-corso-consulenza-abbigliamento-maschile\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/abbigliamento\/vestire-uomo-corso-consulenza-abbigliamento-maschile\/","name":"VESTIRE UOMO: Corso Consulenza Abbigliamento Maschile - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2015-01-20T11:41:06+00:00","dateModified":"2018-10-25T21:10:28+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/abbigliamento\/vestire-uomo-corso-consulenza-abbigliamento-maschile\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/societa\/abbigliamento\/vestire-uomo-corso-consulenza-abbigliamento-maschile\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/abbigliamento\/vestire-uomo-corso-consulenza-abbigliamento-maschile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"VESTIRE UOMO: Corso Consulenza Abbigliamento Maschile"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/46332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=46332"}],"version-history":[{"count":1,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/46332\/revisions"}],"predecessor-version":[{"id":64461,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/46332\/revisions\/64461"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=46332"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=46332"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=46332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}