{"id":46591,"date":"2015-04-22T16:47:56","date_gmt":"2015-04-22T14:47:56","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/nasce-inventiamolo-il-primo-social-network-per-inventori\/"},"modified":"2015-04-22T16:47:56","modified_gmt":"2015-04-22T14:47:56","slug":"nasce-inventiamolo-il-primo-social-network-per-inventori","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/internet\/nasce-inventiamolo-il-primo-social-network-per-inventori\/","title":{"rendered":"Nasce Inventiamolo il primo Social Network per Inventori"},"content":{"rendered":"<p><a href=\"\/uploads\/images\/u_42774\/51b8e24e0f0a462183da040d6db0467b.jpg\" class=\"image\"><img decoding=\"async\" src=\"\/uploads\/images\/u_42774\/51b8e24e0f0a462183da040d6db0467b.jpg\" border=\"0\" \/><\/a><\/p>\n<p>A chi non &egrave; mai venuto in mente un progetto da sperimentare? Un&rsquo;idea da<br \/> concretizzare? Una soluzione che riteneva adatta a risolvere un problema, ma mai<br \/> applicata per mancanza di conoscenze tecniche o scarsa visibilit&agrave;?<br \/> Oggi sembra proprio che i creativi non debbano pi&ugrave; preoccuparsi di tutto ci&ograve;: la<br \/> soluzione &egrave; Inventiamolo.<br \/> Si tratta del primo Social Network Italiano per Inventori, totalmente gratuito, che<br \/> verr&agrave; lanciato sul web il 1 maggio 2015 e che consentir&agrave; un confronto, uno scambio e<br \/> una promozione di idee. Gli utenti, dopo la registrazione o l&rsquo;accesso tramite l&rsquo;account<br \/> di Facebook, potranno usufruire dei vantaggi che offre il portale. Sar&agrave; possibile,<br \/> infatti, proporre il proprio progetto, creare gruppi di lavoro e partecipare a progetti<br \/> gi&agrave; in corso. Inoltre, Inventiamolo dar&agrave; la possibilit&agrave; agli utenti di usufruire di una<br \/> vetrina virtuale gratuita, dove poter esporre il proprio progetto, in modo da garantirne<br \/> una maggiore visibilit&agrave;. Inventiamolo, oltre ad offrire spunti per nuove idee o per<br \/> perfezionarle, consente agli utenti e ai collaboratori di trarre un profitto, dato dalla<br \/> percentuale della vendita dei progetti e la cessione di licenze e basato sulle capacit&agrave;,<br \/> il livello di partecipazione e il feedback.<br \/> Il punto di forza di Inventiamolo sta nel programma &ldquo;Ricerca Low Cost&rdquo;, che<br \/> permette di ridurre notevolmente i costi di ricerca e offre l&rsquo;opportunit&agrave; di lavorare a<br \/> progetti per Aziende.<br \/> I progetti proposti saranno valutati, selezionati e classificati da un gruppo di<br \/> controllo, in modo da offrire all&rsquo;investitore una panoramica chiara ed esaustiva di<br \/> tutte le tipologie di investimento nei diversi settori e progetti<br \/> Per favorire la conoscenza di questo nuovo servizio virtuale, sar&agrave; offerta la possibilit&agrave;<br \/> di effettuare una prova, che consentir&agrave; di sperimentare questo strumento, valutarlo e<br \/> comprendere come utilizzarlo al meglio.<br \/> Quindi non aspettate a sperimentare subito questo innovativo strumento! Visitate il<br \/> sito www.inventiamolo.it , effettuate una prima prova e date visibilit&agrave; alle vostre<br \/> idee! Per qualsiasi domanda o chiarimento potete scrivere a info@inventiamolo.it<br \/>\nA chi non &egrave; mai venuto in mente un progetto da sperimentare? Un&rsquo;idea da<br \/> concretizzare? Una soluzione che riteneva adatta a risolvere un problema, ma mai<br \/> applicata per mancanza di conoscenze tecniche o scarsa visibilit&agrave;?<br \/> Oggi sembra proprio che i creativi non debbano pi&ugrave; preoccuparsi di tutto ci&ograve;: la<br \/> soluzione &egrave; Inventiamolo.<br \/> Si tratta del primo Social Network Italiano per Inventori, totalmente gratuito, che<br \/> verr&agrave; lanciato sul web il 1 maggio 2015 e che consentir&agrave; un confronto, uno scambio e<br \/> una promozione di idee. Gli utenti, dopo la registrazione o l&rsquo;accesso tramite l&rsquo;account<br \/> di Facebook, potranno usufruire dei vantaggi che offre il portale. Sar&agrave; possibile,<br \/> infatti, proporre il proprio progetto, creare gruppi di lavoro e partecipare a progetti<br \/> gi&agrave; in corso. Inoltre, Inventiamolo dar&agrave; la possibilit&agrave; agli utenti di usufruire di una<br \/> vetrina virtuale gratuita, dove poter esporre il proprio progetto, in modo da garantirne<br \/> una maggiore visibilit&agrave;. Inventiamolo, oltre ad offrire spunti per nuove idee o per<br \/> perfezionarle, consente agli utenti e ai collaboratori di trarre un profitto, dato dalla<br \/> percentuale della vendita dei progetti e la cessione di licenze e basato sulle capacit&agrave;,<br \/> il livello di partecipazione e il feedback.<br \/> Il punto di forza di Inventiamolo sta nel programma &ldquo;Ricerca Low Cost&rdquo;, che<br \/> permette di ridurre notevolmente i costi di ricerca e offre l&rsquo;opportunit&agrave; di lavorare a<br \/> progetti per Aziende.<br \/> I progetti proposti saranno valutati, selezionati e classificati da un gruppo di<br \/> controllo, in modo da offrire all&rsquo;investitore una panoramica chiara ed esaustiva di<br \/> tutte le tipologie di investimento nei diversi settori e progetti<br \/> Per favorire la conoscenza di questo nuovo servizio virtuale, sar&agrave; offerta la possibilit&agrave;<br \/> di effettuare una prova, che consentir&agrave; di sperimentare questo strumento, valutarlo e<br \/> comprendere come utilizzarlo al meglio.<br \/> Quindi non aspettate a sperimentare subito questo innovativo strumento! Visitate il<br \/> sito www.inventiamolo.it , effettuate una prima prova e date visibilit&agrave; alle vostre<br \/> idee! Per qualsiasi domanda o chiarimento potete scrivere a info@inventiamolo.it<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si tratta del primo Social Network Italiano per Inventori, totalmente gratuito, che verr\u00e0 lanciato sul web il 1 maggio 2015<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[466],"tags":[45299,1828,1392,2595,48895,49007,259],"class_list":["post-46591","post","type-post","status-publish","format-standard","hentry","category-internet","tag-brevetti","tag-futuro","tag-gratis","tag-idee","tag-inventori","tag-invenzioni","tag-tecnologia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nasce Inventiamolo il primo Social Network per Inventori - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/internet\/nasce-inventiamolo-il-primo-social-network-per-inventori\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nasce Inventiamolo il primo Social Network per Inventori - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Si tratta del primo Social Network Italiano per Inventori, totalmente gratuito, che verr\u00e0 lanciato sul web il 1 maggio 2015\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/internet\/nasce-inventiamolo-il-primo-social-network-per-inventori\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-22T14:47:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.article-marketing.eu\/uploads\/images\/u_42774\/51b8e24e0f0a462183da040d6db0467b.jpg\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/internet\\\/nasce-inventiamolo-il-primo-social-network-per-inventori\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/internet\\\/nasce-inventiamolo-il-primo-social-network-per-inventori\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Nasce Inventiamolo il primo Social Network per Inventori\",\"datePublished\":\"2015-04-22T14:47:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/internet\\\/nasce-inventiamolo-il-primo-social-network-per-inventori\\\/\"},\"wordCount\":704,\"commentCount\":0,\"keywords\":[\"brevetti\",\"futuro\",\"gratis\",\"idee\",\"inventori\",\"invenzioni\",\"tecnologia\"],\"articleSection\":[\"Internet\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/internet\\\/nasce-inventiamolo-il-primo-social-network-per-inventori\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/internet\\\/nasce-inventiamolo-il-primo-social-network-per-inventori\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/internet\\\/nasce-inventiamolo-il-primo-social-network-per-inventori\\\/\",\"name\":\"Nasce Inventiamolo il primo Social Network per Inventori - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2015-04-22T14:47:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/internet\\\/nasce-inventiamolo-il-primo-social-network-per-inventori\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/internet\\\/nasce-inventiamolo-il-primo-social-network-per-inventori\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/internet\\\/nasce-inventiamolo-il-primo-social-network-per-inventori\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nasce Inventiamolo il primo Social Network per Inventori\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nasce Inventiamolo il primo Social Network per Inventori - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/internet\/nasce-inventiamolo-il-primo-social-network-per-inventori\/","og_locale":"it_IT","og_type":"article","og_title":"Nasce Inventiamolo il primo Social Network per Inventori - Article Marketing","og_description":"Si tratta del primo Social Network Italiano per Inventori, totalmente gratuito, che verr\u00e0 lanciato sul web il 1 maggio 2015","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/internet\/nasce-inventiamolo-il-primo-social-network-per-inventori\/","og_site_name":"Article Marketing","article_published_time":"2015-04-22T14:47:56+00:00","og_image":[{"url":"https:\/\/www.article-marketing.eu\/uploads\/images\/u_42774\/51b8e24e0f0a462183da040d6db0467b.jpg","type":"","width":"","height":""}],"author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/internet\/nasce-inventiamolo-il-primo-social-network-per-inventori\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/internet\/nasce-inventiamolo-il-primo-social-network-per-inventori\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Nasce Inventiamolo il primo Social Network per Inventori","datePublished":"2015-04-22T14:47:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/internet\/nasce-inventiamolo-il-primo-social-network-per-inventori\/"},"wordCount":704,"commentCount":0,"keywords":["brevetti","futuro","gratis","idee","inventori","invenzioni","tecnologia"],"articleSection":["Internet"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/internet\/nasce-inventiamolo-il-primo-social-network-per-inventori\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/internet\/nasce-inventiamolo-il-primo-social-network-per-inventori\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/internet\/nasce-inventiamolo-il-primo-social-network-per-inventori\/","name":"Nasce Inventiamolo il primo Social Network per Inventori - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2015-04-22T14:47:56+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/internet\/nasce-inventiamolo-il-primo-social-network-per-inventori\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/internet\/nasce-inventiamolo-il-primo-social-network-per-inventori\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/internet\/nasce-inventiamolo-il-primo-social-network-per-inventori\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Nasce Inventiamolo il primo Social Network per Inventori"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/46591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=46591"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/46591\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=46591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=46591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=46591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}