{"id":47045,"date":"2015-03-04T09:45:23","date_gmt":"2015-03-04T08:45:23","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/ad-avellino-si-presentano-la-fiera-della-ceramica-e-sud-con-gusto\/"},"modified":"2015-03-04T09:45:23","modified_gmt":"2015-03-04T08:45:23","slug":"ad-avellino-si-presentano-la-fiera-della-ceramica-e-sud-con-gusto","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/news-e-attualita\/ad-avellino-si-presentano-la-fiera-della-ceramica-e-sud-con-gusto\/","title":{"rendered":"Ad Avellino si presentano la Fiera della Ceramica e Sud con Gusto"},"content":{"rendered":"<p>Si accendono i riflettori sulla &ldquo;Fiera della Ceramica Artistica Tradizionale e dell&#8217;Artigianato 2.0&rdquo; e sulla Fiera Nazionale &#8220;Sud con Gusto&#8221;, i prossimi eventi ad essere ospitati presso il Centro Fieristico Fiere della Campania di Ariano Irpino (AV) che saranno presentati venerd&igrave; 6 marzo 2015, alle ore 10:30, presso la Sala Grasso di Palazzo Caracciolo, ad Avellino. Sud con Gusto e la Fiera della Ceramica, rispettivamente alla IV edizione e alla prima edizione, rappresentano un momento di scambio, conoscenza e approfondimento, l&rsquo;uno sulle eccellenze del comparto agro-alimentare del Mezzogiorno d&rsquo;Italia e l&rsquo;altro sulla tradizione dell&rsquo;antica arte della ceramica italiana. I due eventi fieristici si svolgeranno in contemporanea a partire da venerd&igrave; 20 fino a domenica 22 marzo 2015. Prenderanno parte alla conferenza stampa: <strong>Francesco Lo Conte<\/strong>, Amministratore Unico Fiere e Congressi; <strong>Domenico Gambacorta<\/strong>, Presidente Provincia di Avellino; <strong>Carmine Famiglietti<\/strong>, Presidente Comunit&agrave; Montana dell&#8217;Ufita; <strong>Mario Manganiello<\/strong>, Assessore Comune di Ariano Irpino e <strong>Lucio Rubano<\/strong>, Vice Presidente AiCC. Saranno presenti, inoltre: <strong>Mario Pagliaro<\/strong>, Bottega delle Mani; <strong>Annarita Fasano,<\/strong> Presidente Associazione Pandora; <strong>Gabriella Taddeo<\/strong>, Museo Citt&agrave; Creativa di Ogliara; <strong>Ottavio D&#8217;Antuono<\/strong>, Storico della ceramica; <strong>Enzo Angiuoni<\/strong>, Artista della Ceramica, <strong>Luigi Russo<\/strong>, Ceramista; i Rappresentanti delle Citt&agrave; della Ceramica campane e i Dirigenti Scolastici degli Istituti d&#8217;Arte.<br \/> <strong>Antonio di Martino<\/strong>, Avvocato; <strong>Lucio Napodano, <\/strong>Consigliere Nazionale Slow Food. Concluder&agrave; l&rsquo;incontro <strong>Vittorio Fucci,<\/strong> Assessore Regione Campania Commercio e Artigianato.Ricchissimo il programma di iniziative che saranno illustrate per l&rsquo;occasione. La Fiera della Ceramica Artistica Tradizionale e dell&#8217;Artigianato 2.0 coniuga il vecchio e il nuovo mondo della ceramica sintetizzando in un&rsquo;innovativa soluzione l&rsquo;antica tradizione di questa espressione artigianale con le nuove frontiere del digitale. L&rsquo;evento &egrave; patrocinato dall&rsquo;AICC &ndash; Associazione Italiana Citt&agrave; della Ceramica, di cui la citt&agrave; di Ariano Irpino &egrave; socia. L&rsquo;Associazione Citt&agrave; della Ceramica esporr&agrave;, per l&rsquo;occasione, la mostra &ldquo;Grand Tour&rdquo;, a cura di Jean Blanchaert, Viola Emaldi e Anty Pansera, con il coordinamento di Giuseppe Olmeti. Il percorso artistico, recentemente presentato a Bruxelles, consta di una selezione di ceramiche di antica tradizione scelte dalla collezione di rappresentanza di AiCC. Spazio anche all&rsquo;artigianato femminile con l&rsquo;Associazione Onlus Pandora che presenter&agrave; il &ldquo;Progetto Ceramica Donna&rdquo; . Le Artiste-Ceramiste salernitane prenderanno parte all&rsquo;evento con un percorso espositivo interamente dedicato alla manifattura e alla passione delle donne per questa antica tradizione italiana, con particolare riferimento alla memoria salernitana. Diversi gli interventi, i workshop e le iniziative previste nei tre giorni e dedicate ai vari aspetti dell&rsquo;interessante mondo dell&rsquo;artigianato artistico. Saranno esposte, inoltre, alcune opere del Museo Citt&agrave; Creativa di Salerno e quelle del Progetto GIPSOS di Antonio Di Rosa. Parallelamente alla Fiera della Ceramica si svolger&agrave; la IV edizione di Sud con Gusto, arricchita da laboratori e aree di degustazione, vendita dei prodotti tipici, conferenze, dibattiti, workshop, showcooking, dimostrazioni di lavorazione dei prodotti ed esibizioni di cake design. Proprio agli appassionati del genere &egrave; dedicato il concorso &ldquo;Torte in Fiera&rdquo; che si svolger&agrave; il 21 marzo e vedr&agrave; il rinomato pasticciere salernitano Sal de Riso, premiare i vincitori. A completare il tutto vi sar&agrave; lo &ldquo;Street Food Festival&rdquo;, kermesse gastronomica dedicata alla diverse tipologie di cibi da strada. Nel complesso, l&rsquo;evento rappresenta un&rsquo;opportunit&agrave; di promozione commerciale delle aziende operanti nel settore, un momento di scambio con i diversi interlocutori e un&rsquo;occasione per valorizzare le eccellenze nazionali e in particolare del Mezzogiorno d&rsquo;Italia. L&rsquo;appuntamento &egrave; quindi per il prossimo 6 marzo presso Palazzo Caracciolo, sede della Provincia di Avellino, dove si conosceranno nel dettaglio gli obiettivi, le curiosit&agrave; e tutte attivit&agrave; che saranno realizzate in occasione dell&rsquo;imminente apertura della tre giorni arianese. <strong>Per info: <\/strong>www.fiereecongressi.eu<strong><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Palazzo Caracciolo, sede dell\u2019ente provinciale, ospiter\u00e0, venerd\u00ec 6 marzo, la conferenza stampa dedicata agli eventi fieristici in programma presso il Fiere della Campania a partire dal 20 marzo.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[81],"tags":[],"class_list":["post-47045","post","type-post","status-publish","format-standard","hentry","category-news-e-attualita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ad Avellino si presentano la Fiera della Ceramica e Sud con Gusto - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/societa\/news-e-attualita\/ad-avellino-si-presentano-la-fiera-della-ceramica-e-sud-con-gusto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ad Avellino si presentano la Fiera della Ceramica e Sud con Gusto - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Palazzo Caracciolo, sede dell\u2019ente provinciale, ospiter\u00e0, venerd\u00ec 6 marzo, la conferenza stampa dedicata agli eventi fieristici in programma presso il Fiere della Campania a partire dal 20 marzo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/societa\/news-e-attualita\/ad-avellino-si-presentano-la-fiera-della-ceramica-e-sud-con-gusto\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-04T08:45:23+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/news-e-attualita\\\/ad-avellino-si-presentano-la-fiera-della-ceramica-e-sud-con-gusto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/news-e-attualita\\\/ad-avellino-si-presentano-la-fiera-della-ceramica-e-sud-con-gusto\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Ad Avellino si presentano la Fiera della Ceramica e Sud con Gusto\",\"datePublished\":\"2015-03-04T08:45:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/news-e-attualita\\\/ad-avellino-si-presentano-la-fiera-della-ceramica-e-sud-con-gusto\\\/\"},\"wordCount\":664,\"commentCount\":0,\"articleSection\":[\"News e Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/news-e-attualita\\\/ad-avellino-si-presentano-la-fiera-della-ceramica-e-sud-con-gusto\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/news-e-attualita\\\/ad-avellino-si-presentano-la-fiera-della-ceramica-e-sud-con-gusto\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/news-e-attualita\\\/ad-avellino-si-presentano-la-fiera-della-ceramica-e-sud-con-gusto\\\/\",\"name\":\"Ad Avellino si presentano la Fiera della Ceramica e Sud con Gusto - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2015-03-04T08:45:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/news-e-attualita\\\/ad-avellino-si-presentano-la-fiera-della-ceramica-e-sud-con-gusto\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/news-e-attualita\\\/ad-avellino-si-presentano-la-fiera-della-ceramica-e-sud-con-gusto\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/societa\\\/news-e-attualita\\\/ad-avellino-si-presentano-la-fiera-della-ceramica-e-sud-con-gusto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ad Avellino si presentano la Fiera della Ceramica e Sud con Gusto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ad Avellino si presentano la Fiera della Ceramica e Sud con Gusto - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/news-e-attualita\/ad-avellino-si-presentano-la-fiera-della-ceramica-e-sud-con-gusto\/","og_locale":"it_IT","og_type":"article","og_title":"Ad Avellino si presentano la Fiera della Ceramica e Sud con Gusto - Article Marketing","og_description":"Palazzo Caracciolo, sede dell\u2019ente provinciale, ospiter\u00e0, venerd\u00ec 6 marzo, la conferenza stampa dedicata agli eventi fieristici in programma presso il Fiere della Campania a partire dal 20 marzo.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/news-e-attualita\/ad-avellino-si-presentano-la-fiera-della-ceramica-e-sud-con-gusto\/","og_site_name":"Article Marketing","article_published_time":"2015-03-04T08:45:23+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/news-e-attualita\/ad-avellino-si-presentano-la-fiera-della-ceramica-e-sud-con-gusto\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/news-e-attualita\/ad-avellino-si-presentano-la-fiera-della-ceramica-e-sud-con-gusto\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Ad Avellino si presentano la Fiera della Ceramica e Sud con Gusto","datePublished":"2015-03-04T08:45:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/news-e-attualita\/ad-avellino-si-presentano-la-fiera-della-ceramica-e-sud-con-gusto\/"},"wordCount":664,"commentCount":0,"articleSection":["News e Attualit\u00e0"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/societa\/news-e-attualita\/ad-avellino-si-presentano-la-fiera-della-ceramica-e-sud-con-gusto\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/news-e-attualita\/ad-avellino-si-presentano-la-fiera-della-ceramica-e-sud-con-gusto\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/news-e-attualita\/ad-avellino-si-presentano-la-fiera-della-ceramica-e-sud-con-gusto\/","name":"Ad Avellino si presentano la Fiera della Ceramica e Sud con Gusto - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2015-03-04T08:45:23+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/news-e-attualita\/ad-avellino-si-presentano-la-fiera-della-ceramica-e-sud-con-gusto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/societa\/news-e-attualita\/ad-avellino-si-presentano-la-fiera-della-ceramica-e-sud-con-gusto\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/societa\/news-e-attualita\/ad-avellino-si-presentano-la-fiera-della-ceramica-e-sud-con-gusto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Ad Avellino si presentano la Fiera della Ceramica e Sud con Gusto"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/47045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=47045"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/47045\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=47045"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=47045"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=47045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}