{"id":48177,"date":"2015-06-29T12:37:37","date_gmt":"2015-06-29T10:37:37","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/progettare-in-sicurezza-i-sistemi-di-distribuzione-di-corrente-da-185-mm\/"},"modified":"2018-10-26T00:33:52","modified_gmt":"2018-10-25T22:33:52","slug":"progettare-in-sicurezza-i-sistemi-di-distribuzione-di-corrente-da-185-mm","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/prodotti\/progettare-in-sicurezza-i-sistemi-di-distribuzione-di-corrente-da-185-mm\/","title":{"rendered":"L\u2019armadio per tutti gli impieghi"},"content":{"rendered":"<p>Le applicazioni sono diverse e complesse, per questo gli armadi IT devono essere in grado di rispondere alle pi&ugrave; svariate esigenze. Gli armadi IT trovano applicazione sia come armadi server che armadi di rete; sono semplici ripartitori di corrente o hanno il delicato compito di offrire un ambiente protetto per le tecnologie server. Sistemi intelligenti di climatizzazione, distribuzione di corrente e sicurezza devono integrarsi perfettamente nell&rsquo;armadio come veri e propri moduli. Con il suo armadio modulare TS IT, Rittal presenta alla Fiera SPS IPC DRIVES ITALIA la possibilit&agrave; di creare pi&ugrave; di 100 soluzioni rack partendo da un unico &ldquo;sistema d armadi&rdquo;.<br \/>\nVignate, maggio 2015 &ndash; Gli armadi rack sono necessari in diversi punti di un ambiente IT: come armadio di rete per gli apparati server e i sistemi di storage in un data center, come distributore di piano per alloggiare le tecnologie di backbone. Entrambe le tipologie di armadio accolgono componenti di rete attivi e passivi. Solitamente con una larghezza di 800 mm, essi offrono spazio sufficiente per la gestione del cablaggio. Per una maggiore flessibilit&agrave;, &egrave; possibile utilizzare in alternativa al piano di montaggio standard da 19&rdquo; un telaio di montaggio da 19&rdquo; regolabile in profondit&agrave;. Una porta in vetro consente una chiara visione dei pannelli di permutazione e degli indicatori di stato delle porte degli switch.<br \/>\nPer integrare i sistemi server pi&ugrave; pesanti e allo stesso tempo con profondit&agrave; maggiore (sia server con1 rack unit di altezza, sia sistemi blade), a seconda della soluzione di climatizzazione, sono utilizzati armadi server con larghezza 600 mm e profondit&agrave; da 1.000 fino a 1.200 mm; per la climatizzazione a rack, gli armadi sono dotati di porta in vetro con serratura, mentre per la climatizzazione di sale e installazioni in batteria la porta &egrave; perforata.<br \/>\nIl sistema modulare TS IT offre un&rsquo;ampia scelta di varianti dimensionali e opzioni di configurazione. &ldquo;Con il TS IT, Rittal offre ai suoi clienti la massima versatilit&agrave; di allestimento per creare soluzioni perfette per armadi server e di rete. Tutto questo ad un prezzo attraente e con tempi di consegna rapidi&rdquo;, ha dichiarato Bernd Hanstein, responsabile della divisione Product Management IT. &ldquo;L&lsquo;armadio TS IT &egrave; la base ideale per integrare in modo flessibile i sistemi di distribuzione di corrente, cooling, monitoraggio e security. Con la piattaforma &lsquo; Rittal &ndash; The System.&lsquo; il cliente riceve tutte le soluzioni di cui ha bisogno da un unico fornitore.&rdquo;<br \/>\nIl fornitore leader di soluzioni per le infrastrutture IT utilizza due tecnologie a 19 pollici tra loro compatibili. Oltre all&rsquo;armadio originale, con profilo da 19&rdquo; installabile con tecnica snap-in e capacit&agrave; di carico fino a 1500 kg, Rittal ha introdotto un telaio di montaggio da 19&ldquo; in diverse dimensioni. Questo permette di avere ottima flessibilit&agrave; per il cablaggio, con spazi di montaggio utili per cavi in rame, fibra, Ethernet e Fibre-Channel. Questa versione dell&rsquo;armadio TS IT supporta un carico massimo di 1.000 Kg ed &egrave; ideale per i componenti di rete.<br \/> Per l&rsquo;impiego in ambienti severi, come negli impianti di produzione, &egrave; disponibile l&rsquo;armadio con grado di protezione IP55. Con la soluzione Safe &ldquo;Micro Data Center&rdquo;, Rittal offre una soluzione sicura all-in-one con infrastruttura IT completa.<\/p>\n<p>TS IT: un security provider ha scelto il TS IT<br \/>\nIl fornitore di servizi di sorveglianza Prosegur con sede a Ratingen (Germania), specializzato in trasporto di valori, conferma le qualit&agrave; del TS IT: &ldquo;Il nostro data centre ospita tutti componenti di rete critici, pi&ugrave; di 50 server fisici e circa. 50 server virtuali in dodici armadi rack TS IT Rittal&ldquo;, ha dichiarato Marco Matzke, responsabile divisione Organisation e IT. &ldquo;Dal &ldquo;sistema di contenitori&rdquo; abbiamo scelto proprio la variante ideale per le nostre esigenze. Abbiamo optato per il TS IT anche perch&eacute; Rittal pu&ograve; fornirci l&rsquo;intero portfolio di soluzioni per il nostro data centre completo, come le soluzioni di cooling, distribuzione di corrente, estinzione e segnalazione incendio.&rdquo; Grazie agli armadi standardizzati, Prosegur &egrave; pronta per le crescite future: ulteriori armadi possono essere aggiunti e ampliati con facilit&agrave;.<br \/>\nSu http:\/\/www.rittal.it &egrave; disponibile il Configuratore IT con il quale i clienti possono preconfigurare l&rsquo;armadio secondo le proprie esigenze.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le applicazioni sono diverse e complesse, per questo gli armadi IT devono essere in grado di rispondere alle pi\u00f9 svariate esigenze. Gli armadi IT trovano applicazione sia come armadi server che armadi di rete; sono semplici ripartitori di corrente o hanno il delicato compito di offrire un ambiente protetto per le tecnologie server. Sistemi intelligenti di climatizzazione, distribuzione di corrente e sicurezza devono integrarsi perfettamente nell\u2019armadio come veri e propri moduli. Con il suo armadio modulare TS IT, Rittal presenta alla Fiera SPS IPC DRIVES ITALIA la possibilit\u00e0 di creare pi\u00f9 di 100 soluzioni rack partendo da un unico \u201csistema d armadi\u201d.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[212],"tags":[],"class_list":["post-48177","post","type-post","status-publish","format-standard","hentry","category-prodotti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2019armadio per tutti gli impieghi - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/prodotti\/progettare-in-sicurezza-i-sistemi-di-distribuzione-di-corrente-da-185-mm\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019armadio per tutti gli impieghi - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Le applicazioni sono diverse e complesse, per questo gli armadi IT devono essere in grado di rispondere alle pi\u00f9 svariate esigenze. Gli armadi IT trovano applicazione sia come armadi server che armadi di rete; sono semplici ripartitori di corrente o hanno il delicato compito di offrire un ambiente protetto per le tecnologie server. Sistemi intelligenti di climatizzazione, distribuzione di corrente e sicurezza devono integrarsi perfettamente nell\u2019armadio come veri e propri moduli. Con il suo armadio modulare TS IT, Rittal presenta alla Fiera SPS IPC DRIVES ITALIA la possibilit\u00e0 di creare pi\u00f9 di 100 soluzioni rack partendo da un unico \u201csistema d armadi\u201d.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/prodotti\/progettare-in-sicurezza-i-sistemi-di-distribuzione-di-corrente-da-185-mm\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2015-06-29T10:37:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-25T22:33:52+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/prodotti\\\/progettare-in-sicurezza-i-sistemi-di-distribuzione-di-corrente-da-185-mm\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/prodotti\\\/progettare-in-sicurezza-i-sistemi-di-distribuzione-di-corrente-da-185-mm\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"L\u2019armadio per tutti gli impieghi\",\"datePublished\":\"2015-06-29T10:37:37+00:00\",\"dateModified\":\"2018-10-25T22:33:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/prodotti\\\/progettare-in-sicurezza-i-sistemi-di-distribuzione-di-corrente-da-185-mm\\\/\"},\"wordCount\":727,\"commentCount\":0,\"articleSection\":[\"Prodotti\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/prodotti\\\/progettare-in-sicurezza-i-sistemi-di-distribuzione-di-corrente-da-185-mm\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/prodotti\\\/progettare-in-sicurezza-i-sistemi-di-distribuzione-di-corrente-da-185-mm\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/prodotti\\\/progettare-in-sicurezza-i-sistemi-di-distribuzione-di-corrente-da-185-mm\\\/\",\"name\":\"L\u2019armadio per tutti gli impieghi - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2015-06-29T10:37:37+00:00\",\"dateModified\":\"2018-10-25T22:33:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/prodotti\\\/progettare-in-sicurezza-i-sistemi-di-distribuzione-di-corrente-da-185-mm\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/prodotti\\\/progettare-in-sicurezza-i-sistemi-di-distribuzione-di-corrente-da-185-mm\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/prodotti\\\/progettare-in-sicurezza-i-sistemi-di-distribuzione-di-corrente-da-185-mm\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019armadio per tutti gli impieghi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019armadio per tutti gli impieghi - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/prodotti\/progettare-in-sicurezza-i-sistemi-di-distribuzione-di-corrente-da-185-mm\/","og_locale":"it_IT","og_type":"article","og_title":"L\u2019armadio per tutti gli impieghi - Article Marketing","og_description":"Le applicazioni sono diverse e complesse, per questo gli armadi IT devono essere in grado di rispondere alle pi\u00f9 svariate esigenze. Gli armadi IT trovano applicazione sia come armadi server che armadi di rete; sono semplici ripartitori di corrente o hanno il delicato compito di offrire un ambiente protetto per le tecnologie server. Sistemi intelligenti di climatizzazione, distribuzione di corrente e sicurezza devono integrarsi perfettamente nell\u2019armadio come veri e propri moduli. Con il suo armadio modulare TS IT, Rittal presenta alla Fiera SPS IPC DRIVES ITALIA la possibilit\u00e0 di creare pi\u00f9 di 100 soluzioni rack partendo da un unico \u201csistema d armadi\u201d.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/prodotti\/progettare-in-sicurezza-i-sistemi-di-distribuzione-di-corrente-da-185-mm\/","og_site_name":"Article Marketing","article_published_time":"2015-06-29T10:37:37+00:00","article_modified_time":"2018-10-25T22:33:52+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/prodotti\/progettare-in-sicurezza-i-sistemi-di-distribuzione-di-corrente-da-185-mm\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/prodotti\/progettare-in-sicurezza-i-sistemi-di-distribuzione-di-corrente-da-185-mm\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"L\u2019armadio per tutti gli impieghi","datePublished":"2015-06-29T10:37:37+00:00","dateModified":"2018-10-25T22:33:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/prodotti\/progettare-in-sicurezza-i-sistemi-di-distribuzione-di-corrente-da-185-mm\/"},"wordCount":727,"commentCount":0,"articleSection":["Prodotti"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/prodotti\/progettare-in-sicurezza-i-sistemi-di-distribuzione-di-corrente-da-185-mm\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/prodotti\/progettare-in-sicurezza-i-sistemi-di-distribuzione-di-corrente-da-185-mm\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/prodotti\/progettare-in-sicurezza-i-sistemi-di-distribuzione-di-corrente-da-185-mm\/","name":"L\u2019armadio per tutti gli impieghi - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2015-06-29T10:37:37+00:00","dateModified":"2018-10-25T22:33:52+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/prodotti\/progettare-in-sicurezza-i-sistemi-di-distribuzione-di-corrente-da-185-mm\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/prodotti\/progettare-in-sicurezza-i-sistemi-di-distribuzione-di-corrente-da-185-mm\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/prodotti\/progettare-in-sicurezza-i-sistemi-di-distribuzione-di-corrente-da-185-mm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"L\u2019armadio per tutti gli impieghi"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/48177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=48177"}],"version-history":[{"count":1,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/48177\/revisions"}],"predecessor-version":[{"id":64647,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/48177\/revisions\/64647"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=48177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=48177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=48177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}