{"id":48254,"date":"2015-07-03T13:48:38","date_gmt":"2015-07-03T11:48:38","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/lartista-abruzzese-riccardo-polidoro-%c3%a8-uscito-in-questi-giorni-con-il-suo-nuovo-singolo-leave-a-mark-su-etichetta-maxy-sound-e-lo-regala-a-tutti-i-suoi-fan\/"},"modified":"2020-08-10T01:22:15","modified_gmt":"2020-08-09T23:22:15","slug":"lartista-abruzzese-riccardo-polidoro-%c3%a8-uscito-in-questi-giorni-con-il-suo-nuovo-singolo-leave-a-mark-su-etichetta-maxy-sound-e-lo-regala-a-tutti-i-suoi-fan","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/musica\/lartista-abruzzese-riccardo-polidoro-%c3%a8-uscito-in-questi-giorni-con-il-suo-nuovo-singolo-leave-a-mark-su-etichetta-maxy-sound-e-lo-regala-a-tutti-i-suoi-fan\/","title":{"rendered":"L&#8217;artista abruzzese Riccardo Polidoro \u00e8 uscito in questi giorni con il suo nuovo singolo &#8220;Leave a Mark&#8221; su etichetta Maxy Sound e lo regala a tutti i suoi fan."},"content":{"rendered":"<p>&#8220;Lascia un segno della tua presenza nel mondo, fai un graffio che nessuno possa togliere, entra nel cuore delle persone&#8221;, cos&igrave; recita il testo del nuovo singolo in Inglese di <strong>Riccardo Polidoro<\/strong>, cantante chietino gi&agrave; noto al pubblico di internet per le sue cover dei brani di <strong>Celine Dion<\/strong> come<strong> &#8220;I Surrender&#8221;<\/strong>, <strong>&#8220;Don&#8217;t save it all for Christmas&#8221;, &#8220;To love you more&#8221;, &#8220;Loved me back to life&#8221;<\/strong> e molti altri. Negli ultimi due anni Riccardo ha collezionato centinaia di migliaia di visualizzazione su youtube e centinaia di fan da tutto il mondo gli scrivono ogni giorno per complimentarsi o chiedere nuove canzoni.<br \/>Cos&igrave;, per questa estate 2015, Riccardo ha deciso di regalare ai fan il suo nuovo singolo <strong>&#8220;Leave a Mark&#8221;<\/strong>. Il brano scritto a quattro mani con l&#8217;autore e produttore <strong>Max Titi<\/strong>, esorta i ragazzi a lasciare un segno della loro presenza, a farsi valere, a non farsi scoraggiare da un mondo sempre pi&ugrave; caotico e a non smettere di cercare la propria identit&agrave; e la propria missione. A dispetto di una melodia estiva orecchiabile e di un video giocosamente esilarante, in cui la protagonista femminile prende letteralmente fuoco, il testo della canzone, che riportiamo di seguito, &egrave; in realt&agrave; ricco di contenuto e stile. <br \/>Dalla sua partecipazione alle selezioni di XFactor, la vittoria a Festival Show e la pubblicazione del suo primo album &#8220;Ladro di Sorrisi&#8221; ed i successivi inediti, Riccardo di strada ne ha fatta molta. Grazie ai nuovi media sta avendo un inarrestabile successo. Come lui stesso dice nel video di presentazione della sua ultima fatica&hellip; &#8220;Cari Fan&hellip; Lasciate un segno&hellip;&#8221; Lui lo sta gi&agrave; facendo sul web.<br \/>Per avere gratuitamente il brano <strong>&#8220;Leave a Mark&#8221;<\/strong>, basta collegarsi al suo <a href=\"http:\/\/www.riccardopolidoro.com\">sito ufficiale di Riccardo<\/a><\/p>\n<p>Video di presentazione del singolo:<br \/>https:\/\/www.youtube.com\/watch?v=mxD2CiShRbE<\/p>\n<p>Videoclip del singolo:<br \/>https:\/\/www.youtube.com\/watch?v=J17rRS6VBok<\/p>\n<p>Leave a Mark su iTunes: <br \/>https:\/\/geo.itunes.apple.com\/it\/album\/leave-a-mark-single\/id1011378282?<\/p>\n<p><strong>LEAVE A MARK <\/strong>(M. Titi &#8211; R. Polidoro)<\/p>\n<p>Jump Jump Jump<br \/>&#8217;cause you&#8217;re amazing<br \/>Leave a mark of your presence on this world<br \/>make a scratch that nobody can rub off<br \/>Leave your name, your address, your position on the map<br \/>your identity, your genes, your fears, your quest.<\/p>\n<p>Write in blue, write in red, bro <br \/>in the colour that makes you feel good<br \/>what you write on the walls will never fall<br \/>leave a mark on the souls of people that you come across<br \/>Write in green, write in red, man!<br \/>if you think that you make mistakes<br \/>what you write on the walls will never fall<br \/>&#8217;cause you&#8217;re amazing, you drive me crazy<br \/>and all your colours make me <\/p>\n<p>Jump Jump Jump<br \/>&#8217;cause you&#8217;re amazing<br \/>&#8217;cause you&#8217;re amazing<\/p>\n<p>Leave a mark on the walls you wanna pound<br \/>and make a mark on those that you want to tear down<br \/>when a single grain of sand brings about a big landslide<br \/>you&#8217;re the only one who makes your paradise<br \/>Write in blue, write in red, bro <br \/>in the colour that makes you feel good<br \/>what you write on the walls will never fall<br \/>leave a mark on the souls of people that you come across<br \/>Write in green, write in red, mate<br \/>if you think that you made mistakes<br \/>what you write on the walls will never fall<br \/>&#8217;cause you&#8217;re amazing, you drive me crazy<br \/>and all your colours make me <br \/>Jump Jump Jump<br \/>&#8217;cause you&#8217;re amazing<br \/>&#8217;cause you&#8217;re amazing<br \/>and all your colors make me <\/p>\n<p>Jump Jump Jump<br \/>&#8217;cause you&#8217;re amazing<br \/>&#8217;cause you&#8217;re amazing<br \/>and all your colours make me <\/p>\n<p>wonder if you could leave a mark on my heart too<br \/>paint the sky, and if you&#8217;re sad sketch a life that dies instead<br \/>shape a miracle, a proof empirical, concrete shit rather than a theoretical<br \/>let&#8217;s get physical, draw your own musical so that your colours blind me <br \/>and make me say<\/p>\n<p>Jump Jump Jump<br \/>&#8217;cause you&#8217;re amazing<br \/>&#8217;cause you&#8217;re amazing<br \/>and all your colours make me<\/p>\n<p><strong>Lascia Un Segno<\/strong><\/p>\n<p>Salta Salta Salta<br \/>perche sei fantastico<br \/>Lascia un segno della tua presenza nel mondo<br \/>fai un graffio che nessuno pu&ograve; tirar via<br \/>Lascia il tuo nome, il tuo indirizzo, la tua posizione sulla mappa, la tua identit&agrave; i tuo geni,<br \/>le tue paure, il tuo obiettivo.<\/p>\n<p>Scrivi in blu in rosso fratello,<br \/>nel colore che ti fa stare bene <br \/>quello che scrivi sul muro non cadr&agrave;<br \/>lascia un segno nell&#8217;anima delle persone che incontri.<br \/>Scrivi in verde, scrivi in rosso<br \/>se pensi di fare errori <br \/>quello che scrivi sul muro non cadr&agrave; <br \/>perch&eacute; sei fantastico, mi fai impazzire, <br \/>e tutti i tuoi colori mi fanno <\/p>\n<p>saltare saltare saltare <br \/>perch&eacute; sei fantastico, perch&eacute; sei fantastico<\/p>\n<p>Lascia un segno sui muri che vuoi prendere a pugni e fai un segno su quelli che vuoi abbattere.<br \/>Quando un singolo granello di sabbia provoca una valanga, tu sei l&#8217;unico a creare il tuo paradiso<\/p>\n<p>Scrivi in blu, scrivi in rosso fratello,<br \/>nel colore che ti fa stare bene <br \/>quello che scrivi nel muro non cadr&agrave;<br \/>lascia un segno nell&#8217;anima delle persone che incontri.<br \/>Scrivi in verde, scrivi in rosso<br \/>se pensi di fare errori <br \/>quello che scrivi sul muro non cadr&agrave; <br \/>perch&eacute; sei fantastico, mi fai impazzire, <br \/>e tutti i tuoi colori mi fanno <\/p>\n<p>saltare saltare saltare <br \/>perch&eacute; sei fantastico, perch&eacute; sei fantastico<br \/>e tutti i tuoi colori mi fanno<\/p>\n<p>sospettare se tu possa lasciare un segno anche nel mio cuore, dipingi il cielo, e se sei triste disegna una vita che muore, dai forma ad un miracolo, una prova empirica, roba vera piuttosto che teorica, diventa violento, disegna il tuo musical, affinch&eacute; il tuoi colori possano accecarmi e mi facciano dire&hellip;.<br \/>salta salta salta <br \/>perch&eacute; sei fantastico, perch&eacute; sei fantastico<br \/>e tutti i tuoi colori mi fanno <br \/>saltare saltare saltare<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Lascia un segno della tua presenza nel mondo, fai un graffio che nessuno possa togliere, entra nel cuore delle persone&#8221;, cos&igrave; recita il testo del nuovo singolo in Inglese di Riccardo Polidoro, cantante chietino gi&agrave; noto al pubblico di internet per le sue cover dei brani di Celine Dion come &#8220;I Surrender&#8221;, &#8220;Don&#8217;t save it all for Christmas&#8221;, &#8220;To love you more&#8221;, &#8220;Loved me back to life&#8221; e molti altri.<\/p>\n<p><a class=\"continue-reading\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/musica\/lartista-abruzzese-riccardo-polidoro-%c3%a8-uscito-in-questi-giorni-con-il-suo-nuovo-singolo-leave-a-mark-su-etichetta-maxy-sound-e-lo-regala-a-tutti-i-suoi-fan\/\">Continue reading&#8230;<\/a><\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[42],"tags":[51991,51987,26553,51992,51990,51988,51989],"class_list":["post-48254","post","type-post","status-publish","format-standard","hentry","category-musica","tag-artisti-abruzzesi","tag-leave-a-mark","tag-max-titi","tag-maxy-sound","tag-musica-gratis","tag-riccardo-polidoro","tag-singolo-gratis"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;artista abruzzese Riccardo Polidoro \u00e8 uscito in questi giorni con il suo nuovo singolo &quot;Leave a Mark&quot; su etichetta Maxy Sound e lo regala a tutti i suoi fan. - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/musica\/lartista-abruzzese-riccardo-polidoro-\u00e8-uscito-in-questi-giorni-con-il-suo-nuovo-singolo-leave-a-mark-su-etichetta-maxy-sound-e-lo-regala-a-tutti-i-suoi-fan\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;artista abruzzese Riccardo Polidoro \u00e8 uscito in questi giorni con il suo nuovo singolo &quot;Leave a Mark&quot; su etichetta Maxy Sound e lo regala a tutti i suoi fan. - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"&#8220;Lascia un segno della tua presenza nel mondo, fai un graffio che nessuno possa togliere, entra nel cuore delle persone&#8221;, cos&igrave; recita il testo del nuovo singolo in Inglese di Riccardo Polidoro, cantante chietino gi&agrave; noto al pubblico di internet per le sue cover dei brani di Celine Dion come &#8220;I Surrender&#8221;, &#8220;Don&#8217;t save it all for Christmas&#8221;, &#8220;To love you more&#8221;, &#8220;Loved me back to life&#8221; e molti altri.Continue reading...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/musica\/lartista-abruzzese-riccardo-polidoro-\u00e8-uscito-in-questi-giorni-con-il-suo-nuovo-singolo-leave-a-mark-su-etichetta-maxy-sound-e-lo-regala-a-tutti-i-suoi-fan\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-03T11:48:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-09T23:22:15+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/musica\\\/lartista-abruzzese-riccardo-polidoro-%c3%a8-uscito-in-questi-giorni-con-il-suo-nuovo-singolo-leave-a-mark-su-etichetta-maxy-sound-e-lo-regala-a-tutti-i-suoi-fan\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/musica\\\/lartista-abruzzese-riccardo-polidoro-%c3%a8-uscito-in-questi-giorni-con-il-suo-nuovo-singolo-leave-a-mark-su-etichetta-maxy-sound-e-lo-regala-a-tutti-i-suoi-fan\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"L&#8217;artista abruzzese Riccardo Polidoro \u00e8 uscito in questi giorni con il suo nuovo singolo &#8220;Leave a Mark&#8221; su etichetta Maxy Sound e lo regala a tutti i suoi fan.\",\"datePublished\":\"2015-07-03T11:48:38+00:00\",\"dateModified\":\"2020-08-09T23:22:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/musica\\\/lartista-abruzzese-riccardo-polidoro-%c3%a8-uscito-in-questi-giorni-con-il-suo-nuovo-singolo-leave-a-mark-su-etichetta-maxy-sound-e-lo-regala-a-tutti-i-suoi-fan\\\/\"},\"wordCount\":976,\"commentCount\":0,\"keywords\":[\"artisti abruzzesi\",\"Leave a Mark\",\"Max Titi\",\"MAxy Sound\",\"musica gratis\",\"Riccardo Polidoro\",\"Singolo gratis\"],\"articleSection\":[\"Musica\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/musica\\\/lartista-abruzzese-riccardo-polidoro-%c3%a8-uscito-in-questi-giorni-con-il-suo-nuovo-singolo-leave-a-mark-su-etichetta-maxy-sound-e-lo-regala-a-tutti-i-suoi-fan\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/musica\\\/lartista-abruzzese-riccardo-polidoro-%c3%a8-uscito-in-questi-giorni-con-il-suo-nuovo-singolo-leave-a-mark-su-etichetta-maxy-sound-e-lo-regala-a-tutti-i-suoi-fan\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/musica\\\/lartista-abruzzese-riccardo-polidoro-%c3%a8-uscito-in-questi-giorni-con-il-suo-nuovo-singolo-leave-a-mark-su-etichetta-maxy-sound-e-lo-regala-a-tutti-i-suoi-fan\\\/\",\"name\":\"L'artista abruzzese Riccardo Polidoro \u00e8 uscito in questi giorni con il suo nuovo singolo \\\"Leave a Mark\\\" su etichetta Maxy Sound e lo regala a tutti i suoi fan. - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2015-07-03T11:48:38+00:00\",\"dateModified\":\"2020-08-09T23:22:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/musica\\\/lartista-abruzzese-riccardo-polidoro-%c3%a8-uscito-in-questi-giorni-con-il-suo-nuovo-singolo-leave-a-mark-su-etichetta-maxy-sound-e-lo-regala-a-tutti-i-suoi-fan\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/musica\\\/lartista-abruzzese-riccardo-polidoro-%c3%a8-uscito-in-questi-giorni-con-il-suo-nuovo-singolo-leave-a-mark-su-etichetta-maxy-sound-e-lo-regala-a-tutti-i-suoi-fan\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/musica\\\/lartista-abruzzese-riccardo-polidoro-%c3%a8-uscito-in-questi-giorni-con-il-suo-nuovo-singolo-leave-a-mark-su-etichetta-maxy-sound-e-lo-regala-a-tutti-i-suoi-fan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;artista abruzzese Riccardo Polidoro \u00e8 uscito in questi giorni con il suo nuovo singolo &#8220;Leave a Mark&#8221; su etichetta Maxy Sound e lo regala a tutti i suoi fan.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'artista abruzzese Riccardo Polidoro \u00e8 uscito in questi giorni con il suo nuovo singolo \"Leave a Mark\" su etichetta Maxy Sound e lo regala a tutti i suoi fan. - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/musica\/lartista-abruzzese-riccardo-polidoro-\u00e8-uscito-in-questi-giorni-con-il-suo-nuovo-singolo-leave-a-mark-su-etichetta-maxy-sound-e-lo-regala-a-tutti-i-suoi-fan\/","og_locale":"it_IT","og_type":"article","og_title":"L'artista abruzzese Riccardo Polidoro \u00e8 uscito in questi giorni con il suo nuovo singolo \"Leave a Mark\" su etichetta Maxy Sound e lo regala a tutti i suoi fan. - Article Marketing","og_description":"&#8220;Lascia un segno della tua presenza nel mondo, fai un graffio che nessuno possa togliere, entra nel cuore delle persone&#8221;, cos&igrave; recita il testo del nuovo singolo in Inglese di Riccardo Polidoro, cantante chietino gi&agrave; noto al pubblico di internet per le sue cover dei brani di Celine Dion come &#8220;I Surrender&#8221;, &#8220;Don&#8217;t save it all for Christmas&#8221;, &#8220;To love you more&#8221;, &#8220;Loved me back to life&#8221; e molti altri.Continue reading...","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/musica\/lartista-abruzzese-riccardo-polidoro-\u00e8-uscito-in-questi-giorni-con-il-suo-nuovo-singolo-leave-a-mark-su-etichetta-maxy-sound-e-lo-regala-a-tutti-i-suoi-fan\/","og_site_name":"Article Marketing","article_published_time":"2015-07-03T11:48:38+00:00","article_modified_time":"2020-08-09T23:22:15+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/musica\/lartista-abruzzese-riccardo-polidoro-%c3%a8-uscito-in-questi-giorni-con-il-suo-nuovo-singolo-leave-a-mark-su-etichetta-maxy-sound-e-lo-regala-a-tutti-i-suoi-fan\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/musica\/lartista-abruzzese-riccardo-polidoro-%c3%a8-uscito-in-questi-giorni-con-il-suo-nuovo-singolo-leave-a-mark-su-etichetta-maxy-sound-e-lo-regala-a-tutti-i-suoi-fan\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"L&#8217;artista abruzzese Riccardo Polidoro \u00e8 uscito in questi giorni con il suo nuovo singolo &#8220;Leave a Mark&#8221; su etichetta Maxy Sound e lo regala a tutti i suoi fan.","datePublished":"2015-07-03T11:48:38+00:00","dateModified":"2020-08-09T23:22:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/musica\/lartista-abruzzese-riccardo-polidoro-%c3%a8-uscito-in-questi-giorni-con-il-suo-nuovo-singolo-leave-a-mark-su-etichetta-maxy-sound-e-lo-regala-a-tutti-i-suoi-fan\/"},"wordCount":976,"commentCount":0,"keywords":["artisti abruzzesi","Leave a Mark","Max Titi","MAxy Sound","musica gratis","Riccardo Polidoro","Singolo gratis"],"articleSection":["Musica"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/musica\/lartista-abruzzese-riccardo-polidoro-%c3%a8-uscito-in-questi-giorni-con-il-suo-nuovo-singolo-leave-a-mark-su-etichetta-maxy-sound-e-lo-regala-a-tutti-i-suoi-fan\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/musica\/lartista-abruzzese-riccardo-polidoro-%c3%a8-uscito-in-questi-giorni-con-il-suo-nuovo-singolo-leave-a-mark-su-etichetta-maxy-sound-e-lo-regala-a-tutti-i-suoi-fan\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/musica\/lartista-abruzzese-riccardo-polidoro-%c3%a8-uscito-in-questi-giorni-con-il-suo-nuovo-singolo-leave-a-mark-su-etichetta-maxy-sound-e-lo-regala-a-tutti-i-suoi-fan\/","name":"L'artista abruzzese Riccardo Polidoro \u00e8 uscito in questi giorni con il suo nuovo singolo \"Leave a Mark\" su etichetta Maxy Sound e lo regala a tutti i suoi fan. - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2015-07-03T11:48:38+00:00","dateModified":"2020-08-09T23:22:15+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/musica\/lartista-abruzzese-riccardo-polidoro-%c3%a8-uscito-in-questi-giorni-con-il-suo-nuovo-singolo-leave-a-mark-su-etichetta-maxy-sound-e-lo-regala-a-tutti-i-suoi-fan\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/musica\/lartista-abruzzese-riccardo-polidoro-%c3%a8-uscito-in-questi-giorni-con-il-suo-nuovo-singolo-leave-a-mark-su-etichetta-maxy-sound-e-lo-regala-a-tutti-i-suoi-fan\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/musica\/lartista-abruzzese-riccardo-polidoro-%c3%a8-uscito-in-questi-giorni-con-il-suo-nuovo-singolo-leave-a-mark-su-etichetta-maxy-sound-e-lo-regala-a-tutti-i-suoi-fan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"L&#8217;artista abruzzese Riccardo Polidoro \u00e8 uscito in questi giorni con il suo nuovo singolo &#8220;Leave a Mark&#8221; su etichetta Maxy Sound e lo regala a tutti i suoi fan."}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/48254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=48254"}],"version-history":[{"count":1,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/48254\/revisions"}],"predecessor-version":[{"id":66573,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/48254\/revisions\/66573"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=48254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=48254"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=48254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}