{"id":48542,"date":"2015-07-21T16:15:38","date_gmt":"2015-07-21T14:15:38","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/la-devitalizzazione-dal-dentista-per-la-cura-della-tua-bocca\/"},"modified":"2015-07-21T16:15:38","modified_gmt":"2015-07-21T14:15:38","slug":"la-devitalizzazione-dal-dentista-per-la-cura-della-tua-bocca","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/la-devitalizzazione-dal-dentista-per-la-cura-della-tua-bocca\/","title":{"rendered":"La devitalizzazione dal dentista per la cura della tua bocca"},"content":{"rendered":"<p>La terapia canalare consiste nel togliere tessuto pulpare che si trova all&#8217;interno dei denti tra corona e radice. La devitalizzazione &egrave; necessaria quando una carie mal curata o trascurata devasta la parte minerale del dente fino a raggiungere il tessuto pulpare contaminandolo ed infettandolo. La polpa dentaria presente all&#8217;interno del dente &egrave; chiamata anche nervo,proprio perch&egrave; all&#8217;interno vi sono terminazione nervose, vene e cellule connettivali. Una brutta carie causa infezione, per cui la polpa infiammata provoca dolore,in questo caso il tessuto pulpare va asportato con la terapia canalare.<\/p>\n<p>Anche i nei casi di rimozioni di vecchi restauri o corone si interviene con la devitalizzazione . Una procedura lunga, che varia a seconda delle condizioni di partenza del dente, alle difficolt&agrave; anatomiche che si riscontrano durante il percorso della devitalizzazione(calcificazioni, radici curve, canali poco penetrabili.<\/p>\n<p>Appositi strumenti provvedono all&#8217;esportazione del tessuto; dopo un materiale sigillante chiamato guttaperca, precedentemente riscaldata per poi solidificarsi con il raffreddamento viene utilizzata per l&#8217;otturazione canalare garantendo un sigillo che impedisce ai batteri di proliferare.<\/p>\n<p>Il trattamento si svolge in anestesia locale, laddove la terapia si svolge in un unica seduta, la durata &egrave; di circa 45 minuti 120 minuti a seconda del caso. E&#8217; preferibile non masticare sul dente trattato finch&egrave; c&#8217;&egrave; l&#8217;anestesia, uno per non ferirsi senza rendersene conto lingua e guancia, due perch&egrave; al risveglio se il dente duole un po&#8217; meglio tenerlo al riposo da forze masticatorie.<\/p>\n<p>Quando invece si presentano pazienti con stati infiammatori come ascessi importanti, &egrave; utile seguire una medicazione per poi procedere dopo qualche giorno. Presso uno <strong><a href=\"http:\/\/www.studiodentistico-santoro.it\/\" target=\"_blank\" title=\"studio dentistico bari\">studio dentistico<\/a><\/strong> pi&ugrave; vicino a casa, ogni paziente verr&agrave; sempre informato dopo un attenta valutazione del percorso che andr&agrave; ad affrontare, al fine di rendere il tutto quanto pi&ugrave; confortevole e tranquillo.<br \/>\nPer conoscere tutto sull&#8217;argomento devitalizzazione e non solo, &egrave; possibile richiedere gratuitamente un primo appuntamento in alcuni studi dentistici, i contatti sono presenti sul sito ufficiale dello stesso dentista.<\/p>\n<p>Presso tutti gli studi dentistici migliori e attrezzati nelle vostre citt&agrave; l&#8217;intervento ortodontico di devitalizzazione aiuta a risolvere il vostro problema in modo definitivo e normalmente senza nessuna ulteriore problematica relativa allo stesso problema.<\/p>\n<p>La devitalizzazione trova in campo medico dentistico la soluzione a diverse tipologie di problematiche come: la cura delle carie dei vostri denti, per traumi gravi ai vostri denti, per la cura di un&#8217;infiammazione profonda della polpa dentale, per alcuni eccessi dentali, per la cura dei denti gravemente scheggiati, per la rottura accidentale dei denti in generale. <\/p>\n<p>Grazie a questo intervento di devitalizzazione i pazienti che si recano tempestivamente in uno studio dentistico nella propria citt&agrave; posso evitare di incorrere in problematiche molto pi&ugrave; serie come infezioni batteriche che le stesse possono scatenare lesioni ancora pi&ugrave; pericolose e gravi come ad esempio: granulomi e cisti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La terapia canalare consiste nel togliere tessuto pulpare che si trova all&#8217;interno dei denti tra corona e radice. La devitalizzazione \u00e8 necessaria quando una carie mal curata o trascurata devasta la parte minerale del dente fino a raggiungere il tessuto pulpare contaminandolo ed infettandolo. La polpa dentaria presente all&#8217;interno del dente \u00e8 chiamata anche nervo,proprio perch\u00e8 all&#8217;interno vi sono terminazione nervose, vene e cellule connettivali. Una brutta carie causa infezione, per cui la polpa infiammata provoca dolore,in questo caso il tessuto pulpare va asportato con la terapia canalare.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[70],"tags":[11810],"class_list":["post-48542","post","type-post","status-publish","format-standard","hentry","category-medicina","tag-studio-dentistico-bari"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La devitalizzazione dal dentista per la cura della tua bocca - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/la-devitalizzazione-dal-dentista-per-la-cura-della-tua-bocca\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La devitalizzazione dal dentista per la cura della tua bocca - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"La terapia canalare consiste nel togliere tessuto pulpare che si trova all&#039;interno dei denti tra corona e radice. La devitalizzazione \u00e8 necessaria quando una carie mal curata o trascurata devasta la parte minerale del dente fino a raggiungere il tessuto pulpare contaminandolo ed infettandolo. La polpa dentaria presente all&#039;interno del dente \u00e8 chiamata anche nervo,proprio perch\u00e8 all&#039;interno vi sono terminazione nervose, vene e cellule connettivali. Una brutta carie causa infezione, per cui la polpa infiammata provoca dolore,in questo caso il tessuto pulpare va asportato con la terapia canalare.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/la-devitalizzazione-dal-dentista-per-la-cura-della-tua-bocca\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-21T14:15:38+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/medicina\\\/la-devitalizzazione-dal-dentista-per-la-cura-della-tua-bocca\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/medicina\\\/la-devitalizzazione-dal-dentista-per-la-cura-della-tua-bocca\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"La devitalizzazione dal dentista per la cura della tua bocca\",\"datePublished\":\"2015-07-21T14:15:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/medicina\\\/la-devitalizzazione-dal-dentista-per-la-cura-della-tua-bocca\\\/\"},\"wordCount\":480,\"commentCount\":0,\"keywords\":[\"studio dentistico bari\"],\"articleSection\":[\"Medicina\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/medicina\\\/la-devitalizzazione-dal-dentista-per-la-cura-della-tua-bocca\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/medicina\\\/la-devitalizzazione-dal-dentista-per-la-cura-della-tua-bocca\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/medicina\\\/la-devitalizzazione-dal-dentista-per-la-cura-della-tua-bocca\\\/\",\"name\":\"La devitalizzazione dal dentista per la cura della tua bocca - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2015-07-21T14:15:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/medicina\\\/la-devitalizzazione-dal-dentista-per-la-cura-della-tua-bocca\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/medicina\\\/la-devitalizzazione-dal-dentista-per-la-cura-della-tua-bocca\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/medicina\\\/la-devitalizzazione-dal-dentista-per-la-cura-della-tua-bocca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La devitalizzazione dal dentista per la cura della tua bocca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La devitalizzazione dal dentista per la cura della tua bocca - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/la-devitalizzazione-dal-dentista-per-la-cura-della-tua-bocca\/","og_locale":"it_IT","og_type":"article","og_title":"La devitalizzazione dal dentista per la cura della tua bocca - Article Marketing","og_description":"La terapia canalare consiste nel togliere tessuto pulpare che si trova all'interno dei denti tra corona e radice. La devitalizzazione \u00e8 necessaria quando una carie mal curata o trascurata devasta la parte minerale del dente fino a raggiungere il tessuto pulpare contaminandolo ed infettandolo. La polpa dentaria presente all'interno del dente \u00e8 chiamata anche nervo,proprio perch\u00e8 all'interno vi sono terminazione nervose, vene e cellule connettivali. Una brutta carie causa infezione, per cui la polpa infiammata provoca dolore,in questo caso il tessuto pulpare va asportato con la terapia canalare.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/la-devitalizzazione-dal-dentista-per-la-cura-della-tua-bocca\/","og_site_name":"Article Marketing","article_published_time":"2015-07-21T14:15:38+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/la-devitalizzazione-dal-dentista-per-la-cura-della-tua-bocca\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/la-devitalizzazione-dal-dentista-per-la-cura-della-tua-bocca\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"La devitalizzazione dal dentista per la cura della tua bocca","datePublished":"2015-07-21T14:15:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/la-devitalizzazione-dal-dentista-per-la-cura-della-tua-bocca\/"},"wordCount":480,"commentCount":0,"keywords":["studio dentistico bari"],"articleSection":["Medicina"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/la-devitalizzazione-dal-dentista-per-la-cura-della-tua-bocca\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/la-devitalizzazione-dal-dentista-per-la-cura-della-tua-bocca\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/la-devitalizzazione-dal-dentista-per-la-cura-della-tua-bocca\/","name":"La devitalizzazione dal dentista per la cura della tua bocca - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2015-07-21T14:15:38+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/la-devitalizzazione-dal-dentista-per-la-cura-della-tua-bocca\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/la-devitalizzazione-dal-dentista-per-la-cura-della-tua-bocca\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/medicina\/la-devitalizzazione-dal-dentista-per-la-cura-della-tua-bocca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"La devitalizzazione dal dentista per la cura della tua bocca"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/48542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=48542"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/48542\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=48542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=48542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=48542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}