{"id":48777,"date":"2015-08-25T17:15:18","date_gmt":"2015-08-25T15:15:18","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/situazione-digitale-italiana-serve-un-passo-avanti\/"},"modified":"2015-08-25T17:15:18","modified_gmt":"2015-08-25T15:15:18","slug":"situazione-digitale-italiana-serve-un-passo-avanti","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marketing\/situazione-digitale-italiana-serve-un-passo-avanti\/","title":{"rendered":"Situazione digitale italiana, serve un passo avanti."},"content":{"rendered":"<p><strong>Il CNA testimonia l&#8217;arretratezza tecologica delle Pmi Italiane. Occorre colmare il gap per non rimanere indietro nel cammino verso il digitale.<\/strong><br \/>Osservando la situazione digitale italiana sembra paradossale, ma tuttora in Italia una PMI su dieci non &egrave; dotata di computer, una su cinque non utilizza pc portatili e pi&ugrave; del 50% &egrave; sprovvista di tablet. Nonostante ci&ograve; la consapevolezza dell&rsquo;impossibilit&agrave; di prescindere dal web per agire con successo nel mercato &egrave; quasi totale fra le imprese. Naturalmente in questo scenario le aziende pi&ugrave; grandi sono pi&ugrave; sensibili alla necessit&agrave; di tenere il passo con l&rsquo;evoluzione del digitale e il 98% di esse possiede un sito web. Questa percentuale diminuisce al diminuire della grandezza dell&rsquo;impresa, tanto che solo il 61% delle aziende con massimo 9 addetti ha un sito. Lo stesso vale per l&rsquo;utilizzo degli strumenti digitali: solo il 26,2 % delle micro imprese li utilizza.<br \/>La classe dimensionale, invece, sembrerebbe non influire sul commercio elettronico: il 26,5% delle aziende campione &egrave; attiva in questo settore con differenze poco significative in base al numero di addetti. L&rsquo;elemento strutturale &egrave; determinante quando si prendono in considerazione le aziende che operano come acquirenti o come venditori: infatti se da un lato le imprese che comprano online sono circa il 25% in tutte le classi dimensionali, nel caso delle vendite, ad aver colto l&rsquo;opportunit&agrave; di operare online &egrave; il 12% circa delle micro-imprese contro il 21% circa delle imprese con pi&ugrave; di 20 addetti.<br \/>Ma quali sono i principali ostacoli per la diffusione del digitale?<br \/>In primis sono spesso soprattutto i costi che le micro imprese non riescono a sostenere per la gestione del sito, la consulenza ICT esterna o i corsi di formazione. Infatti, fra le aziende con meno di 10 dipendenti, solo il 16% ha svolto formazione ICT nell&rsquo;ultimo anno e solo un&rsquo; azienda su tre si avvale del supporto di consulenti.<br \/>Un&rsquo;altra motivazione forte, al di l&agrave; dell&rsquo;aspetto finanziario, &egrave; rappresentata dalla scarsa digitalizzazione della PA che ha un livello di informatizzazione del tutto inadeguato rispetto alle necessit&agrave; delle imprese: solo una micro-impresa su tre riesce a sbrigare pi&ugrave; della met&agrave; delle pratiche per via telematica. Proprio per questo &egrave; necessario sensibilizzare gli organismi centrali, auspicando la realizzazione di un da parte del Governo di un piano straordinario per l&rsquo;innovazione digitale della micro e piccola impresa italiana. Questa &egrave; l&rsquo;unica via per aumentare la produttivit&agrave; italiana ed allinearci a livelli degli stranieri e deve essere realizzata nel minor tempo possibile in modo dal colmare il gap digitale italiano.<br \/>Il governo si dovr&agrave; impegnare per consentire alle micro-piccole imprese di avere un sito web, di essere attive nel commercio estero e di utilizzare, almeno un volta, strumenti di fabbricazione digitale . Infine, sarebbe importante che le micro-piccole imprese svolgessero almeno la met&agrave; degli adempimenti burocratici via web, passando nel giro di due anni dal 24% al 50%&raquo;.<br \/>Per ulteriori informazioni sulle tecnologie delle imprese italiane visita il sito <a href=\"http:\/\/www.fatturafacile.com\/news\/digitale-fatturazione-pmi\/\">http:\/\/www.fatturafacile.com\/news\/digitale-fatturazione-pmi\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Emerge da un&#8217;analisi del CNA un&#8217; arretratezza dell&#8217;Italia nei confronti del digitale. Molte Pmi risultano ancora sprovviste dei principali strumenti tecnologici in grado di garantire la digitalizzazione.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[103],"tags":[3069,259],"class_list":["post-48777","post","type-post","status-publish","format-standard","hentry","category-marketing","tag-digitale","tag-tecnologia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Situazione digitale italiana, serve un passo avanti. - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marketing\/situazione-digitale-italiana-serve-un-passo-avanti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Situazione digitale italiana, serve un passo avanti. - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Emerge da un&#039;analisi del CNA un&#039; arretratezza dell&#039;Italia nei confronti del digitale. Molte Pmi risultano ancora sprovviste dei principali strumenti tecnologici in grado di garantire la digitalizzazione.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marketing\/situazione-digitale-italiana-serve-un-passo-avanti\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2015-08-25T15:15:18+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/marketing\\\/situazione-digitale-italiana-serve-un-passo-avanti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/marketing\\\/situazione-digitale-italiana-serve-un-passo-avanti\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Situazione digitale italiana, serve un passo avanti.\",\"datePublished\":\"2015-08-25T15:15:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/marketing\\\/situazione-digitale-italiana-serve-un-passo-avanti\\\/\"},\"wordCount\":523,\"commentCount\":0,\"keywords\":[\"digitale\",\"tecnologia\"],\"articleSection\":[\"Marketing\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/marketing\\\/situazione-digitale-italiana-serve-un-passo-avanti\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/marketing\\\/situazione-digitale-italiana-serve-un-passo-avanti\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/marketing\\\/situazione-digitale-italiana-serve-un-passo-avanti\\\/\",\"name\":\"Situazione digitale italiana, serve un passo avanti. - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2015-08-25T15:15:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/marketing\\\/situazione-digitale-italiana-serve-un-passo-avanti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/marketing\\\/situazione-digitale-italiana-serve-un-passo-avanti\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/marketing\\\/situazione-digitale-italiana-serve-un-passo-avanti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Situazione digitale italiana, serve un passo avanti.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Situazione digitale italiana, serve un passo avanti. - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marketing\/situazione-digitale-italiana-serve-un-passo-avanti\/","og_locale":"it_IT","og_type":"article","og_title":"Situazione digitale italiana, serve un passo avanti. - Article Marketing","og_description":"Emerge da un'analisi del CNA un' arretratezza dell'Italia nei confronti del digitale. Molte Pmi risultano ancora sprovviste dei principali strumenti tecnologici in grado di garantire la digitalizzazione.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marketing\/situazione-digitale-italiana-serve-un-passo-avanti\/","og_site_name":"Article Marketing","article_published_time":"2015-08-25T15:15:18+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marketing\/situazione-digitale-italiana-serve-un-passo-avanti\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marketing\/situazione-digitale-italiana-serve-un-passo-avanti\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Situazione digitale italiana, serve un passo avanti.","datePublished":"2015-08-25T15:15:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marketing\/situazione-digitale-italiana-serve-un-passo-avanti\/"},"wordCount":523,"commentCount":0,"keywords":["digitale","tecnologia"],"articleSection":["Marketing"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marketing\/situazione-digitale-italiana-serve-un-passo-avanti\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marketing\/situazione-digitale-italiana-serve-un-passo-avanti\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marketing\/situazione-digitale-italiana-serve-un-passo-avanti\/","name":"Situazione digitale italiana, serve un passo avanti. - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2015-08-25T15:15:18+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marketing\/situazione-digitale-italiana-serve-un-passo-avanti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marketing\/situazione-digitale-italiana-serve-un-passo-avanti\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marketing\/situazione-digitale-italiana-serve-un-passo-avanti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Situazione digitale italiana, serve un passo avanti."}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/48777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=48777"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/48777\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=48777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=48777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=48777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}