{"id":48938,"date":"2015-09-08T13:15:40","date_gmt":"2015-09-08T11:15:40","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/pubblicato-il-bilancio-2014-sa8000-del-gruppo-serenissima-ristorazione-la-soddisfazione-del-presidente-mario-putin-2\/"},"modified":"2015-09-08T13:15:40","modified_gmt":"2015-09-08T11:15:40","slug":"pubblicato-il-bilancio-2014-sa8000-del-gruppo-serenissima-ristorazione-la-soddisfazione-del-presidente-mario-putin-2","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/pubblicato-il-bilancio-2014-sa8000-del-gruppo-serenissima-ristorazione-la-soddisfazione-del-presidente-mario-putin-2\/","title":{"rendered":"Pubblicato il bilancio 2014 SA8000 del Gruppo Serenissima Ristorazione: la soddisfazione del Presidente Mario Putin"},"content":{"rendered":"<p><em><strong>Il bilancio 2014 relativo alla SA8000 rivela come il Gruppo <a href=\"http:\/\/serenissimaristorazione.myblog.it\/\" title=\"Il Blog di Serenissima Ristorazione \">Serenissima Ristorazione<\/a> possa essere definita una realt&agrave; dall&#8217;elevata etica, professionalit&agrave; e responsabilit&agrave; sociale con ampia soddisfazione del Presidente Mario Putin.<\/strong><\/em><br \/>\nResponsabilit&agrave; sociale di Serenissima Ristorazione: bilancio commentato dal Presidente Mario Putin<br \/>\nAderente al Sistema di Gestione SA8000, <strong>Serenissima Ristorazione<\/strong> ha pubblicato il bilancio 2014 ad esso relativo. Il Presidente <strong>Mario Putin<\/strong> ha infatti posto sempre particolare attenzione al valore della responsabilit&agrave; sociale, volta a creare ambienti di lavoro caratterizzati da rispetto, etica e professionalit&agrave;. Il Sistema di Gestione SA8000 &egrave; volto a stabilire uno standard per ogni azienda, a livello internazionale, atto a stabilire dei requisiti che determinino la vivibilit&agrave; del posto di lavoro, al fine di elargire una certificazione per quelle realt&agrave; aziendali che li rispettino. Dai risultati pubblicati da <strong>Serenissima Ristorazione<\/strong>, la societ&agrave; vicentina appare in grado di mantenere un&#8217;elevata stabilit&agrave; ed efficienza, nonostante il panorama nazionale ancora caratterizzato da complessit&agrave; e instabilit&agrave;. Il Presidente <strong>Mario Putin<\/strong> si dichiara particolarmente soddisfatto dei risultati conseguiti, i quali dimostrano quanto il Gruppo sia in grado di rispettare i propri dipendenti, riuscendo a creare una situazione positiva sia internamente, che esternamente, grazie alla gestione coerente e responsabile delle questioni di stampo imprenditoriale.<br \/>\nSerenissima Ristorazione: societ&agrave; del Presidente Mario Putin<br \/>\nNata negli anni Ottanta, <strong>Serenissima Ristorazione<\/strong> ha sede a Vicenza ed opera principalmente nei settori della ristorazione commerciale, scolastica, sociosanitaria, aziendale e collettiva. Il Presidente <strong>Mario Putin<\/strong> ha predisposto la societ&agrave; come composta da tredici consociate, ognuna delle quali in grado di coprire ogni segmento della produzione alimentare. I pasti trattati sono infatti relativi a cibi freschi, semifreschi, surgelati e secchi. La componente pi&ugrave; innovativa tra tutte &egrave; rappresentata dal Centro Cottura situato a Boara Pisana (PD) il quale mette in atto il metodo all&#8217;avanguardia denominato Cook &amp; Chill, basato sul legame refrigerato dei cibi e perci&ograve; in grado di fornire un livello di qualit&agrave; ed igiene non comparato dai metodi di produzione, conservazione e distribuzione tradizionali. <strong>Serenissima Ristorazione<\/strong> presenta sedi in Spagna e Polonia, costituendosi cos&igrave; come piccola multinazionale che si prefigge di esportare la qualit&agrave; alimentare italiana anche al di l&agrave; dei confini nazionali. Costantemente impegnata nel sociale, per volont&agrave; del Presidente <strong>Mario Putin<\/strong> vengono di frequente messe in atto azioni di project financing a livello ospedaliero, dove vengono forniti servizi di carattere non sanitario.<br \/>\n<em><strong>Per ulteriori particolari su Serenissima Ristorazione, visita la pagina della societ&agrave; del Presidente Mario Putin<\/strong><br \/><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Serenissima Ristorazione, societ\u00e0 vicentina attiva da oltre trent\u2019anni nel campo della ristorazione, garantisce un alto livello di responsabilit\u00e0 sociale, come dimostrato dal bilancio 2014 SA8000 del Gruppo , approvato dal Presidente Mario Putin<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[129],"tags":[47405,47404],"class_list":["post-48938","post","type-post","status-publish","format-standard","hentry","category-aziende","tag-mario-putin","tag-serenissima-ristorazione"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pubblicato il bilancio 2014 SA8000 del Gruppo Serenissima Ristorazione: la soddisfazione del Presidente Mario Putin - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/pubblicato-il-bilancio-2014-sa8000-del-gruppo-serenissima-ristorazione-la-soddisfazione-del-presidente-mario-putin-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pubblicato il bilancio 2014 SA8000 del Gruppo Serenissima Ristorazione: la soddisfazione del Presidente Mario Putin - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Serenissima Ristorazione, societ\u00e0 vicentina attiva da oltre trent\u2019anni nel campo della ristorazione, garantisce un alto livello di responsabilit\u00e0 sociale, come dimostrato dal bilancio 2014 SA8000 del Gruppo , approvato dal Presidente Mario Putin\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/pubblicato-il-bilancio-2014-sa8000-del-gruppo-serenissima-ristorazione-la-soddisfazione-del-presidente-mario-putin-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-08T11:15:40+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/aziende\\\/pubblicato-il-bilancio-2014-sa8000-del-gruppo-serenissima-ristorazione-la-soddisfazione-del-presidente-mario-putin-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/aziende\\\/pubblicato-il-bilancio-2014-sa8000-del-gruppo-serenissima-ristorazione-la-soddisfazione-del-presidente-mario-putin-2\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Pubblicato il bilancio 2014 SA8000 del Gruppo Serenissima Ristorazione: la soddisfazione del Presidente Mario Putin\",\"datePublished\":\"2015-09-08T11:15:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/aziende\\\/pubblicato-il-bilancio-2014-sa8000-del-gruppo-serenissima-ristorazione-la-soddisfazione-del-presidente-mario-putin-2\\\/\"},\"wordCount\":434,\"commentCount\":0,\"keywords\":[\"Mario Putin\",\"Serenissima Ristorazione\"],\"articleSection\":[\"Aziende\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/aziende\\\/pubblicato-il-bilancio-2014-sa8000-del-gruppo-serenissima-ristorazione-la-soddisfazione-del-presidente-mario-putin-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/aziende\\\/pubblicato-il-bilancio-2014-sa8000-del-gruppo-serenissima-ristorazione-la-soddisfazione-del-presidente-mario-putin-2\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/aziende\\\/pubblicato-il-bilancio-2014-sa8000-del-gruppo-serenissima-ristorazione-la-soddisfazione-del-presidente-mario-putin-2\\\/\",\"name\":\"Pubblicato il bilancio 2014 SA8000 del Gruppo Serenissima Ristorazione: la soddisfazione del Presidente Mario Putin - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2015-09-08T11:15:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/aziende\\\/pubblicato-il-bilancio-2014-sa8000-del-gruppo-serenissima-ristorazione-la-soddisfazione-del-presidente-mario-putin-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/aziende\\\/pubblicato-il-bilancio-2014-sa8000-del-gruppo-serenissima-ristorazione-la-soddisfazione-del-presidente-mario-putin-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/aziende\\\/pubblicato-il-bilancio-2014-sa8000-del-gruppo-serenissima-ristorazione-la-soddisfazione-del-presidente-mario-putin-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pubblicato il bilancio 2014 SA8000 del Gruppo Serenissima Ristorazione: la soddisfazione del Presidente Mario Putin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pubblicato il bilancio 2014 SA8000 del Gruppo Serenissima Ristorazione: la soddisfazione del Presidente Mario Putin - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/pubblicato-il-bilancio-2014-sa8000-del-gruppo-serenissima-ristorazione-la-soddisfazione-del-presidente-mario-putin-2\/","og_locale":"it_IT","og_type":"article","og_title":"Pubblicato il bilancio 2014 SA8000 del Gruppo Serenissima Ristorazione: la soddisfazione del Presidente Mario Putin - Article Marketing","og_description":"Serenissima Ristorazione, societ\u00e0 vicentina attiva da oltre trent\u2019anni nel campo della ristorazione, garantisce un alto livello di responsabilit\u00e0 sociale, come dimostrato dal bilancio 2014 SA8000 del Gruppo , approvato dal Presidente Mario Putin","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/pubblicato-il-bilancio-2014-sa8000-del-gruppo-serenissima-ristorazione-la-soddisfazione-del-presidente-mario-putin-2\/","og_site_name":"Article Marketing","article_published_time":"2015-09-08T11:15:40+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/pubblicato-il-bilancio-2014-sa8000-del-gruppo-serenissima-ristorazione-la-soddisfazione-del-presidente-mario-putin-2\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/pubblicato-il-bilancio-2014-sa8000-del-gruppo-serenissima-ristorazione-la-soddisfazione-del-presidente-mario-putin-2\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Pubblicato il bilancio 2014 SA8000 del Gruppo Serenissima Ristorazione: la soddisfazione del Presidente Mario Putin","datePublished":"2015-09-08T11:15:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/pubblicato-il-bilancio-2014-sa8000-del-gruppo-serenissima-ristorazione-la-soddisfazione-del-presidente-mario-putin-2\/"},"wordCount":434,"commentCount":0,"keywords":["Mario Putin","Serenissima Ristorazione"],"articleSection":["Aziende"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/pubblicato-il-bilancio-2014-sa8000-del-gruppo-serenissima-ristorazione-la-soddisfazione-del-presidente-mario-putin-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/pubblicato-il-bilancio-2014-sa8000-del-gruppo-serenissima-ristorazione-la-soddisfazione-del-presidente-mario-putin-2\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/pubblicato-il-bilancio-2014-sa8000-del-gruppo-serenissima-ristorazione-la-soddisfazione-del-presidente-mario-putin-2\/","name":"Pubblicato il bilancio 2014 SA8000 del Gruppo Serenissima Ristorazione: la soddisfazione del Presidente Mario Putin - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2015-09-08T11:15:40+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/pubblicato-il-bilancio-2014-sa8000-del-gruppo-serenissima-ristorazione-la-soddisfazione-del-presidente-mario-putin-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/pubblicato-il-bilancio-2014-sa8000-del-gruppo-serenissima-ristorazione-la-soddisfazione-del-presidente-mario-putin-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/aziende\/pubblicato-il-bilancio-2014-sa8000-del-gruppo-serenissima-ristorazione-la-soddisfazione-del-presidente-mario-putin-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Pubblicato il bilancio 2014 SA8000 del Gruppo Serenissima Ristorazione: la soddisfazione del Presidente Mario Putin"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/48938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=48938"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/48938\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=48938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=48938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=48938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}