{"id":48940,"date":"2015-09-08T19:26:55","date_gmt":"2015-09-08T17:26:55","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/marco-zoppi-voluntary-disclosure-tra-criticit%2525c3%2525a0-della-regolamentazione\/"},"modified":"2018-10-26T00:35:01","modified_gmt":"2018-10-25T22:35:01","slug":"marco-zoppi-voluntary-disclosure-tra-criticit%2525c3%2525a0-della-regolamentazione","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marco-zoppi-voluntary-disclosure-tra-criticit%2525c3%2525a0-della-regolamentazione\/","title":{"rendered":"Marco Zoppi: Voluntary Disclosure tra criticit\u00e0 della regolamentazione"},"content":{"rendered":"<p>Ultime news e utilit&agrave; dei servizi di calcolo in Svizzera di Global Capital Trust <strong>Dal 1 gennaio 2015 &egrave; entrata a far parte dell&#8217;ordinamento italiano la nuova regolamentazione in tema di emersione e ritorno dei capitali tenuti in modo irregolare all&rsquo;estero, la legge n. 186 del 15\/12\/2014 sulla c.d. Voluntary Disclosure. Il fondatore e Amministratore Delegato della societ&agrave; svizzera Global Capital Trust, Marco Zoppi, ci aiuta ad apprenderne le peculiarit&agrave;:<\/strong> &ldquo;Con l&#8217;introduzione dell&#8217;istituto della Voluntary Disclosure &ndash; ci spiega il dott. Marco Zoppi, viene concessa la facolt&agrave; di autodenuncia con regolarizzazione della propria posizione a quei contribuenti italiani che detengano posizioni non regolarizzate in paesi esteri; naturalmente &egrave; richiesto il pagamento delle tasse eluse e delle relative ammende. Il termine finale per aderire alla Voluntary Disclosure &egrave; il 30 settembre 2015, ma rumors insistenti provenienti anche da fonti rilevanti parlano di uno slittamento del termine quantomeno alla fine dell&#8217;anno. La decisione di muovere in avanti il termine di scadenza &egrave; sicuramente importante per tutti i professionisti &#8211; dice Marco Zoppi &#8211; si &egrave; per l&#8217;appunto in attesa di molteplici circolari ministeriali che dovranno chiarire tutti i punti ancora oscuri della normativa sulla Voluntary Disclosure. Un punto da chiarire, per fare un esempio, &egrave; quello relativo ai casi in cui si verifica il raddoppio dei tempi per il calcolo della Voluntary Disclosure. La normativa, infatti, stabilisce che al ricorrere di reati penali fiscali, come il falso in bilancio o le false fatturazioni, la base temporale per il calcolo della Voluntary Disclosure raddoppi, passando da 5 a 10 anni. Ancora da chiarire sono le peculiarit&agrave; della giustificazione dei prelievi da conto corrente effettuati in contanti. Se da una parte viene fissata l&#8217;esigenza di giustificarli, dall&rsquo;altra non c&rsquo;&egrave; chiarezza relativamente agli elementi a base di detta giustificazione. Visto che Global Capital Trust &egrave; una societ&agrave; svizzera, voglio menzionare anche la situazione relativa ai frontalieri. Per coloro tra i frontalieri che vogliano fare la Voluntary Disclosure non &egrave; stato fino a questo momento ben definito l&#8217;utilizzo del &ldquo;secondo pilastro&rdquo; fiscale svizzero&rdquo;. <strong>Vari operatori del settore sono attivi nel fornire aiuto nella procedura di adesione alla Voluntary Disclosure, secondo Marco Zoppi quali possono essere i vantaggi di rivolgersi ad una societ&agrave; svizzera come Global Capital Trust?<\/strong> <strong><\/strong> &ldquo;Global Capital Trust si presenta come partner di calcolo estero riguardo ai professionisti italiani. Entrando pi&ugrave; in dettaglio, Global Capital Trust prospetta di assistere i professionisti italiani sia nelle prudenti operazioni di selezione delle movimentazioni all&rsquo;estero, mettendo a frutto &#8211; ribadisce il dottor Marco Zoppi &#8211; i rapporti forti con i pi&ugrave; affermati istituti internazionali, che nella fase di calcolo vero e proprio dei costi della Voluntary Disclosure. Proprio in rapporto ai calcoli, Global Capital Trust pu&ograve; contare sulla puntualit&agrave; di un programma ad hoc, creato in collaborazione con lo studio Mattavelli di Lugano, che consente di ottenere anche un veloce paragone tra costi della Voluntary Disclosure forfettaria ed analitica. Riteniamo &#8211; ribadisce Marco Zoppi &#8211; di disporre della giusta professionalit&agrave; per poter appoggiare il professionista italiano in questa delicata prima fase, mettendo anche gli assistiti nelle condizioni di poter valutare la Voluntary Disclosure in modalit&agrave; assolutamente riservata, come una compagnia svizzera come Global Capital Trust in questo momento &egrave; in grado di fare&rdquo;. <strong>GLOBAL CAPITAL TRUST AG<\/strong> <br \/>8, Kolinplatz 6300 &#8211; Zug CH +41 41 7267766 <br \/>info@globalcapitaltrust.ch <br \/>www.globalcapitaltrust.ch\/it\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marco Zoppi: Voluntary Disclosure tra criticit\u00e0 della regolamentazione, ultime news e utilit\u00e0 dei servizi di calcolo in Svizzera di Global Capital Trust<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[59],"tags":[],"class_list":["post-48940","post","type-post","status-publish","format-standard","hentry","category-economia-e-lavoro"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Marco Zoppi: Voluntary Disclosure tra criticit\u00e0 della regolamentazione - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marco-zoppi-voluntary-disclosure-tra-criticit%25c3%25a0-della-regolamentazione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marco Zoppi: Voluntary Disclosure tra criticit\u00e0 della regolamentazione - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Marco Zoppi: Voluntary Disclosure tra criticit\u00e0 della regolamentazione, ultime news e utilit\u00e0 dei servizi di calcolo in Svizzera di Global Capital Trust\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marco-zoppi-voluntary-disclosure-tra-criticit%25c3%25a0-della-regolamentazione\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-08T17:26:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-25T22:35:01+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/marco-zoppi-voluntary-disclosure-tra-criticit%2525c3%2525a0-della-regolamentazione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/marco-zoppi-voluntary-disclosure-tra-criticit%2525c3%2525a0-della-regolamentazione\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Marco Zoppi: Voluntary Disclosure tra criticit\u00e0 della regolamentazione\",\"datePublished\":\"2015-09-08T17:26:55+00:00\",\"dateModified\":\"2018-10-25T22:35:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/marco-zoppi-voluntary-disclosure-tra-criticit%2525c3%2525a0-della-regolamentazione\\\/\"},\"wordCount\":578,\"commentCount\":0,\"articleSection\":[\"Economia e lavoro\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/marco-zoppi-voluntary-disclosure-tra-criticit%2525c3%2525a0-della-regolamentazione\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/marco-zoppi-voluntary-disclosure-tra-criticit%2525c3%2525a0-della-regolamentazione\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/marco-zoppi-voluntary-disclosure-tra-criticit%2525c3%2525a0-della-regolamentazione\\\/\",\"name\":\"Marco Zoppi: Voluntary Disclosure tra criticit\u00e0 della regolamentazione - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2015-09-08T17:26:55+00:00\",\"dateModified\":\"2018-10-25T22:35:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/marco-zoppi-voluntary-disclosure-tra-criticit%2525c3%2525a0-della-regolamentazione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/marco-zoppi-voluntary-disclosure-tra-criticit%2525c3%2525a0-della-regolamentazione\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/marco-zoppi-voluntary-disclosure-tra-criticit%2525c3%2525a0-della-regolamentazione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Marco Zoppi: Voluntary Disclosure tra criticit\u00e0 della regolamentazione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Marco Zoppi: Voluntary Disclosure tra criticit\u00e0 della regolamentazione - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marco-zoppi-voluntary-disclosure-tra-criticit%25c3%25a0-della-regolamentazione\/","og_locale":"it_IT","og_type":"article","og_title":"Marco Zoppi: Voluntary Disclosure tra criticit\u00e0 della regolamentazione - Article Marketing","og_description":"Marco Zoppi: Voluntary Disclosure tra criticit\u00e0 della regolamentazione, ultime news e utilit\u00e0 dei servizi di calcolo in Svizzera di Global Capital Trust","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marco-zoppi-voluntary-disclosure-tra-criticit%25c3%25a0-della-regolamentazione\/","og_site_name":"Article Marketing","article_published_time":"2015-09-08T17:26:55+00:00","article_modified_time":"2018-10-25T22:35:01+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marco-zoppi-voluntary-disclosure-tra-criticit%2525c3%2525a0-della-regolamentazione\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marco-zoppi-voluntary-disclosure-tra-criticit%2525c3%2525a0-della-regolamentazione\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Marco Zoppi: Voluntary Disclosure tra criticit\u00e0 della regolamentazione","datePublished":"2015-09-08T17:26:55+00:00","dateModified":"2018-10-25T22:35:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marco-zoppi-voluntary-disclosure-tra-criticit%2525c3%2525a0-della-regolamentazione\/"},"wordCount":578,"commentCount":0,"articleSection":["Economia e lavoro"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marco-zoppi-voluntary-disclosure-tra-criticit%2525c3%2525a0-della-regolamentazione\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marco-zoppi-voluntary-disclosure-tra-criticit%2525c3%2525a0-della-regolamentazione\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marco-zoppi-voluntary-disclosure-tra-criticit%2525c3%2525a0-della-regolamentazione\/","name":"Marco Zoppi: Voluntary Disclosure tra criticit\u00e0 della regolamentazione - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2015-09-08T17:26:55+00:00","dateModified":"2018-10-25T22:35:01+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marco-zoppi-voluntary-disclosure-tra-criticit%2525c3%2525a0-della-regolamentazione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marco-zoppi-voluntary-disclosure-tra-criticit%2525c3%2525a0-della-regolamentazione\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/marco-zoppi-voluntary-disclosure-tra-criticit%2525c3%2525a0-della-regolamentazione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Marco Zoppi: Voluntary Disclosure tra criticit\u00e0 della regolamentazione"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/48940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=48940"}],"version-history":[{"count":1,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/48940\/revisions"}],"predecessor-version":[{"id":64716,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/48940\/revisions\/64716"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=48940"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=48940"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=48940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}