{"id":49059,"date":"2015-09-16T16:10:55","date_gmt":"2015-09-16T14:10:55","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/pianetacoppia-per-creare-la-relazionea%252580%2525a6-giusta\/"},"modified":"2015-09-16T16:10:55","modified_gmt":"2015-09-16T14:10:55","slug":"pianetacoppia-per-creare-la-relazionea%252580%2525a6-giusta","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/pianetacoppia-per-creare-la-relazionea%252580%2525a6-giusta\/","title":{"rendered":"PianetaCoppia, per creare la relazione\u2026 giusta"},"content":{"rendered":"<p>Nell&rsquo;era del dating online, dei social network, delle chat e delle applicazioni smartphone che aumentano le occasioni per incontrare persone senza un grande sforzo, flirtare, creare relazioni, a pi&ugrave; livelli,c&rsquo;&egrave; qualcuno che va controtendenza: Giorgio Gallinotto, classe 1966, laurea alla Bocconi Master in Business &amp; Administration presso l&rsquo;University of Notredame negli Stati Uniti. Dopo oltre 20 anni di esperienza manageriale per multinazionali italiane ed estere, assieme a un team di professionisti (provenienti da diversi settori, dalla nutrizione al fitness, dall&rsquo;emotional training alla consulenza di immagine) ha fondato a Milano Pianeta Coppia.<br \/>Un&rsquo;agenzia matrimoniale ai tempi di Internet? Bella sfida o sta cambiando qualcosa? &laquo;Benvengano tutti gli strumenti che facilitano l&rsquo;incontro fra le persone che hanno desiderio di incontrarsi, e fra questi internet &egrave; senza dubbio il pi&ugrave; potente&raquo;, commenta Giorgio Gallinotto: &laquo;chiunque sia alla ricerca di un partner pu&ograve; &minus; con pochi clic &minus; mettersi &ldquo;in vetrina&rdquo;: foto, descrizione di s&eacute;, caratteristiche del partner desiderato. Ultimamente molti &ldquo;delusi&rdquo; stanno per&ograve; abbandonando la rete, che nasconde diverse insidie, false identit&agrave; o profili creati ad hoc.<br \/> Chi va in <a href=\"http:\/\/www.pianetacoppia.it\/agenzia-matrimoniale-milano-offerta-donne\/\" target=\"_blank\" title=\"Agenzia Matrimoniale PianetaCoppia\">agenzia matrimoniale Milano<\/a> vuole davvero investire in una relazione, si iscrive non per conoscere centinaia di persone ma, al contrario, per selezionare accuratamente i propri incontri. Per&ograve; la nostra funzione non &egrave; solo quella di organizzare incontri. Pianeta Coppia segue, prepara e riordina le tessere del puzzle emotivo, affettivo. Con il nostro team di professionisti, mettiamo a disposizione di chi &egrave; alla ricerca di un partner una serie di interventi mirati, che coinvolgono la sfera emotiva, fisica e affettiva. Lavoriamo insomma a tutto campo, dall&rsquo;estetica al modo di esprimersi, dall&rsquo;abbigliamento alle abitudini&raquo;.<br \/>Ma qual &egrave; il punto di partenza del percorso? &laquo;Per saper amare bisogna amarsi&raquo;, risponde la dottoressa Laura Intiso, love coach, psicoterapeuta e sessuologa di Pianeta Coppia. &laquo;Si tratta di un concetto fondamentale, che spesso dimentichiamo. Lo stato di benessere &egrave; un bene prezioso per liberare il proprio cuore verso nuovi incontri e amori. Ed essere consapevoli dei punti di forza personali, aiuta anche a riconoscere ci&ograve; che si ha da offrire ai potenziali partner. Dunque, le nostre qualit&agrave; personali le dobbiamo riconoscere e valorizzare, a volte potenziare, altre volte organizzare e orientare verso il nostro obiettivo di conquista.<br \/>Talvolta, prima della effettiva ricerca dell&rsquo;anima gemella, pu&ograve; essere utile invece esplorare i meccanismi affettivi che ci portiamo dentro fin dall&rsquo;infanzia e che ci condizionano ancora nelle scelte affettive al fine di elaborarli. Spesso entrano in gioco paure spesso inconsapevoli che ci spingono ad allontanarci o peggio a far allontanare il potenziale partner senza che ce ne rendiamo conto&raquo;, continua la love coach. &laquo;Ci pu&ograve; essere per esempio un blocco legato all&rsquo;intimit&agrave;, anche se poi razionalmente, a parole, si dice di voler trovare un partner. Se dopo10 incontri nessuno suscita il minimo interesse, forse vale la pena di chiederci se la nostra voglia di coppia &egrave; soltanto teorica o se di fondo nutriamo delle resistenze, magari inconsce&raquo;.<br \/>&laquo;A volte c&rsquo;&egrave; un impulso inconscio ma tenace che agisce in profondit&agrave; e porta a ripetere sempre lo stesso copione affettivo&raquo;, suggerisce ancora la psicoterapeuta. &laquo;E la ragione numero uno per la quale molte donne non hanno storie d&rsquo;amore soddisfacenti non &egrave; che non sono affascinanti e seducenti, &egrave; che scelgono sempre e solo uomini che, alla resa dei conti, si dimostrano identici l&rsquo;uno all&rsquo;altro. Cos&igrave;, pur cambiando partner, si rimettono sempre pi&ugrave; o meno con lo stesso tipo di uomo: sbagliato. Al contrario e purtroppo, non mettono in discussione il fatto che cercano di continuo l&rsquo;uomo sbagliato e non riescono a &ldquo;vedere&rdquo;, proprio in senso letterale, l&rsquo;uomo giusto&raquo;.<br \/>Insomma, l&rsquo;identikit del potenziale partner &egrave; un aspetto delicato&hellip; &laquo;Al potenziale partner oggi si chiede molto&raquo;, risponde la dottoressa Intiso. &laquo;E questo pu&ograve; anche andar bene. Non bisogna per&ograve; esagerare. Il che non significa accontentarsi, ma fare i conti con l&rsquo;immagine interiore che abbiamo del nostro partner ideale. A volte ci allontana dalla felicit&agrave;. C&rsquo;&egrave; probabilmente pi&ugrave; di un compagno possibile con il quale essere non solo serene, ma davvero felici&raquo;.<\/p>\n<p>&laquo;Avere una mente aperta e disponibile nel conoscere qualcuno, un atteggiamento esplorativo e curioso&raquo;, &egrave; il consiglio dell&rsquo;esperta. &laquo;Rimanere bloccate su certi dettagli, requisiti che lui deve avere a priori, non sempre funziona. Anche perch&eacute;, non tutte le donne desiderano realmente quello che dicono di volere&hellip; Cos&igrave;, scavando nel profondo durante i colloqui, l&rsquo;identikit iniziale tante volte viene limato, bisgona aggiustare il tiro; forse qualcosa in noi &egrave; cambiato, forse si &egrave; evoluto&hellip; Che sorpresa allora scoprire che quell&rsquo;identikit dell&rsquo;uomo ideale oggi non regge pi&ugrave;, e si desidera un compagno diverso! &raquo;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nella ricerca dell&#8217;anima gemella pu\u00f2 essere utile rivolgersi ad un&#8217;agenzia matrimoniale specializzata nel trovare il giusto partner e creare un incontro speciale.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[429],"tags":[27048,2279,14027,39745,1343,8213,9654],"class_list":["post-49059","post","type-post","status-publish","format-standard","hentry","category-professionisti","tag-agenzia-matrimoniale","tag-amore","tag-anima-gemella","tag-incontri","tag-milano","tag-partner","tag-single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PianetaCoppia, per creare la relazione\u2026 giusta - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/pianetacoppia-per-creare-la-relazionea%2580%25a6-giusta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PianetaCoppia, per creare la relazione\u2026 giusta - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Nella ricerca dell&#039;anima gemella pu\u00f2 essere utile rivolgersi ad un&#039;agenzia matrimoniale specializzata nel trovare il giusto partner e creare un incontro speciale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/pianetacoppia-per-creare-la-relazionea%2580%25a6-giusta\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-16T14:10:55+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/pianetacoppia-per-creare-la-relazionea%252580%2525a6-giusta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/pianetacoppia-per-creare-la-relazionea%252580%2525a6-giusta\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"PianetaCoppia, per creare la relazione\u2026 giusta\",\"datePublished\":\"2015-09-16T14:10:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/pianetacoppia-per-creare-la-relazionea%252580%2525a6-giusta\\\/\"},\"wordCount\":862,\"commentCount\":0,\"keywords\":[\"agenzia matrimoniale\",\"amore\",\"anima gemella\",\"incontri\",\"milano\",\"partner\",\"single\"],\"articleSection\":[\"Professionisti\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/pianetacoppia-per-creare-la-relazionea%252580%2525a6-giusta\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/pianetacoppia-per-creare-la-relazionea%252580%2525a6-giusta\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/pianetacoppia-per-creare-la-relazionea%252580%2525a6-giusta\\\/\",\"name\":\"PianetaCoppia, per creare la relazione\u2026 giusta - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2015-09-16T14:10:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/pianetacoppia-per-creare-la-relazionea%252580%2525a6-giusta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/pianetacoppia-per-creare-la-relazionea%252580%2525a6-giusta\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/pianetacoppia-per-creare-la-relazionea%252580%2525a6-giusta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PianetaCoppia, per creare la relazione\u2026 giusta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PianetaCoppia, per creare la relazione\u2026 giusta - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/pianetacoppia-per-creare-la-relazionea%2580%25a6-giusta\/","og_locale":"it_IT","og_type":"article","og_title":"PianetaCoppia, per creare la relazione\u2026 giusta - Article Marketing","og_description":"Nella ricerca dell'anima gemella pu\u00f2 essere utile rivolgersi ad un'agenzia matrimoniale specializzata nel trovare il giusto partner e creare un incontro speciale.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/pianetacoppia-per-creare-la-relazionea%2580%25a6-giusta\/","og_site_name":"Article Marketing","article_published_time":"2015-09-16T14:10:55+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/pianetacoppia-per-creare-la-relazionea%252580%2525a6-giusta\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/pianetacoppia-per-creare-la-relazionea%252580%2525a6-giusta\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"PianetaCoppia, per creare la relazione\u2026 giusta","datePublished":"2015-09-16T14:10:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/pianetacoppia-per-creare-la-relazionea%252580%2525a6-giusta\/"},"wordCount":862,"commentCount":0,"keywords":["agenzia matrimoniale","amore","anima gemella","incontri","milano","partner","single"],"articleSection":["Professionisti"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/pianetacoppia-per-creare-la-relazionea%252580%2525a6-giusta\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/pianetacoppia-per-creare-la-relazionea%252580%2525a6-giusta\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/pianetacoppia-per-creare-la-relazionea%252580%2525a6-giusta\/","name":"PianetaCoppia, per creare la relazione\u2026 giusta - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2015-09-16T14:10:55+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/pianetacoppia-per-creare-la-relazionea%252580%2525a6-giusta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/pianetacoppia-per-creare-la-relazionea%252580%2525a6-giusta\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/pianetacoppia-per-creare-la-relazionea%252580%2525a6-giusta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"PianetaCoppia, per creare la relazione\u2026 giusta"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/49059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=49059"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/49059\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=49059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=49059"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=49059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}