{"id":49316,"date":"2015-10-01T18:26:50","date_gmt":"2015-10-01T16:26:50","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/a%80cla%80%99arte-del-breakfasta%80%9d-il-nuovo-evento-di-formazione-promosso-da-fas-italia\/"},"modified":"2018-10-26T00:35:36","modified_gmt":"2018-10-25T22:35:36","slug":"a%80cla%80%99arte-del-breakfasta%80%9d-il-nuovo-evento-di-formazione-promosso-da-fas-italia","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/a%80cla%80%99arte-del-breakfasta%80%9d-il-nuovo-evento-di-formazione-promosso-da-fas-italia\/","title":{"rendered":"\u201cL\u2019Arte del Breakfast\u201d: il nuovo evento di formazione promosso da Fas Italia"},"content":{"rendered":"<p><em>Firenze, 1 ottobre 2015 &ndash; <\/em><strong>Fas Italia<\/strong> presenta il nuovo seminario &ldquo;<em>L&#8217;Arte del Breakfast<\/em>&rdquo; che si terr&agrave; a <strong>Firenze il 21 Ottobre 2015<\/strong>. L&#8217;evento &egrave; completamente gratuito e ma &egrave; riservato a numero chiuso di partecipanti. Chi desidera prendere parte all&#8217;evento potr&agrave; prenotare il proprio posto collegandosi alla seguente pagina web: http:\/\/www.fas-italia.it\/fiere-e-manifestazioni\/larte-del-breakfast_1761-28094.html. Inoltre, sempre tramite la stessa pagina &egrave; possibile scaricare il programma completo dell&#8217;evento.<\/p>\n<p> Il seminario &egrave; dedicato agli operatori del settore che desiderano scoprire come <strong>migliorare e rinnovare il servizio della prima colazione in albergo<\/strong>. Il seminario &egrave; un&#8217;ottima occasione per aggiornarsi e confrontarsi con specialisti, nonch&eacute; costituisce un modo per reperire nuove idee sulle quale far partire nuovi investimenti.<\/p>\n<p> In particolare, la prima colazione &egrave; un elemento distintivo di un albergo, tramite la quale si possono ottenere graditi commenti positivi e pubblicit&agrave; da parte dei clienti soddisfatti. Questo aspetto pu&ograve; consentire di lasciare <strong>un&#8217;immagine vincente della struttura<\/strong>, e aiuta a ottenere concreti riscontri anche sui <strong>social network<\/strong>; questi ultimi, infine, permettono di <strong>attirare nuovi clienti<\/strong>.<\/p>\n<p> Nel programma del seminario sono previsti <strong>speech professionali sul tema del breakfast<\/strong>. Vediamo nel dettaglio quali sono gli interventi e i relatori, che parteciperanno all&#8217;evento:<\/p>\n<p> &#8220;<strong>Managerialit&agrave; e strumenti pratici al servizio dell&rsquo;albergatore<\/strong>&#8220;: l&#8217;intervento avr&agrave; come relatore Giacomo Pini<strong>,<\/strong> autore dell&#8217;omonimo libro.<\/p>\n<p> &#8220;Ospitalit&agrave; Accessibile&#8221; anche nel breakfast &egrave; il titolo dell&#8217;intervento che vedr&agrave; protagonista Roberto Vitali, presidente Village For All.<\/p>\n<p> <strong>La gestione dei costi<\/strong>, invece, &egrave; al centro dell&#8217;intervento a cura di Giovanni Carobbi, che offrir&agrave; ulteriori spunti ai partecipanti su come calcolare e ottimizzare le spese.<\/p>\n<p> &ldquo;Le innovazioni nel breakfast&rdquo;: questo &egrave; il titolo che vedr&agrave; intervenire Fas Italia insieme a SmartHamster.com nella presentazione di <strong>App Smart Room Service<\/strong>. L&#8217;applicazione consente di <strong>ordinare il servizio in camera in ben 12 lingue<\/strong>. &Eacute; un dato di fatto che i nostri alberghi sono sempre pi&ugrave; frequentati da ospiti internazionali, e molti di loro sono abituati a ordinare direttamente in camera. Inoltre, bisogna considerare che non tutti gli stranieri padroneggiano la lingua inglese o l&#8217;italiano. L&#8217;App Smart Room, perci&ograve;, consente di <strong>invogliare l&#8217;ospite a ordinare in camera in maniera veloce<\/strong> e, soprattutto, leggendo il menu in una lingua che pu&ograve; comprendere.<\/p>\n<p> Il Dott. Nicola Serpieri di Firenze HACCP avr&agrave; il compito di illustrare le nuove <strong>regole e le normative che riguardano il servizio della colazione<\/strong> con un intervento intitolato &ldquo;HACCP e nuove normative per la prima colazione&rdquo;.<\/p>\n<p> La buona reputazione di un albergo dipende anche dalle recensioni che la struttura riceve. Molte di queste informazioni, come detto, sono veicolare dai social network. Su questo tema, molto attuale, &egrave; incentrato l&#8217;intervento di Stefania Corbelli, che offrir&agrave; ai partecipanti ulteriori consigli sull&#8217;<strong>utilizzo degli strumenti social e su come sfruttare al meglio i media per costruirsi un&#8217;immagine vincente.<\/strong> <\/p>\n<p> Tra gli ultimi interventi figura la relazione di Mario Romanelli di Travel Appeal dal titolo evocativo, &ldquo;Pane, burro e reputation&rdquo;, che riflette sull&#8217;importanza che ha per gli alberghi la prima colazione ai fini della reputazione, per fidelizzare in questo modo la clientela<\/p>\n<p> A quest&#8217;ultima seguir&agrave; l&rsquo;intervento della Dott.ssa Chiara Roma, Dietista AIC, tratta un argomento di stretta attualit&agrave;, ossia quello della celiachia e delle intolleranze alimentari, offrendo una nuova prospettiva. Se da un lato offrire un buffet diversificato pu&ograve; rappresentare un&#8217;operazione complessa, d&#8217;altro canto pu&ograve; essere <strong>un&#8217;opportunit&agrave; da cogliere nel modo pi&ugrave; adeguato<\/strong>.<\/p>\n<p> Infine, ricordiamo che il seminario &ldquo;L&#8217;Arte del Breakfast&rdquo; si terr&agrave; <strong>mercoled&igrave; 21 ottobre 2015<\/strong>. Le registrazioni dei partecipanti avranno inizio alle ore 9,00, mentre l&#8217;avvio del corso &egrave; previsto alle 9,30 per concludersi alle ore 18,00. Il seminario si svolger&agrave; presso <strong>Italiana Hotels Florence<\/strong>, situato in Viale Europa, 205 a Firenze.<\/p>\n<p> L&#8217;evento offre la possibilit&agrave; ai partecipanti di usufruire di un servizio di consulenza, disponibile per tutta la giornata, grazie al quale poter scoprire praticamente come organizzare e rendere redditizio il servizio della prima colazione in albergo e avere suggerimenti interessanti su come favorire e incrementare il proprio business.<\/p>\n<p> Fas Italia si dimostra in prima fila negli eventi di formazione che mirano a offrire agli operatori del settore occasioni di incontro e approfondimento, al fine di migliorare e ottimizzare l&#8217;attivit&agrave; ricettiva.<br \/>\n<strong>Fas Italia<\/strong><br \/> Via Giuseppe la Farina, 30R, Firenze<br \/> Tel: 055 470536-0552479578<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fas Italia presenta il nuovo seminario di formazione dedicato all&#8217;organizzazione e alla gestione del servizio di prima colazione in albergo. Possono partecipare al seminario tutti gli operatori del settore che desiderano aggiornarsi e trovare nuove idee per l&#8217;ottimizzazione del servizio di prima colazione in albergo.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[388],"tags":[],"class_list":["post-49316","post","type-post","status-publish","format-standard","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201cL\u2019Arte del Breakfast\u201d: il nuovo evento di formazione promosso da Fas Italia - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/a?cla??arte-del-breakfasta??-il-nuovo-evento-di-formazione-promosso-da-fas-italia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cL\u2019Arte del Breakfast\u201d: il nuovo evento di formazione promosso da Fas Italia - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Fas Italia presenta il nuovo seminario di formazione dedicato all&#039;organizzazione e alla gestione del servizio di prima colazione in albergo. Possono partecipare al seminario tutti gli operatori del settore che desiderano aggiornarsi e trovare nuove idee per l&#039;ottimizzazione del servizio di prima colazione in albergo.\" \/>\n<meta property=\"og:url\" content=\"\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-01T16:26:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-25T22:35:36+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/a%80cla%80%99arte-del-breakfasta%80%9d-il-nuovo-evento-di-formazione-promosso-da-fas-italia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/a%80cla%80%99arte-del-breakfasta%80%9d-il-nuovo-evento-di-formazione-promosso-da-fas-italia\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"\u201cL\u2019Arte del Breakfast\u201d: il nuovo evento di formazione promosso da Fas Italia\",\"datePublished\":\"2015-10-01T16:26:50+00:00\",\"dateModified\":\"2018-10-25T22:35:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/a%80cla%80%99arte-del-breakfasta%80%9d-il-nuovo-evento-di-formazione-promosso-da-fas-italia\\\/\"},\"wordCount\":736,\"commentCount\":0,\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/a%80cla%80%99arte-del-breakfasta%80%9d-il-nuovo-evento-di-formazione-promosso-da-fas-italia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/a%80cla%80%99arte-del-breakfasta%80%9d-il-nuovo-evento-di-formazione-promosso-da-fas-italia\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/a%80cla%80%99arte-del-breakfasta%80%9d-il-nuovo-evento-di-formazione-promosso-da-fas-italia\\\/\",\"name\":\"\u201cL\u2019Arte del Breakfast\u201d: il nuovo evento di formazione promosso da Fas Italia - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2015-10-01T16:26:50+00:00\",\"dateModified\":\"2018-10-25T22:35:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/a%80cla%80%99arte-del-breakfasta%80%9d-il-nuovo-evento-di-formazione-promosso-da-fas-italia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/a%80cla%80%99arte-del-breakfasta%80%9d-il-nuovo-evento-di-formazione-promosso-da-fas-italia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/a%80cla%80%99arte-del-breakfasta%80%9d-il-nuovo-evento-di-formazione-promosso-da-fas-italia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cL\u2019Arte del Breakfast\u201d: il nuovo evento di formazione promosso da Fas Italia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cL\u2019Arte del Breakfast\u201d: il nuovo evento di formazione promosso da Fas Italia - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/a?cla??arte-del-breakfasta??-il-nuovo-evento-di-formazione-promosso-da-fas-italia\/","og_locale":"it_IT","og_type":"article","og_title":"\u201cL\u2019Arte del Breakfast\u201d: il nuovo evento di formazione promosso da Fas Italia - Article Marketing","og_description":"Fas Italia presenta il nuovo seminario di formazione dedicato all'organizzazione e alla gestione del servizio di prima colazione in albergo. Possono partecipare al seminario tutti gli operatori del settore che desiderano aggiornarsi e trovare nuove idee per l'ottimizzazione del servizio di prima colazione in albergo.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/a?cla??arte-del-breakfasta??-il-nuovo-evento-di-formazione-promosso-da-fas-italia\/","og_site_name":"Article Marketing","article_published_time":"2015-10-01T16:26:50+00:00","article_modified_time":"2018-10-25T22:35:36+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/a%80cla%80%99arte-del-breakfasta%80%9d-il-nuovo-evento-di-formazione-promosso-da-fas-italia\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/a%80cla%80%99arte-del-breakfasta%80%9d-il-nuovo-evento-di-formazione-promosso-da-fas-italia\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"\u201cL\u2019Arte del Breakfast\u201d: il nuovo evento di formazione promosso da Fas Italia","datePublished":"2015-10-01T16:26:50+00:00","dateModified":"2018-10-25T22:35:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/a%80cla%80%99arte-del-breakfasta%80%9d-il-nuovo-evento-di-formazione-promosso-da-fas-italia\/"},"wordCount":736,"commentCount":0,"articleSection":["Eventi"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/a%80cla%80%99arte-del-breakfasta%80%9d-il-nuovo-evento-di-formazione-promosso-da-fas-italia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/a%80cla%80%99arte-del-breakfasta%80%9d-il-nuovo-evento-di-formazione-promosso-da-fas-italia\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/a%80cla%80%99arte-del-breakfasta%80%9d-il-nuovo-evento-di-formazione-promosso-da-fas-italia\/","name":"\u201cL\u2019Arte del Breakfast\u201d: il nuovo evento di formazione promosso da Fas Italia - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2015-10-01T16:26:50+00:00","dateModified":"2018-10-25T22:35:36+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/a%80cla%80%99arte-del-breakfasta%80%9d-il-nuovo-evento-di-formazione-promosso-da-fas-italia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/a%80cla%80%99arte-del-breakfasta%80%9d-il-nuovo-evento-di-formazione-promosso-da-fas-italia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/a%80cla%80%99arte-del-breakfasta%80%9d-il-nuovo-evento-di-formazione-promosso-da-fas-italia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"\u201cL\u2019Arte del Breakfast\u201d: il nuovo evento di formazione promosso da Fas Italia"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/49316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=49316"}],"version-history":[{"count":2,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/49316\/revisions"}],"predecessor-version":[{"id":64752,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/49316\/revisions\/64752"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=49316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=49316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=49316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}