{"id":49321,"date":"2015-10-06T14:24:13","date_gmt":"2015-10-06T12:24:13","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/fattoria-mantellassi-partner-a-grosseto-il-7-ottobre-al-primo-appuntamento-con-il-prestigioso-evento-a%25252580cdiamo-gusto-alla-parolaa%25252580%2525259d\/"},"modified":"2015-10-06T14:24:13","modified_gmt":"2015-10-06T12:24:13","slug":"fattoria-mantellassi-partner-a-grosseto-il-7-ottobre-al-primo-appuntamento-con-il-prestigioso-evento-a%25252580cdiamo-gusto-alla-parolaa%25252580%2525259d","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/fattoria-mantellassi-partner-a-grosseto-il-7-ottobre-al-primo-appuntamento-con-il-prestigioso-evento-a%25252580cdiamo-gusto-alla-parolaa%25252580%2525259d\/","title":{"rendered":"FATTORIA MANTELLASSI PARTNER, A GROSSETO, IL 7 OTTOBRE, CON \u201cDIAMO GUSTO ALLA PAROLA\u201d"},"content":{"rendered":"<p>Cinema e letteratura sposano la cultura del gusto dando la parola a sei importanti scrittori ognuno dei quali parler&agrave; al pubblico del film della serata<br \/>&ldquo;Uno, due, sei&hellip; stella!&rdquo; E mai la parola stella &egrave; stata migliore interprete per descrivere le sei serate in programma a Grosseto a partire dal 7 ottobre con cadenza mensile, ogni primo mercoled&igrave; del mese. <br \/>La prima stella &egrave; sicuramente da attribuire ai film in programmazione, sei titoli di grande rilevanza che affronteranno temi diversi, dal sociale al letterario, ognuno dei quali verr&agrave; di volta in volta discusso e presentato al pubblico da altrettanti scrittori. Si succederanno infatti Massimo Onofri, Sergio Garufi, Bianca Garavelli, Marco Vichi, Beatrice Monroy e Barbara Garlaschelli, nomi importanti nel panorama critico letterario italiano.<br \/>L&rsquo;evento, distribuito appunto su sei serate, avr&agrave; luogo a Grosseto, presso il cinema Stella ed &egrave; stato progettato dalla Banca della Maremma con il patrocinio del Comune della citt&agrave; toscana e della Fondazione Grosseto Cultura e in collaborazione con il Cral della Banca della Maremma.<br \/>Il connubio con &ldquo;il gusto&rdquo; avverr&agrave; con un aperitivo a buffet accompagnato da una degustazione dei migliori vini del territorio toscano a cui far&agrave; seguito la proiezione del film.<br \/>Ad aprire la kermesse, il 7 ottobre, una &ldquo;perla&rdquo; del grande Mario Monicelli, il film &ldquo;Un borghese piccolo piccolo&rdquo; che sar&agrave; presentato al pubblico da Massimo Onofri.<br \/><strong>Per questo primo mercoled&igrave;, Fattoria Mantellassi offrir&agrave; una degustazione con due delle sue etichette di eccellenza: il pluripremiato D.O.C.G rosso SAN GIUSEPPE e il bianco SCALANDRINO. <\/strong><br \/> <strong><em>Per prenotazioni e info: cinema Stella, tel 0564 474213<\/em><\/strong><br \/><strong><em><a href=\"mailto:info@cralmaremma.it\">info@cralmaremma.it<\/a><\/em><\/strong><br \/><strong><em> <\/em><\/strong><\/p>\n<p>ELLEVI PR<br \/>Di Lucia Villa<br \/>Piazza Napoli, 24<br \/>20146 Milano<br \/>Tel 02\/45496051<br \/>Cell. 3490856770<\/p>\n<p>Cinema e letteratura sposano la cultura del gusto dando la parola a sei importanti scrittori ognuno dei quali parler&agrave; al pubblico del film della serata<br \/>&ldquo;Uno, due, sei&hellip; stella!&rdquo; E mai la parola stella &egrave; stata migliore interprete per descrivere le sei serate in programma a Grosseto a partire dal 7 ottobre con cadenza mensile, ogni primo mercoled&igrave; del mese. <br \/>La prima stella &egrave; sicuramente da attribuire ai film in programmazione, sei titoli di grande rilevanza che affronteranno temi diversi, dal sociale al letterario, ognuno dei quali verr&agrave; di volta in volta discusso e presentato al pubblico da altrettanti scrittori. Si succederanno infatti Massimo Onofri, Sergio Garufi, Bianca Garavelli, Marco Vichi, Beatrice Monroy e Barbara Garlaschelli, nomi importanti nel panorama critico letterario italiano.<br \/>L&rsquo;evento, distribuito appunto su sei serate, avr&agrave; luogo a Grosseto, presso il cinema Stella ed &egrave; stato progettato dalla Banca della Maremma con il patrocinio del Comune della citt&agrave; toscana e della Fondazione Grosseto Cultura e in collaborazione con il Cral della Banca della Maremma.<br \/>Il connubio con &ldquo;il gusto&rdquo; avverr&agrave; con un aperitivo a buffet accompagnato da una degustazione dei migliori vini del territorio toscano a cui far&agrave; seguito la proiezione del film.<br \/>Ad aprire la kermesse, il 7 ottobre, una &ldquo;perla&rdquo; del grande Mario Monicelli, il film &ldquo;Un borghese piccolo piccolo&rdquo; che sar&agrave; presentato al pubblico da Massimo Onofri.<br \/><strong>Per questo primo mercoled&igrave;, Fattoria Mantellassi offrir&agrave; una degustazione con due delle sue etichette di eccellenza: il pluripremiato D.O.C.G rosso SAN GIUSEPPE e il bianco SCALANDRINO. <\/strong><br \/> <strong><em>Per prenotazioni e info: cinema Stella, tel 0564 474213<\/em><\/strong><br \/><strong><em>info@cralmaremma.it<\/em><\/strong><br \/><strong><em> <\/em><\/strong><\/p>\n<p>ELLEVI PR<br \/>Di Lucia Villa<br \/>Piazza Napoli, 24<br \/>20146 Milano<br \/>Tel 02\/45496051<br \/>Cell. 3490856770<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cinema e letteratura sposano la cultura del gusto dando la parola a sei importanti scrittori ognuno dei quali parler\u00e0 al pubblico del film della serata<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[388],"tags":[48473,50538,52668,2462],"class_list":["post-49321","post","type-post","status-publish","format-standard","hentry","category-eventi","tag-fattoria-mantellassi","tag-san-giuseppe","tag-scalandrino","tag-vino"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FATTORIA MANTELLASSI PARTNER, A GROSSETO, IL 7 OTTOBRE, CON \u201cDIAMO GUSTO ALLA PAROLA\u201d - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/fattoria-mantellassi-partner-a-grosseto-il-7-ottobre-al-primo-appuntamento-con-il-prestigioso-evento-a%252580cdiamo-gusto-alla-parolaa%252580%25259d\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FATTORIA MANTELLASSI PARTNER, A GROSSETO, IL 7 OTTOBRE, CON \u201cDIAMO GUSTO ALLA PAROLA\u201d - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Cinema e letteratura sposano la cultura del gusto dando la parola a sei importanti scrittori ognuno dei quali parler\u00e0 al pubblico del film della serata\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/fattoria-mantellassi-partner-a-grosseto-il-7-ottobre-al-primo-appuntamento-con-il-prestigioso-evento-a%252580cdiamo-gusto-alla-parolaa%252580%25259d\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-06T12:24:13+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/fattoria-mantellassi-partner-a-grosseto-il-7-ottobre-al-primo-appuntamento-con-il-prestigioso-evento-a%25252580cdiamo-gusto-alla-parolaa%25252580%2525259d\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/fattoria-mantellassi-partner-a-grosseto-il-7-ottobre-al-primo-appuntamento-con-il-prestigioso-evento-a%25252580cdiamo-gusto-alla-parolaa%25252580%2525259d\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"FATTORIA MANTELLASSI PARTNER, A GROSSETO, IL 7 OTTOBRE, CON \u201cDIAMO GUSTO ALLA PAROLA\u201d\",\"datePublished\":\"2015-10-06T12:24:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/fattoria-mantellassi-partner-a-grosseto-il-7-ottobre-al-primo-appuntamento-con-il-prestigioso-evento-a%25252580cdiamo-gusto-alla-parolaa%25252580%2525259d\\\/\"},\"wordCount\":590,\"commentCount\":0,\"keywords\":[\"fattoria mantellassi\",\"san giuseppe\",\"scalandrino\",\"vino\"],\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/fattoria-mantellassi-partner-a-grosseto-il-7-ottobre-al-primo-appuntamento-con-il-prestigioso-evento-a%25252580cdiamo-gusto-alla-parolaa%25252580%2525259d\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/fattoria-mantellassi-partner-a-grosseto-il-7-ottobre-al-primo-appuntamento-con-il-prestigioso-evento-a%25252580cdiamo-gusto-alla-parolaa%25252580%2525259d\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/fattoria-mantellassi-partner-a-grosseto-il-7-ottobre-al-primo-appuntamento-con-il-prestigioso-evento-a%25252580cdiamo-gusto-alla-parolaa%25252580%2525259d\\\/\",\"name\":\"FATTORIA MANTELLASSI PARTNER, A GROSSETO, IL 7 OTTOBRE, CON \u201cDIAMO GUSTO ALLA PAROLA\u201d - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2015-10-06T12:24:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/fattoria-mantellassi-partner-a-grosseto-il-7-ottobre-al-primo-appuntamento-con-il-prestigioso-evento-a%25252580cdiamo-gusto-alla-parolaa%25252580%2525259d\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/fattoria-mantellassi-partner-a-grosseto-il-7-ottobre-al-primo-appuntamento-con-il-prestigioso-evento-a%25252580cdiamo-gusto-alla-parolaa%25252580%2525259d\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/fattoria-mantellassi-partner-a-grosseto-il-7-ottobre-al-primo-appuntamento-con-il-prestigioso-evento-a%25252580cdiamo-gusto-alla-parolaa%25252580%2525259d\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FATTORIA MANTELLASSI PARTNER, A GROSSETO, IL 7 OTTOBRE, CON \u201cDIAMO GUSTO ALLA PAROLA\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FATTORIA MANTELLASSI PARTNER, A GROSSETO, IL 7 OTTOBRE, CON \u201cDIAMO GUSTO ALLA PAROLA\u201d - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/fattoria-mantellassi-partner-a-grosseto-il-7-ottobre-al-primo-appuntamento-con-il-prestigioso-evento-a%252580cdiamo-gusto-alla-parolaa%252580%25259d\/","og_locale":"it_IT","og_type":"article","og_title":"FATTORIA MANTELLASSI PARTNER, A GROSSETO, IL 7 OTTOBRE, CON \u201cDIAMO GUSTO ALLA PAROLA\u201d - Article Marketing","og_description":"Cinema e letteratura sposano la cultura del gusto dando la parola a sei importanti scrittori ognuno dei quali parler\u00e0 al pubblico del film della serata","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/fattoria-mantellassi-partner-a-grosseto-il-7-ottobre-al-primo-appuntamento-con-il-prestigioso-evento-a%252580cdiamo-gusto-alla-parolaa%252580%25259d\/","og_site_name":"Article Marketing","article_published_time":"2015-10-06T12:24:13+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/fattoria-mantellassi-partner-a-grosseto-il-7-ottobre-al-primo-appuntamento-con-il-prestigioso-evento-a%25252580cdiamo-gusto-alla-parolaa%25252580%2525259d\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/fattoria-mantellassi-partner-a-grosseto-il-7-ottobre-al-primo-appuntamento-con-il-prestigioso-evento-a%25252580cdiamo-gusto-alla-parolaa%25252580%2525259d\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"FATTORIA MANTELLASSI PARTNER, A GROSSETO, IL 7 OTTOBRE, CON \u201cDIAMO GUSTO ALLA PAROLA\u201d","datePublished":"2015-10-06T12:24:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/fattoria-mantellassi-partner-a-grosseto-il-7-ottobre-al-primo-appuntamento-con-il-prestigioso-evento-a%25252580cdiamo-gusto-alla-parolaa%25252580%2525259d\/"},"wordCount":590,"commentCount":0,"keywords":["fattoria mantellassi","san giuseppe","scalandrino","vino"],"articleSection":["Eventi"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/fattoria-mantellassi-partner-a-grosseto-il-7-ottobre-al-primo-appuntamento-con-il-prestigioso-evento-a%25252580cdiamo-gusto-alla-parolaa%25252580%2525259d\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/fattoria-mantellassi-partner-a-grosseto-il-7-ottobre-al-primo-appuntamento-con-il-prestigioso-evento-a%25252580cdiamo-gusto-alla-parolaa%25252580%2525259d\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/fattoria-mantellassi-partner-a-grosseto-il-7-ottobre-al-primo-appuntamento-con-il-prestigioso-evento-a%25252580cdiamo-gusto-alla-parolaa%25252580%2525259d\/","name":"FATTORIA MANTELLASSI PARTNER, A GROSSETO, IL 7 OTTOBRE, CON \u201cDIAMO GUSTO ALLA PAROLA\u201d - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2015-10-06T12:24:13+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/fattoria-mantellassi-partner-a-grosseto-il-7-ottobre-al-primo-appuntamento-con-il-prestigioso-evento-a%25252580cdiamo-gusto-alla-parolaa%25252580%2525259d\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/fattoria-mantellassi-partner-a-grosseto-il-7-ottobre-al-primo-appuntamento-con-il-prestigioso-evento-a%25252580cdiamo-gusto-alla-parolaa%25252580%2525259d\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/fattoria-mantellassi-partner-a-grosseto-il-7-ottobre-al-primo-appuntamento-con-il-prestigioso-evento-a%25252580cdiamo-gusto-alla-parolaa%25252580%2525259d\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"FATTORIA MANTELLASSI PARTNER, A GROSSETO, IL 7 OTTOBRE, CON \u201cDIAMO GUSTO ALLA PAROLA\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/49321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=49321"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/49321\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=49321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=49321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=49321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}