{"id":5067,"date":"2010-05-12T12:57:43","date_gmt":"2010-05-12T10:57:43","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/mcafee-inc-posizionata-nel-quadrante-dei-leader-nella-categoria-secure-e-mail-gateway\/"},"modified":"2018-07-10T05:35:43","modified_gmt":"2018-07-10T03:35:43","slug":"mcafee-inc-posizionata-nel-quadrante-dei-leader-nella-categoria-secure-e-mail-gateway","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/mcafee-inc-posizionata-nel-quadrante-dei-leader-nella-categoria-secure-e-mail-gateway\/","title":{"rendered":"McAfee, Inc. posizionata nel quadrante dei leader nella categoria Secure E-mail Gateway"},"content":{"rendered":"<p style=\"MARGIN-BOTTOM: 0pt; LINE-HEIGHT: 115%; TEXT-ALIGN: justify\"><strong>McAfee, Inc.<\/strong> ha annunciato di essere stata posizionata da Gartner, Inc., una delle pi\u00f9 importanti societ\u00e0 di ricerca e consulenza, nel Quadrante dei Leader all\u2019interno del report&nbsp; \u201cMagic Quadrant for Secure E-mail Gateways\u201d&nbsp; pubblicato il 27 Aprile 2010 (redatto da: <strong>Peter Firstbrook e Eric Ouellet<\/strong>). <\/p>\n<p style=\"MARGIN-BOTTOM: 0pt; LINE-HEIGHT: 115%; TEXT-ALIGN: justify\">&nbsp;<\/p>\n<p style=\"MARGIN-BOTTOM: 0pt; LINE-HEIGHT: 115%; TEXT-ALIGN: justify\">Questo report prende in considerazione 17 vendor. &nbsp;Secondo la definizione di Gartner, \u201ci leader presentano prestazioni attuali positive, una visione chiara della direzione del mercato e stanno creando attivamente competenze per sostenere la posizione di leadership nel mercato. Le aziende inserite nel quadrante offrono una gamma completa e avanzata di funzionalit\u00e0 per la protezione dell\u2019e-mail e dimostrano&nbsp; chiaramente una visione e una capacit\u00e0 d\u2019esecuzione eccellenti per soddisfare i requisiti attuali e futuri dei clienti. Tipicamente, i leader vantano quote di mercato piuttosto elevate e\/o solide crescite di fatturato, posseggono una buona parte delle funzionalit\u00e0 di filtering delle minacce o dei contenuti e mostrano commenti positivi da parte dei clienti relativamente all\u2019efficacia dell\u2019anti-spam e i servizi e l\u2019assistenza correlati\u201d.<\/p>\n<p style=\"LINE-HEIGHT: 115%; TEXT-ALIGN: justify\">&nbsp;<\/p>\n<p style=\"MARGIN-BOTTOM: 0pt; LINE-HEIGHT: 115%; TEXT-ALIGN: justify\">\u201cRiteniamo che il nostro posizionamento nel quadrante dei leader di Gartner sia una conferma della strategia McAfee per offrire soluzioni per la sicurezza dell\u2019e-mail che garantiscano una&nbsp; protezione eccellente fornendo opzioni di implementazione flessibili ai nostri clienti\u201d, ha affermato Dan Ryan, executive vice president e general manager della business unit Network Security di McAfee. \u201cCon l\u2019acquisizione di Secure Computing nel 2008 e di MX Logic nel 2009, riteniamo che McAfee oggi vanti il pi\u00f9 ampio portafoglio di soluzioni per la protezione dell\u2019e-mail disponibile sul mercato, fornendo ai clienti la possibilit\u00e0 di scegliere tra appliance on-premise, software-as-a-service (SaaS) e soluzioni ibride\u201d. <\/p>\n<p style=\"MARGIN-BOTTOM: 0pt; LINE-HEIGHT: 115%; TEXT-ALIGN: justify\">&nbsp;<\/p>\n<p style=\"LINE-HEIGHT: 115%; TEXT-ALIGN: justify\">McAfee fornisce soluzioni per la protezione dell\u2019e-mail security sia come appliance on-premise che soluzioni in modalit\u00e0 Software-as-a-Service (SaaS). I clienti possono anche scegliere di combinare i servizi McAfee SaaS con appliance on-premise e virtuali.<\/p>\n<p style=\"LINE-HEIGHT: 115%; TEXT-ALIGN: justify\">&nbsp;<\/p>\n<p style=\"LINE-HEIGHT: 115%; TEXT-ALIGN: justify\">Per richiedere un copia completa del report Secure E-mail Gateways Magic Quadrant, fare clic qui: http:\/\/www.mcafee.com\/us\/campaigns\/gartner_secure_email_gateway\/index.html<\/p>\n<p style=\"TEXT-ALIGN: justify\">&nbsp;<\/p>\n<p style=\"TEXT-ALIGN: justify\"><strong><em>Il Gartner Magic Quadrant <\/em><\/strong><\/p>\n<p style=\"LINE-HEIGHT: 115%; TEXT-ALIGN: justify\"><em>Il Magic Quadrant \u00e8 protetto da Copyright 2010 di Gartner, Inc. e viene riprodotto su autorizzazione. Il Magic Quadrant \u00e8 una rappresentazione grafica di un mercato in e per uno specifico periodo di tempo. Rappresenta l&#8217;analisi di Gartner su come alcuni fornitori operano rispetto a criteri specifici per quel mercato, come definito da Gartner. Gartner non avalla alcun fornitore, prodotto o servizio descritto nel Magic Quadrant e non consiglia agli utenti di tecnologia di selezionare solo quei fornitori collocati nel quadrante dei &quot;Leader&quot;. Il Magic Quadrant \u00e8 da intendersi esclusivamente come uno strumento di ricerca, e non intende essere una guida specifica all&#8217;azione. Gartner declina ogni responsabilit\u00e0, esplicita o implicita, relativamente a questa ricerca, comprese eventuali garanzie di commerciabilit\u00e0 o idoneit\u00e0 per uno scopo particolare.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>A proposito di McAfee, Inc.<\/strong><\/p>\n<p><em>McAfee, Inc., con sede centrale a Santa Clara, California, \u00e8 la principale azienda mondiale dedicata alla tecnologia della sicurezza.&nbsp; McAfee \u00e8 costantemente impegnata ad affrontare le pi\u00f9 difficili sfide legate alla sicurezza. L&#8217;azienda offre prodotti e servizi di sicurezza collaudati e proattivi che proteggono sistemi e reti in tutto il mondo, consentendo agli utenti di connettersi in modo sicuro a Internet, navigare ed effettuare acquisti sul Web in sicurezza. Supportata da un pluripremiato team di ricerca, McAfee crea prodotti innovativi destinati a utenti consumer, aziende, pubblica amministrazione e service provider che necessitano di conformarsi alle normative, proteggere i dati, prevenire le interruzioni dell&#8217;attivit\u00e0, individuare le vulnerabilit\u00e0 e monitorare e migliorare costantemente la propria sicurezza, www.mcafee.com.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La valutazione basata sulla completezza della visione dell\u2019azienda e capacit\u00e0 operativa<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[190],"tags":[14409],"class_list":["post-5067","post","type-post","status-publish","format-standard","hentry","category-comunicati-stampa","tag-easynet-magnet-networks"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>McAfee, Inc. posizionata nel quadrante dei leader nella categoria Secure E-mail Gateway - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/mcafee-inc-posizionata-nel-quadrante-dei-leader-nella-categoria-secure-e-mail-gateway\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"McAfee, Inc. posizionata nel quadrante dei leader nella categoria Secure E-mail Gateway - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"La valutazione basata sulla completezza della visione dell\u2019azienda e capacit\u00e0 operativa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/mcafee-inc-posizionata-nel-quadrante-dei-leader-nella-categoria-secure-e-mail-gateway\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2010-05-12T10:57:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-10T03:35:43+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/mcafee-inc-posizionata-nel-quadrante-dei-leader-nella-categoria-secure-e-mail-gateway\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/mcafee-inc-posizionata-nel-quadrante-dei-leader-nella-categoria-secure-e-mail-gateway\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"McAfee, Inc. posizionata nel quadrante dei leader nella categoria Secure E-mail Gateway\",\"datePublished\":\"2010-05-12T10:57:43+00:00\",\"dateModified\":\"2018-07-10T03:35:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/mcafee-inc-posizionata-nel-quadrante-dei-leader-nella-categoria-secure-e-mail-gateway\\\/\"},\"wordCount\":602,\"commentCount\":0,\"keywords\":[\"easynet; magnet networks\"],\"articleSection\":[\"Comunicati stampa\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/mcafee-inc-posizionata-nel-quadrante-dei-leader-nella-categoria-secure-e-mail-gateway\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/mcafee-inc-posizionata-nel-quadrante-dei-leader-nella-categoria-secure-e-mail-gateway\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/mcafee-inc-posizionata-nel-quadrante-dei-leader-nella-categoria-secure-e-mail-gateway\\\/\",\"name\":\"McAfee, Inc. posizionata nel quadrante dei leader nella categoria Secure E-mail Gateway - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2010-05-12T10:57:43+00:00\",\"dateModified\":\"2018-07-10T03:35:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/mcafee-inc-posizionata-nel-quadrante-dei-leader-nella-categoria-secure-e-mail-gateway\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/mcafee-inc-posizionata-nel-quadrante-dei-leader-nella-categoria-secure-e-mail-gateway\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/mcafee-inc-posizionata-nel-quadrante-dei-leader-nella-categoria-secure-e-mail-gateway\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"McAfee, Inc. posizionata nel quadrante dei leader nella categoria Secure E-mail Gateway\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"McAfee, Inc. posizionata nel quadrante dei leader nella categoria Secure E-mail Gateway - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/mcafee-inc-posizionata-nel-quadrante-dei-leader-nella-categoria-secure-e-mail-gateway\/","og_locale":"it_IT","og_type":"article","og_title":"McAfee, Inc. posizionata nel quadrante dei leader nella categoria Secure E-mail Gateway - Article Marketing","og_description":"La valutazione basata sulla completezza della visione dell\u2019azienda e capacit\u00e0 operativa","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/mcafee-inc-posizionata-nel-quadrante-dei-leader-nella-categoria-secure-e-mail-gateway\/","og_site_name":"Article Marketing","article_published_time":"2010-05-12T10:57:43+00:00","article_modified_time":"2018-07-10T03:35:43+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/mcafee-inc-posizionata-nel-quadrante-dei-leader-nella-categoria-secure-e-mail-gateway\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/mcafee-inc-posizionata-nel-quadrante-dei-leader-nella-categoria-secure-e-mail-gateway\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"McAfee, Inc. posizionata nel quadrante dei leader nella categoria Secure E-mail Gateway","datePublished":"2010-05-12T10:57:43+00:00","dateModified":"2018-07-10T03:35:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/mcafee-inc-posizionata-nel-quadrante-dei-leader-nella-categoria-secure-e-mail-gateway\/"},"wordCount":602,"commentCount":0,"keywords":["easynet; magnet networks"],"articleSection":["Comunicati stampa"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/mcafee-inc-posizionata-nel-quadrante-dei-leader-nella-categoria-secure-e-mail-gateway\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/mcafee-inc-posizionata-nel-quadrante-dei-leader-nella-categoria-secure-e-mail-gateway\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/mcafee-inc-posizionata-nel-quadrante-dei-leader-nella-categoria-secure-e-mail-gateway\/","name":"McAfee, Inc. posizionata nel quadrante dei leader nella categoria Secure E-mail Gateway - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2010-05-12T10:57:43+00:00","dateModified":"2018-07-10T03:35:43+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/mcafee-inc-posizionata-nel-quadrante-dei-leader-nella-categoria-secure-e-mail-gateway\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/mcafee-inc-posizionata-nel-quadrante-dei-leader-nella-categoria-secure-e-mail-gateway\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/mcafee-inc-posizionata-nel-quadrante-dei-leader-nella-categoria-secure-e-mail-gateway\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"McAfee, Inc. posizionata nel quadrante dei leader nella categoria Secure E-mail Gateway"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/5067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=5067"}],"version-history":[{"count":2,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/5067\/revisions"}],"predecessor-version":[{"id":61882,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/5067\/revisions\/61882"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=5067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=5067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=5067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}