{"id":53027,"date":"2016-07-13T23:50:23","date_gmt":"2016-07-13T21:50:23","guid":{"rendered":""},"modified":"2020-08-10T01:21:07","modified_gmt":"2020-08-09T23:21:07","slug":"castellarte-la-xxiii-edizione-%c3%a8-dedicata-ai-a%80critmi-di-festaa%80%9d-della%80%99antropologo-paolo-apolito-e-al-meglio-della%80%99arte-di-strada-italiana-e-internazionale-acrobati-attori-musici","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/castellarte-la-xxiii-edizione-%c3%a8-dedicata-ai-a%80critmi-di-festaa%80%9d-della%80%99antropologo-paolo-apolito-e-al-meglio-della%80%99arte-di-strada-italiana-e-internazionale-acrobati-attori-musici\/","title":{"rendered":"Castellarte: la XXIII edizione \u00e8 dedicata ai \u201cRitmi di Festa\u201d dell\u2019antropologo Paolo Apolito e al meglio dell\u2019arte di strada italiana e internazionale. Acrobati, attori, musicisti vivono con il pubblico la magia di uno dei borghi medievali pi\u00f9 belli d\u2019Irp"},"content":{"rendered":"<p>Dal 29 al 31 luglio 2016, a Mercogliano (Av) torna Castellarte con la XXIII edizione del Festival Internazionale di Artisti IN Strada pi&ugrave; importante del centro-sud, dedicata quest&rsquo;anno ai &ldquo;Ritmi di Festa&rdquo;, descritti nella loro funzione sociale e terapeutica nell&rsquo;omonimo libro dell&rsquo;antropologo Paolo Apolito. <br \/>Il ritmo come vita, la festa come espressione di gioia e anelito alla pace, la strada come luogo d&rsquo;incontro tra sconosciuti che, nel ritmo, possono riconoscere matrici comuni e possibilit&agrave; di dialogo; &egrave; questo il messaggio che parte da Capocastello, uno dei pi&ugrave; bei borghi medievali d&rsquo;Irpinia e da sempre grande &ldquo;palcoscenico diffuso&rdquo; di Castellarte. <br \/>Nelle stradine inerpicate, negli slarghi e nelle piazzette lastricate di pietra bianca, il grande pubblico di Castellarte (circa 60.000 presenze l&rsquo;anno) vivr&agrave; l&rsquo;esperienza di un Festival che &egrave; un vero tripudio di sensazioni. Dalle esibizioni di acrobati e clown, al burlesque, alla musica pi&ugrave; festosa, al teatro per bambini, alle esposizioni di artigianato, agli spazi dedicati all&rsquo;enogastronomia del territorio irpino, il Festival &egrave; un appuntamento immancabile nell&rsquo;estate campana. <br \/>Oltre all&rsquo;interessantissima conferenza-spettacolo del prof. Paolo Apolito dal titolo &ldquo;L&rsquo;Antropologo a domicilio&rdquo; che riprende i temi del libro &ldquo;Ritmi di Festa. Corpo, danza, socialit&agrave;&rdquo; (ed. Il Mulino), il cast selezionato dal Direttore Artistico Anna Di Nardo entusiasmer&agrave; il pubblico con spettacoli di successo nelle maggiori piazze internazionali. Dal laboratorio di teatro-ragazzi degli israeliani Koom Koom Theater; alla magia acrobatica del duo tedesco Elab&ouml;; alla commistione tra clownerie, fuoco e acrobazia dei Creme &amp; Brul&eacute;e; all&rsquo;allegra stramberia circense dei Fivequartettrio; alla vertiginosa giocoleria de I Nipoti di Bernardone; alla clownerie surreale e contemporanea di Andrea Farnetani, vincitore del Pav&egrave; d&#8217;Or&#8221; al Festival de Artistes de Rue de Vevey 2014; a Fraser Hooper, clown vincitore delle Olimpiadi dell&rsquo;arte di strada che si svolgono in Nuova Zelanda. <br \/>La musica &egrave; varia e coinvolgente, dal trio di chitarre con percussionista I Poter&igrave;co gi&agrave; semifinalista in &ldquo;Italia&rsquo;s got talent 2015&rdquo;; all&rsquo;indole sociale e cantautorale de I Musicanti del Vento, gi&agrave; finalisti al Premio De Andr&eacute; e in corsa per il palco del Primo Maggio a Roma; al folk-rock dei romani The Shak &amp; Speares gi&agrave; su palchi importanti come quello del Neapolis con gli Skunk Anansie; al country-folk-punk dei partenopei Mexico86; al &ldquo;power-gipsy-dance&rdquo; dei fiorentini Baro Drom Orkestar che si definiscono &ldquo;poco world music e molto punk&rdquo; e hanno aperto concerti di artisti del calibro di Goran Bregovic; alla frenesia sonora degli ottoni della Bandragola Orkestar nata dal cuore multietnico di Torino, il quartiere Porta Palazzo, per poi girare il mondo con i loro suoni meticci; al crooner Antonio Sorgentone con la sua vena retr&ograve; che rimanda agli anni &rsquo;50 e a Carosone e Buscaglione; ai Fantasia Pura Italiana ironici e teatrali; ai partenopei Kafka sulla spiaggia. <br \/>Per la prima volta a Castellarte ci sar&agrave; uno spazio dedicato al burlesque, con la presenza di ben tre artisti uniti nel progetto Burlesque Riot. The Duncan&rsquo;s Performance Art Project con Giuditta Sin e Gonzalo De Laverga in uno show ispirato alla trasgressiva icona della danza Isadora Duncan e Miss Vampfire, che canta le sue composizioni e standard jazz in uno spettacolo pieno della classe e dell&rsquo;ironia delle vamp holliwoodiane. <br \/>Altra novit&agrave; di questa edizione &egrave; l&rsquo;app per smartphone Castellarte Next Fest che Castellarte ha voluto per facilitare, grazie alla tecnologia, la fruizione del Festival. <\/p>\n<p>Torna per la terza volta consecutiva il Concorso Fotografico promosso dall&rsquo;Associazione Culturale Fotografica &ldquo;Colori Mediteranei&rdquo; che muover&agrave; uno stuolo di fotoamatori su &egrave; gi&ugrave; per Capocastello a catturare gli attimi pi&ugrave; belli dell&rsquo;interazione artisti-pubblico e del Festival. <br \/>Castellarte &egrave; stato incluso dal portale italive.it &#8211; promosso dal Codacons con la collaborazione di Coldiretti e la partecipazione di Autostrade per l&rsquo;Italia &#8211; tra le manifestazioni italiane di maggior pregio in lizza per il Premio Italive; &egrave; possibile esprimere il sostegno a Castellarte votando sul sito ed esprimendo anche il livello di gradimento. <br \/>Spazi dedicati all&rsquo;artigianato, con la partecipazione quest&rsquo;anno della CNA Avellino, e Aree del Gusto dedicate alle eccellenze enogastronomiche del territorio irpino &#8211; terra dei tre celebri vitigni D.O.C.G. Fiano di Avellino, Greco di Tufo e Taurasi &#8211; completano la ricetta di Castellarte che, anche quest&rsquo;anno, ha scelto di celebrare nel migliore dei modi il suo amore per l&rsquo;arte di strada e il territorio del comprensorio del Partenio. Il Festival &egrave; organizzato dai volontari dell&rsquo;Associazione Castellarte e l&rsquo;ingresso &egrave; gratuito. Info: www.castellarte.it. <\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>E&#8217; uno dei grandi eventi dell&#8217;estate in Campania con oltre 50.000 presenze annue; il borgo medievale di Capocastello a Mercogliano (Av) diventa per tre giorni il palcoscenico diffuso per le esibizioni di arte circense, giocoleria, musica, teatro e quest&#8217;anno anche burlesque. Ingresso gratuito<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[27],"tags":[],"class_list":["post-53027","post","type-post","status-publish","format-standard","hentry","category-arte-e-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Castellarte: la XXIII edizione \u00e8 dedicata ai \u201cRitmi di Festa\u201d dell\u2019antropologo Paolo Apolito e al meglio dell\u2019arte di strada italiana e internazionale. Acrobati, attori, musicisti vivono con il pubblico la magia di uno dei borghi medievali pi\u00f9 belli d\u2019Irp - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/castellarte-la-xxiii-edizione-\u00e8-dedicata-ai-a?critmi-di-festaa??-della??antropologo-paolo-apolito-e-al-meglio-della??arte-di-strada-italiana-e-internazionale-acrobati-attori-musici\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Castellarte: la XXIII edizione \u00e8 dedicata ai \u201cRitmi di Festa\u201d dell\u2019antropologo Paolo Apolito e al meglio dell\u2019arte di strada italiana e internazionale. Acrobati, attori, musicisti vivono con il pubblico la magia di uno dei borghi medievali pi\u00f9 belli d\u2019Irp - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"E&#039; uno dei grandi eventi dell&#039;estate in Campania con oltre 50.000 presenze annue; il borgo medievale di Capocastello a Mercogliano (Av) diventa per tre giorni il palcoscenico diffuso per le esibizioni di arte circense, giocoleria, musica, teatro e quest&#039;anno anche burlesque. Ingresso gratuito\" \/>\n<meta property=\"og:url\" content=\"\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2016-07-13T21:50:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-09T23:21:07+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/castellarte-la-xxiii-edizione-%c3%a8-dedicata-ai-a%80critmi-di-festaa%80%9d-della%80%99antropologo-paolo-apolito-e-al-meglio-della%80%99arte-di-strada-italiana-e-internazionale-acrobati-attori-musici\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/castellarte-la-xxiii-edizione-%c3%a8-dedicata-ai-a%80critmi-di-festaa%80%9d-della%80%99antropologo-paolo-apolito-e-al-meglio-della%80%99arte-di-strada-italiana-e-internazionale-acrobati-attori-musici\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Castellarte: la XXIII edizione \u00e8 dedicata ai \u201cRitmi di Festa\u201d dell\u2019antropologo Paolo Apolito e al meglio dell\u2019arte di strada italiana e internazionale. Acrobati, attori, musicisti vivono con il pubblico la magia di uno dei borghi medievali pi\u00f9 belli d\u2019Irp\",\"datePublished\":\"2016-07-13T21:50:23+00:00\",\"dateModified\":\"2020-08-09T23:21:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/castellarte-la-xxiii-edizione-%c3%a8-dedicata-ai-a%80critmi-di-festaa%80%9d-della%80%99antropologo-paolo-apolito-e-al-meglio-della%80%99arte-di-strada-italiana-e-internazionale-acrobati-attori-musici\\\/\"},\"wordCount\":850,\"commentCount\":0,\"articleSection\":[\"Arte e cultura\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/castellarte-la-xxiii-edizione-%c3%a8-dedicata-ai-a%80critmi-di-festaa%80%9d-della%80%99antropologo-paolo-apolito-e-al-meglio-della%80%99arte-di-strada-italiana-e-internazionale-acrobati-attori-musici\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/castellarte-la-xxiii-edizione-%c3%a8-dedicata-ai-a%80critmi-di-festaa%80%9d-della%80%99antropologo-paolo-apolito-e-al-meglio-della%80%99arte-di-strada-italiana-e-internazionale-acrobati-attori-musici\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/castellarte-la-xxiii-edizione-%c3%a8-dedicata-ai-a%80critmi-di-festaa%80%9d-della%80%99antropologo-paolo-apolito-e-al-meglio-della%80%99arte-di-strada-italiana-e-internazionale-acrobati-attori-musici\\\/\",\"name\":\"Castellarte: la XXIII edizione \u00e8 dedicata ai \u201cRitmi di Festa\u201d dell\u2019antropologo Paolo Apolito e al meglio dell\u2019arte di strada italiana e internazionale. Acrobati, attori, musicisti vivono con il pubblico la magia di uno dei borghi medievali pi\u00f9 belli d\u2019Irp - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2016-07-13T21:50:23+00:00\",\"dateModified\":\"2020-08-09T23:21:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/castellarte-la-xxiii-edizione-%c3%a8-dedicata-ai-a%80critmi-di-festaa%80%9d-della%80%99antropologo-paolo-apolito-e-al-meglio-della%80%99arte-di-strada-italiana-e-internazionale-acrobati-attori-musici\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/castellarte-la-xxiii-edizione-%c3%a8-dedicata-ai-a%80critmi-di-festaa%80%9d-della%80%99antropologo-paolo-apolito-e-al-meglio-della%80%99arte-di-strada-italiana-e-internazionale-acrobati-attori-musici\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/arte-e-cultura\\\/castellarte-la-xxiii-edizione-%c3%a8-dedicata-ai-a%80critmi-di-festaa%80%9d-della%80%99antropologo-paolo-apolito-e-al-meglio-della%80%99arte-di-strada-italiana-e-internazionale-acrobati-attori-musici\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Castellarte: la XXIII edizione \u00e8 dedicata ai \u201cRitmi di Festa\u201d dell\u2019antropologo Paolo Apolito e al meglio dell\u2019arte di strada italiana e internazionale. Acrobati, attori, musicisti vivono con il pubblico la magia di uno dei borghi medievali pi\u00f9 belli d\u2019Irp\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Castellarte: la XXIII edizione \u00e8 dedicata ai \u201cRitmi di Festa\u201d dell\u2019antropologo Paolo Apolito e al meglio dell\u2019arte di strada italiana e internazionale. Acrobati, attori, musicisti vivono con il pubblico la magia di uno dei borghi medievali pi\u00f9 belli d\u2019Irp - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/castellarte-la-xxiii-edizione-\u00e8-dedicata-ai-a?critmi-di-festaa??-della??antropologo-paolo-apolito-e-al-meglio-della??arte-di-strada-italiana-e-internazionale-acrobati-attori-musici\/","og_locale":"it_IT","og_type":"article","og_title":"Castellarte: la XXIII edizione \u00e8 dedicata ai \u201cRitmi di Festa\u201d dell\u2019antropologo Paolo Apolito e al meglio dell\u2019arte di strada italiana e internazionale. Acrobati, attori, musicisti vivono con il pubblico la magia di uno dei borghi medievali pi\u00f9 belli d\u2019Irp - Article Marketing","og_description":"E' uno dei grandi eventi dell'estate in Campania con oltre 50.000 presenze annue; il borgo medievale di Capocastello a Mercogliano (Av) diventa per tre giorni il palcoscenico diffuso per le esibizioni di arte circense, giocoleria, musica, teatro e quest'anno anche burlesque. Ingresso gratuito","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/castellarte-la-xxiii-edizione-\u00e8-dedicata-ai-a?critmi-di-festaa??-della??antropologo-paolo-apolito-e-al-meglio-della??arte-di-strada-italiana-e-internazionale-acrobati-attori-musici\/","og_site_name":"Article Marketing","article_published_time":"2016-07-13T21:50:23+00:00","article_modified_time":"2020-08-09T23:21:07+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/castellarte-la-xxiii-edizione-%c3%a8-dedicata-ai-a%80critmi-di-festaa%80%9d-della%80%99antropologo-paolo-apolito-e-al-meglio-della%80%99arte-di-strada-italiana-e-internazionale-acrobati-attori-musici\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/castellarte-la-xxiii-edizione-%c3%a8-dedicata-ai-a%80critmi-di-festaa%80%9d-della%80%99antropologo-paolo-apolito-e-al-meglio-della%80%99arte-di-strada-italiana-e-internazionale-acrobati-attori-musici\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Castellarte: la XXIII edizione \u00e8 dedicata ai \u201cRitmi di Festa\u201d dell\u2019antropologo Paolo Apolito e al meglio dell\u2019arte di strada italiana e internazionale. Acrobati, attori, musicisti vivono con il pubblico la magia di uno dei borghi medievali pi\u00f9 belli d\u2019Irp","datePublished":"2016-07-13T21:50:23+00:00","dateModified":"2020-08-09T23:21:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/castellarte-la-xxiii-edizione-%c3%a8-dedicata-ai-a%80critmi-di-festaa%80%9d-della%80%99antropologo-paolo-apolito-e-al-meglio-della%80%99arte-di-strada-italiana-e-internazionale-acrobati-attori-musici\/"},"wordCount":850,"commentCount":0,"articleSection":["Arte e cultura"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/castellarte-la-xxiii-edizione-%c3%a8-dedicata-ai-a%80critmi-di-festaa%80%9d-della%80%99antropologo-paolo-apolito-e-al-meglio-della%80%99arte-di-strada-italiana-e-internazionale-acrobati-attori-musici\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/castellarte-la-xxiii-edizione-%c3%a8-dedicata-ai-a%80critmi-di-festaa%80%9d-della%80%99antropologo-paolo-apolito-e-al-meglio-della%80%99arte-di-strada-italiana-e-internazionale-acrobati-attori-musici\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/castellarte-la-xxiii-edizione-%c3%a8-dedicata-ai-a%80critmi-di-festaa%80%9d-della%80%99antropologo-paolo-apolito-e-al-meglio-della%80%99arte-di-strada-italiana-e-internazionale-acrobati-attori-musici\/","name":"Castellarte: la XXIII edizione \u00e8 dedicata ai \u201cRitmi di Festa\u201d dell\u2019antropologo Paolo Apolito e al meglio dell\u2019arte di strada italiana e internazionale. Acrobati, attori, musicisti vivono con il pubblico la magia di uno dei borghi medievali pi\u00f9 belli d\u2019Irp - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2016-07-13T21:50:23+00:00","dateModified":"2020-08-09T23:21:07+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/castellarte-la-xxiii-edizione-%c3%a8-dedicata-ai-a%80critmi-di-festaa%80%9d-della%80%99antropologo-paolo-apolito-e-al-meglio-della%80%99arte-di-strada-italiana-e-internazionale-acrobati-attori-musici\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/castellarte-la-xxiii-edizione-%c3%a8-dedicata-ai-a%80critmi-di-festaa%80%9d-della%80%99antropologo-paolo-apolito-e-al-meglio-della%80%99arte-di-strada-italiana-e-internazionale-acrobati-attori-musici\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/arte-e-cultura\/castellarte-la-xxiii-edizione-%c3%a8-dedicata-ai-a%80critmi-di-festaa%80%9d-della%80%99antropologo-paolo-apolito-e-al-meglio-della%80%99arte-di-strada-italiana-e-internazionale-acrobati-attori-musici\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Castellarte: la XXIII edizione \u00e8 dedicata ai \u201cRitmi di Festa\u201d dell\u2019antropologo Paolo Apolito e al meglio dell\u2019arte di strada italiana e internazionale. Acrobati, attori, musicisti vivono con il pubblico la magia di uno dei borghi medievali pi\u00f9 belli d\u2019Irp"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/53027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=53027"}],"version-history":[{"count":1,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/53027\/revisions"}],"predecessor-version":[{"id":67261,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/53027\/revisions\/67261"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=53027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=53027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=53027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}