{"id":54258,"date":"2017-01-16T20:40:50","date_gmt":"2017-01-16T19:40:50","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/scopri-come-diventare-un-sales-manager-di-successo-comunicando-efficacemente\/"},"modified":"2017-01-16T20:40:50","modified_gmt":"2017-01-16T19:40:50","slug":"scopri-come-diventare-un-sales-manager-di-successo-comunicando-efficacemente","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/scopri-come-diventare-un-sales-manager-di-successo-comunicando-efficacemente\/","title":{"rendered":"Scopri come diventare un sales manager di successo, comunicando efficacemente"},"content":{"rendered":"<p>La comunicazione efficace, per il sales manager, &egrave; forse l&rsquo;attivit&agrave; svolta pi&ugrave; trasversalmente nel corso della giornata lavorativa. Nel mio recente libro &ldquo;Il sales manager di successo&rdquo; edito da Wolters Kluwer \/ Ipsoa (<a href=\"http:\/\/www.turboformazionevendita.com\/articoli\/sales_manager_di_successo.html\">questo link consente di scaricarne liberamente un ricco estratto<\/a>) vengono presentate una serie di modalit&agrave; efficaci per raggiungere un successo duraturo nelle attivit&agrave; di sales management. Il testo, di circa 480 pagine, per ognuno dei 12 capitoli dedicati all&rsquo;eccellenza nel sales management, presenta modelli efficaci in tema di comunicazione, leadership, presa di decisioni, gestione priorit&agrave;, relazioni interpersonali, cultura della vendita, assunzioni &amp; dismissioni, dimensionamento e organizzazione rete vendita, sales forecast, remunerazione e compenso, audit \/ formazione rete vendita, motivazione, ed altro ancora. Questo post ha lo scopo di sintetizzare i temi legati alla comunicazione efficace.<br \/>Ogni interazione umana &egrave; una forma di comunicazione. Nel mondo del business, nulla forse &egrave; pi&ugrave; importante del possedere doti per comunicare al meglio. Il sales manager, naturalmente, non sfugge a questa logica: l&rsquo;interagire con il proprio sales team, con i propri capi, con i clienti, e probabilmente con molte altre persone in azienda passa obbligatoriamente attraverso le sue capacit&agrave; a comunicare efficacemente.<br \/>Nonostante il processo di comunicazione sia cos&igrave; importante nelle attivit&agrave; umane (e segnatamente in quelle di sales management e di vendita) mi &egrave; talvolta capitato di imbattermi in aula in manager delle vendite convinti di essere ad un punto tale, su questo fronte, da non riuscire pi&ugrave; a migliorare.<br \/>Forse si tratta un po&rsquo; della differenza che intercorre tra un buon comunicatore ed un comunicatore eccellente: il primo, raggiunto questo livello, si sente &laquo;arrivato&raquo; e trova difficoltoso progredire ulteriormente. Chi &egrave; in un tale momento di stallo, si rallegri: le tecniche e le modalit&agrave; di comunicazione eccellenti possono essere apprese da chiunque e poi utilizzate in pieno nell&rsquo;attivit&agrave; di tutti i giorni. Si tratta solo di approfondire come funziona il processo di comunicazione, come comunicare esattamente ci&ograve; che si vuole, che modalit&agrave; sia preferibile a seconda del contesto e, per finire, quali siano i fattori che influenzano la capacit&agrave; di comunicare al meglio.<br \/>C&rsquo;&egrave; una distinzione tra abilit&agrave; nel comunicare bene e abilit&agrave; nel comunicare in maniera eccellente. Ad un primo esame il buon comunicatore parrebbe essere chi &egrave; padrone del processo dell&rsquo;ascolto e del parlare; questo &egrave; senz&rsquo;altro vero, e le due attivit&agrave; sono interconnesse tra di loro, durante il processo comunicativo: padroneggiarle con perizia (vedremo come) &egrave; senz&rsquo;altro indice dell&rsquo;abilit&agrave; nel comunicare. Tuttavia il saper comunicare in modo eccellente va oltre ci&ograve;: coinvolge la sfera inconscia dell&rsquo;individuo, i suoi valori di fondo, le sue convinzioni, il suo sistema percettivo, i filtri che (inconsciamente) utilizza per trattenere brandelli di messaggio, il suo desiderio e la sua volont&agrave; di ottenere un certo risultato, i comportamenti che decide di adottare, il modello linguistico che utilizza.<br \/>Il testo va poi nel dettaglio delle modalit&agrave; pi&ugrave; avanzate oggi disponibili per le due attivit&agrave; base del comunicare: ascoltare e parlare, analizzando in profondit&agrave; varie scuole di pensiero, tra le quali sottolineo quella di von Thun.<br \/>Analizza l&rsquo;impatto dei tre livelli della comunicazione, e come utilizzarli al meglio per generare attenzione, coinvolgimento, influenzamento dell&rsquo;interlocutore.<br \/>Affronta anche i modelli comunicativi relativi ad alcune attivit&agrave; manageriali specifiche: feedback di valutazione, comunicazione epistolare \/ telefonica \/ di persona, e la comunicazione uno a molti, con particolare rilevanza a come alcuni sistemi mnemotecnici possano agevolare il sales manager nel processo del comunicare alla propria rete vendita.<br \/>Per terminare questo post indico nuovamente un url dal quale si pu&ograve; scaricare liberamente un ricco estratto del mio libro (www.turboformazionevendita.com) , disponibile in versione integrale e anche in formato e-book presso l&rsquo;editore, nelle migliori librerie specializzate e in quelle web.<br \/>Sul sito www.turboformazionevendita.com potrai trovare (oltre a centinaia di articoli sulle tecniche di vendita) e-book, audiocorsi, casi di studio, e completi estratti di alcuni dei miei libri, tutto scaricabile liberamente<\/p>\n<p>Grazie, di cuore, per la lettura di questo post, e l&rsquo;eventuale condivisione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Scopri come comunicando efficacemente sia possibile raggiungere un successo duraturo nel sales management<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[59],"tags":[54440],"class_list":["post-54258","post","type-post","status-publish","format-standard","hentry","category-economia-e-lavoro","tag-s"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Scopri come diventare un sales manager di successo, comunicando efficacemente - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/scopri-come-diventare-un-sales-manager-di-successo-comunicando-efficacemente\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Scopri come diventare un sales manager di successo, comunicando efficacemente - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Scopri come comunicando efficacemente sia possibile raggiungere un successo duraturo nel sales management\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/scopri-come-diventare-un-sales-manager-di-successo-comunicando-efficacemente\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2017-01-16T19:40:50+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/scopri-come-diventare-un-sales-manager-di-successo-comunicando-efficacemente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/scopri-come-diventare-un-sales-manager-di-successo-comunicando-efficacemente\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Scopri come diventare un sales manager di successo, comunicando efficacemente\",\"datePublished\":\"2017-01-16T19:40:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/scopri-come-diventare-un-sales-manager-di-successo-comunicando-efficacemente\\\/\"},\"wordCount\":718,\"commentCount\":0,\"keywords\":[\"s\"],\"articleSection\":[\"Economia e lavoro\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/scopri-come-diventare-un-sales-manager-di-successo-comunicando-efficacemente\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/scopri-come-diventare-un-sales-manager-di-successo-comunicando-efficacemente\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/scopri-come-diventare-un-sales-manager-di-successo-comunicando-efficacemente\\\/\",\"name\":\"Scopri come diventare un sales manager di successo, comunicando efficacemente - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2017-01-16T19:40:50+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/scopri-come-diventare-un-sales-manager-di-successo-comunicando-efficacemente\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/scopri-come-diventare-un-sales-manager-di-successo-comunicando-efficacemente\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/scopri-come-diventare-un-sales-manager-di-successo-comunicando-efficacemente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Scopri come diventare un sales manager di successo, comunicando efficacemente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Scopri come diventare un sales manager di successo, comunicando efficacemente - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/scopri-come-diventare-un-sales-manager-di-successo-comunicando-efficacemente\/","og_locale":"it_IT","og_type":"article","og_title":"Scopri come diventare un sales manager di successo, comunicando efficacemente - Article Marketing","og_description":"Scopri come comunicando efficacemente sia possibile raggiungere un successo duraturo nel sales management","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/scopri-come-diventare-un-sales-manager-di-successo-comunicando-efficacemente\/","og_site_name":"Article Marketing","article_published_time":"2017-01-16T19:40:50+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/scopri-come-diventare-un-sales-manager-di-successo-comunicando-efficacemente\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/scopri-come-diventare-un-sales-manager-di-successo-comunicando-efficacemente\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Scopri come diventare un sales manager di successo, comunicando efficacemente","datePublished":"2017-01-16T19:40:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/scopri-come-diventare-un-sales-manager-di-successo-comunicando-efficacemente\/"},"wordCount":718,"commentCount":0,"keywords":["s"],"articleSection":["Economia e lavoro"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/scopri-come-diventare-un-sales-manager-di-successo-comunicando-efficacemente\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/scopri-come-diventare-un-sales-manager-di-successo-comunicando-efficacemente\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/scopri-come-diventare-un-sales-manager-di-successo-comunicando-efficacemente\/","name":"Scopri come diventare un sales manager di successo, comunicando efficacemente - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2017-01-16T19:40:50+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/scopri-come-diventare-un-sales-manager-di-successo-comunicando-efficacemente\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/scopri-come-diventare-un-sales-manager-di-successo-comunicando-efficacemente\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/scopri-come-diventare-un-sales-manager-di-successo-comunicando-efficacemente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Scopri come diventare un sales manager di successo, comunicando efficacemente"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/54258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=54258"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/54258\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=54258"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=54258"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=54258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}