{"id":5498,"date":"2010-06-18T08:34:47","date_gmt":"2010-06-18T06:34:47","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/telepass-con-autostrade-per-litalia-e-pirelli-nuova-campagna-per-la-sicurezza-stradale-estate-2010\/"},"modified":"2010-06-18T08:34:47","modified_gmt":"2010-06-18T06:34:47","slug":"telepass-con-autostrade-per-litalia-e-pirelli-nuova-campagna-per-la-sicurezza-stradale-estate-2010","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/motori\/telepass-con-autostrade-per-litalia-e-pirelli-nuova-campagna-per-la-sicurezza-stradale-estate-2010\/","title":{"rendered":"Telepass con Autostrade per l&#8217;Italia e Pirelli: Nuova Campagna per la Sicurezza Stradale Estate 2010"},"content":{"rendered":"<p><strong>[Roma, 18 Giugno 2010]<\/strong> Telepass \u00e8 partner della sicurezza stradale nella nuova campagna di sensibilizzazione lanciata da Autostrade per l\u2019Italia e Pirelli in vista dell\u2019esodo e controesodo estivo 2010.<\/p>\n<p><a><img loading=\"lazy\" decoding=\"async\" width=\"280\" height=\"340\" align=\"left\" alt=\"telepass-pirelli-autostrade-sicurezza-pneumatici\" src=\"http:\/\/www.globalsearchinteractive.net\/wp-content\/uploads\/2010\/06\/telepass-pirelli-autostrade-sicurezza-pneumatici.jpg\" title=\"telepass-pirelli-autostrade-sicurezza-pneumatici\" style=\"margin-right: 5px;\" \/><\/a>La <strong>campagna di sicurezza stradale \u201c<em>Safe &amp; Go<\/em>\u201d<\/strong>, presentata a Roma questa settimana, sar\u00e0 avviata nel week-end del 19-20 Giugno per concludersi nel fine settimana del 28-29 Agosto. La campagna di Sicurezza Stradale per l\u2019Estate 2010 sar\u00e0 attiva in alcune delle Aree di Servizio autostradali a pi\u00f9 alto traffico, dove Pirelli offrir\u00e0 agli automobilisti il controllo gratuito dello stato di sicurezza degli pneumatici, per permettere di affrontare una vacanza o un rientro dalle vacanze in tutta sicurezza.<\/p>\n<p>Pirelli rilascer\u00e0 agli automobilisti un attestato di controllo degli pneumatici, regalando anche uno spessimetro per controllare lo stato di salute delle ruote del veicolo, e un manuale con il decalogo di regole per una guida sicura, realizzato da Autostrade per l\u2019Italia.<\/p>\n<p>Oltre al <strong>check-up gratuito degli pneumatici<\/strong> e ai <strong>regali per una guida sicura<\/strong>, tutti gli automobilisti che effettueranno il controllo presso le officine mobili di Pirelli riceveranno <strong>incentivi e agevolazioni fino a 170 Euro<\/strong> per la sostituzione, entro il 14 Agosto 2010, degli pneumatici usurati. Tutti gli automobilisti riceveranno un incentivo di 100 Euro per l&#8217;acquisto di un successivo treno di ruote, mentre i clienti Telepass Premium riceveranno un bonus addizionale consistente in 70 Euro di credito in pedaggi autostradali.<\/p>\n<p>Sul sito web <a href=\"http:\/\/www.telepass.it\" title=\"Sito web Telepass\">http:\/\/www.telepass.it<\/a> sono disponibili maggiori informazioni circa la nuova campagna <\/a>La <strong>campagna di sicurezza stradale \u201c<em>Safe &amp; Go<\/em>\u201d<\/strong>, presentata a Roma questa settimana, sar\u00e0 avviata nel week-end del 19-20 Giugno per concludersi nel fine settimana del 28-29 Agosto. La campagna di Sicurezza Stradale per l\u2019Estate 2010 sar\u00e0 attiva in alcune delle Aree di Servizio autostradali a pi\u00f9 alto traffico, dove Pirelli offrir\u00e0 agli automobilisti il controllo gratuito dello stato di sicurezza degli pneumatici, per permettere di affrontare una vacanza o un rientro dalle vacanze in tutta sicurezza.<\/p>\n<p>Pirelli rilascer\u00e0 agli automobilisti un attestato di controllo degli pneumatici, regalando anche uno spessimetro per controllare lo stato di salute delle ruote del veicolo, e un manuale con il decalogo di regole per una guida sicura, realizzato da Autostrade per l\u2019Italia.<\/p>\n<p>Oltre al <strong>check-up gratuito degli pneumatici<\/strong> e ai <strong>regali per una guida sicura<\/strong>, tutti gli automobilisti che effettueranno il controllo presso le officine mobili di Pirelli riceveranno <strong>incentivi e agevolazioni fino a 170 Euro<\/strong> per la sostituzione, entro il 14 Agosto 2010, degli pneumatici usurati. Tutti gli automobilisti riceveranno un incentivo di 100 Euro per l&#8217;acquisto di un successivo treno di ruote, mentre i clienti Telepass Premium riceveranno un bonus addizionale consistente in 70 Euro di credito in pedaggi autostradali.<\/p>\n<p>Sul sito web http:\/\/www.telepass.it sono disponibili maggiori informazioni circa la nuova campagna di <strong>Sicurezza Stradale Estate 2010<\/strong> e gli incentivi offerti da Telepass e Pirelli. Sul sito Telepass \u00e8 anche disponibile una mappa interattiva (Google Map) che riporta tutte le date e le Aree di Servizio che parteciperanno all\u2019iniziativa, all\u2019indirizzo http:\/\/bit.ly\/telepass-pirelli-autostrade-sicurezza.<\/p>\n<\/p>\n<p><strong>#<\/strong><\/p>\n<p><strong>Telepass SpA<\/strong><br \/>\nTelepass S.p.A. \u00e8 la societ\u00e0 soggetta all&#8217;attivit\u00e0 di direzione e coordinamento di Autostrade per l&#8217;Italia creata per svolgere le attivit\u00e0 relative all\u2019emissione, commercializzazione e gestione dei sistemi di pagamento elettronico Telepass e Viacard. Maggiori informazioni sui prodotti e servizi di Telepass sono disponibili online sul sito web Telepass all\u2019indirizzo http:\/\/www.telepass.it e alla pagina dedicata al Mondo Telepass.<\/p>\n<p><strong>Online Press Office<\/strong><br \/> Email: ufficiostampa@autostrade.it<br \/> Telefono: +39 06 4363.2500<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuova campagna per la Sicurezza Stradale di Autostrade per l\u2019Italia, Pirelli e Telepass in vista dell\u2019esodo e controesodo estivo 2010. Officine mobili Pirelli offriranno il check-up gratuito delle gomme nelle principali Aree di Servizio delle autostrade italiane, per una vacanza all\u2019insegna della sicurezza. Per gli automobilisti, regali e incentivi fino a 170 Euro per il cambio degli pneumatici.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[479],"tags":[],"class_list":["post-5498","post","type-post","status-publish","format-standard","hentry","category-motori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Telepass con Autostrade per l&#039;Italia e Pirelli: Nuova Campagna per la Sicurezza Stradale Estate 2010 - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/motori\/telepass-con-autostrade-per-litalia-e-pirelli-nuova-campagna-per-la-sicurezza-stradale-estate-2010\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Telepass con Autostrade per l&#039;Italia e Pirelli: Nuova Campagna per la Sicurezza Stradale Estate 2010 - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Nuova campagna per la Sicurezza Stradale di Autostrade per l\u2019Italia, Pirelli e Telepass in vista dell\u2019esodo e controesodo estivo 2010. Officine mobili Pirelli offriranno il check-up gratuito delle gomme nelle principali Aree di Servizio delle autostrade italiane, per una vacanza all\u2019insegna della sicurezza. Per gli automobilisti, regali e incentivi fino a 170 Euro per il cambio degli pneumatici.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/motori\/telepass-con-autostrade-per-litalia-e-pirelli-nuova-campagna-per-la-sicurezza-stradale-estate-2010\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2010-06-18T06:34:47+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.globalsearchinteractive.net\/wp-content\/uploads\/2010\/06\/telepass-pirelli-autostrade-sicurezza-pneumatici.jpg\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/motori\\\/telepass-con-autostrade-per-litalia-e-pirelli-nuova-campagna-per-la-sicurezza-stradale-estate-2010\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/motori\\\/telepass-con-autostrade-per-litalia-e-pirelli-nuova-campagna-per-la-sicurezza-stradale-estate-2010\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Telepass con Autostrade per l&#8217;Italia e Pirelli: Nuova Campagna per la Sicurezza Stradale Estate 2010\",\"datePublished\":\"2010-06-18T06:34:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/motori\\\/telepass-con-autostrade-per-litalia-e-pirelli-nuova-campagna-per-la-sicurezza-stradale-estate-2010\\\/\"},\"wordCount\":574,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/motori\\\/telepass-con-autostrade-per-litalia-e-pirelli-nuova-campagna-per-la-sicurezza-stradale-estate-2010\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.globalsearchinteractive.net\\\/wp-content\\\/uploads\\\/2010\\\/06\\\/telepass-pirelli-autostrade-sicurezza-pneumatici.jpg\",\"articleSection\":[\"Motori\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/motori\\\/telepass-con-autostrade-per-litalia-e-pirelli-nuova-campagna-per-la-sicurezza-stradale-estate-2010\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/motori\\\/telepass-con-autostrade-per-litalia-e-pirelli-nuova-campagna-per-la-sicurezza-stradale-estate-2010\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/motori\\\/telepass-con-autostrade-per-litalia-e-pirelli-nuova-campagna-per-la-sicurezza-stradale-estate-2010\\\/\",\"name\":\"Telepass con Autostrade per l'Italia e Pirelli: Nuova Campagna per la Sicurezza Stradale Estate 2010 - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/motori\\\/telepass-con-autostrade-per-litalia-e-pirelli-nuova-campagna-per-la-sicurezza-stradale-estate-2010\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/motori\\\/telepass-con-autostrade-per-litalia-e-pirelli-nuova-campagna-per-la-sicurezza-stradale-estate-2010\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.globalsearchinteractive.net\\\/wp-content\\\/uploads\\\/2010\\\/06\\\/telepass-pirelli-autostrade-sicurezza-pneumatici.jpg\",\"datePublished\":\"2010-06-18T06:34:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/motori\\\/telepass-con-autostrade-per-litalia-e-pirelli-nuova-campagna-per-la-sicurezza-stradale-estate-2010\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/motori\\\/telepass-con-autostrade-per-litalia-e-pirelli-nuova-campagna-per-la-sicurezza-stradale-estate-2010\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/motori\\\/telepass-con-autostrade-per-litalia-e-pirelli-nuova-campagna-per-la-sicurezza-stradale-estate-2010\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.globalsearchinteractive.net\\\/wp-content\\\/uploads\\\/2010\\\/06\\\/telepass-pirelli-autostrade-sicurezza-pneumatici.jpg\",\"contentUrl\":\"http:\\\/\\\/www.globalsearchinteractive.net\\\/wp-content\\\/uploads\\\/2010\\\/06\\\/telepass-pirelli-autostrade-sicurezza-pneumatici.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/motori\\\/telepass-con-autostrade-per-litalia-e-pirelli-nuova-campagna-per-la-sicurezza-stradale-estate-2010\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Telepass con Autostrade per l&#8217;Italia e Pirelli: Nuova Campagna per la Sicurezza Stradale Estate 2010\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Telepass con Autostrade per l'Italia e Pirelli: Nuova Campagna per la Sicurezza Stradale Estate 2010 - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/motori\/telepass-con-autostrade-per-litalia-e-pirelli-nuova-campagna-per-la-sicurezza-stradale-estate-2010\/","og_locale":"it_IT","og_type":"article","og_title":"Telepass con Autostrade per l'Italia e Pirelli: Nuova Campagna per la Sicurezza Stradale Estate 2010 - Article Marketing","og_description":"Nuova campagna per la Sicurezza Stradale di Autostrade per l\u2019Italia, Pirelli e Telepass in vista dell\u2019esodo e controesodo estivo 2010. Officine mobili Pirelli offriranno il check-up gratuito delle gomme nelle principali Aree di Servizio delle autostrade italiane, per una vacanza all\u2019insegna della sicurezza. Per gli automobilisti, regali e incentivi fino a 170 Euro per il cambio degli pneumatici.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/motori\/telepass-con-autostrade-per-litalia-e-pirelli-nuova-campagna-per-la-sicurezza-stradale-estate-2010\/","og_site_name":"Article Marketing","article_published_time":"2010-06-18T06:34:47+00:00","og_image":[{"url":"http:\/\/www.globalsearchinteractive.net\/wp-content\/uploads\/2010\/06\/telepass-pirelli-autostrade-sicurezza-pneumatici.jpg","type":"","width":"","height":""}],"author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/motori\/telepass-con-autostrade-per-litalia-e-pirelli-nuova-campagna-per-la-sicurezza-stradale-estate-2010\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/motori\/telepass-con-autostrade-per-litalia-e-pirelli-nuova-campagna-per-la-sicurezza-stradale-estate-2010\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Telepass con Autostrade per l&#8217;Italia e Pirelli: Nuova Campagna per la Sicurezza Stradale Estate 2010","datePublished":"2010-06-18T06:34:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/motori\/telepass-con-autostrade-per-litalia-e-pirelli-nuova-campagna-per-la-sicurezza-stradale-estate-2010\/"},"wordCount":574,"commentCount":0,"image":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/motori\/telepass-con-autostrade-per-litalia-e-pirelli-nuova-campagna-per-la-sicurezza-stradale-estate-2010\/#primaryimage"},"thumbnailUrl":"http:\/\/www.globalsearchinteractive.net\/wp-content\/uploads\/2010\/06\/telepass-pirelli-autostrade-sicurezza-pneumatici.jpg","articleSection":["Motori"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/motori\/telepass-con-autostrade-per-litalia-e-pirelli-nuova-campagna-per-la-sicurezza-stradale-estate-2010\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/motori\/telepass-con-autostrade-per-litalia-e-pirelli-nuova-campagna-per-la-sicurezza-stradale-estate-2010\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/motori\/telepass-con-autostrade-per-litalia-e-pirelli-nuova-campagna-per-la-sicurezza-stradale-estate-2010\/","name":"Telepass con Autostrade per l'Italia e Pirelli: Nuova Campagna per la Sicurezza Stradale Estate 2010 - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/motori\/telepass-con-autostrade-per-litalia-e-pirelli-nuova-campagna-per-la-sicurezza-stradale-estate-2010\/#primaryimage"},"image":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/motori\/telepass-con-autostrade-per-litalia-e-pirelli-nuova-campagna-per-la-sicurezza-stradale-estate-2010\/#primaryimage"},"thumbnailUrl":"http:\/\/www.globalsearchinteractive.net\/wp-content\/uploads\/2010\/06\/telepass-pirelli-autostrade-sicurezza-pneumatici.jpg","datePublished":"2010-06-18T06:34:47+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/motori\/telepass-con-autostrade-per-litalia-e-pirelli-nuova-campagna-per-la-sicurezza-stradale-estate-2010\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/motori\/telepass-con-autostrade-per-litalia-e-pirelli-nuova-campagna-per-la-sicurezza-stradale-estate-2010\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.article-marketing.eu\/comunicati\/motori\/telepass-con-autostrade-per-litalia-e-pirelli-nuova-campagna-per-la-sicurezza-stradale-estate-2010\/#primaryimage","url":"http:\/\/www.globalsearchinteractive.net\/wp-content\/uploads\/2010\/06\/telepass-pirelli-autostrade-sicurezza-pneumatici.jpg","contentUrl":"http:\/\/www.globalsearchinteractive.net\/wp-content\/uploads\/2010\/06\/telepass-pirelli-autostrade-sicurezza-pneumatici.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/motori\/telepass-con-autostrade-per-litalia-e-pirelli-nuova-campagna-per-la-sicurezza-stradale-estate-2010\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Telepass con Autostrade per l&#8217;Italia e Pirelli: Nuova Campagna per la Sicurezza Stradale Estate 2010"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/5498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=5498"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/5498\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=5498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=5498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=5498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}