{"id":6128,"date":"2010-07-29T19:37:24","date_gmt":"2010-07-29T17:37:24","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/la-depressione-cosa%80%99%c3%a8-quali-sono-i-sintomi-come-curarla\/"},"modified":"2010-07-29T19:37:24","modified_gmt":"2010-07-29T17:37:24","slug":"la-depressione-cosa%80%99%c3%a8-quali-sono-i-sintomi-come-curarla","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/la-depressione-cosa%80%99%c3%a8-quali-sono-i-sintomi-come-curarla\/","title":{"rendered":"La depressione: cos\u2019\u00e8, quali sono i sintomi, come curarla."},"content":{"rendered":"<p><strong>La depressione: cos&rsquo;&egrave;, quali sono i sintomi, come curarla.<\/strong><br \/><strong>Prima parte<\/strong><br \/><strong>&#8211; Cos&rsquo;&egrave; la depressione?<\/strong><br \/>La depressione &egrave; classificata come un disturbo dell&rsquo;umore.<br \/>L&rsquo;umore nel linguaggio comune indica una disposizione dell&rsquo;animo o un atteggiamento interiore. In medicina e in psicologia, &egrave; inteso come lo stato emozionale interno di un individuo, ossia l&rsquo;insieme delle disposizioni affettive ed istintive che determinano il tono prevalente dell&rsquo;attivit&agrave; psichica.<br \/>L&rsquo;umore pu&ograve; avere un potente effetto sulla nostra vita, sul nostro comportamento, su ci&ograve; che pensiamo, sentiamo e desideriamo. L&rsquo;umore &egrave;, per sua natura, estremamente fluttuante in ognuno di noi e presenta diverse sfumature; ci&ograve; dipende da parametri psicobiologici, da stimoli provenienti dal mondo esterno o da contenuti del nostro mondo interno.<br \/>La perdita dell&rsquo;equilibrio fra avvenimenti esterni ed interni (la percezione di noi stessi e del mondo), la perdita della capacit&agrave; di modulare l&rsquo;umore, &egrave; la principale caratteristica dei disturbi dell&rsquo;umore. In questi disturbi, l&rsquo;umore rimane come bloccato e non &egrave; pi&ugrave; modificabile in base agli avvenimenti esterni. Al contrario, &egrave; la realt&agrave; esterna ad essere letta, &ldquo;colorata&rdquo;, in base al tono dell&rsquo;umore: se l&rsquo;umore &egrave; nero (depressione), tutto viene percepito come nero, se l&rsquo;umore &egrave; euforico (come negli stati maniacali) tutto viene letto con la stessa positivit&agrave; (anche gli eventi potenzialmente nocivi).<br \/>I disturbi dell&rsquo;umore sono i disturbi psichiatrici pi&ugrave; diffusi, hanno manifestazioni cliniche molto variabili e sono caratterizzati dalla presenza di molti sintomi sia fisici che psichici.<br \/>Alcuni &ldquo;sintomi depressivi&rdquo; sporadici e fluttuanti sono esperienza comune nella vita di tutti noi e sono rapidamente transitori: nel linguaggio comune diciamo di &ldquo;essere depressi&rdquo; quando ci capita di sentirci un po&rsquo; tristi per qualcosa che &egrave; andato storto sul lavoro, in famiglia o con gli amici. La tristezza &egrave; un emozione umana ed &egrave; perfettamente normale attraversare dei momenti di sconforto in relazione a determinati eventi. <br \/>La sindrome depressiva &egrave; ben altra cosa, ha una durata pi&ugrave; ampia, presenta molti sintomi ed &egrave; caratterizzata dalla presenza di eventi di vita precedenti all&rsquo;esordio e da una spiccata familiarit&agrave; (un soggetto depresso ha molto spesso in famiglia altri soggetti con lo stesso tipo di disturbo). Tale patologia &egrave; contraddistinta da sintomi specifici ed &egrave; in grado di minare potentemente la capacit&agrave; di una persona di affrontare la vita. La depressione &egrave; una condizione psicologica che influisce negativamente sull&rsquo;umore, sul pensiero, sul comportamento e comporta spesso delle alterazioni del sonno, dell&rsquo;appetito e del desiderio sessuale: tutto ci&ograve; diminuisce in maniera da lieve a grave il &ldquo;funzionamento&rdquo; di una persona e le sue abilit&agrave; di adattamento alla vita sociale.<br \/>La depressione non &egrave; quindi un semplice abbassamento dell&rsquo;umore, ma un insieme di sintomi pi&ugrave; o meno complessi che alterano anche in maniera consistente il modo in cui una persona ragiona, pensa e raffigura se stessa, gli altri ed il mondo esterno.<\/p>\n<p>Dott.ssa Danila Macci&ograve; <a href=\"http:\/\/www.psicologogenova-masone.it\/\">www.psicologogenova-masone.it<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La depressione: cos\u2019\u00e8, quali sono i sintomi, come curarla.<br \/>In questa prima parte si descrive cosa sia la depressione, a seguire gli articoli riguardanti sintomi specifici e cura della depressione.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[265],"tags":[16480,16478,5631,16481,15321,15322,16479],"class_list":["post-6128","post","type-post","status-publish","format-standard","hentry","category-salute-e-benessere","tag-cose-depressione","tag-cura-depressione","tag-depressione","tag-disturbi-dellumore","tag-psicologo","tag-psicoterapeuta","tag-sintomi-depressione"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La depressione: cos\u2019\u00e8, quali sono i sintomi, come curarla. - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/la-depressione-cosa??\u00e8-quali-sono-i-sintomi-come-curarla\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La depressione: cos\u2019\u00e8, quali sono i sintomi, come curarla. - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"La depressione: cos\u2019\u00e8, quali sono i sintomi, come curarla.In questa prima parte si descrive cosa sia la depressione, a seguire gli articoli riguardanti sintomi specifici e cura della depressione.\" \/>\n<meta property=\"og:url\" content=\"\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2010-07-29T17:37:24+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/la-depressione-cosa%80%99%c3%a8-quali-sono-i-sintomi-come-curarla\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/la-depressione-cosa%80%99%c3%a8-quali-sono-i-sintomi-come-curarla\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"La depressione: cos\u2019\u00e8, quali sono i sintomi, come curarla.\",\"datePublished\":\"2010-07-29T17:37:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/la-depressione-cosa%80%99%c3%a8-quali-sono-i-sintomi-come-curarla\\\/\"},\"wordCount\":545,\"commentCount\":0,\"keywords\":[\"cos'\u00e8 depressione\",\"cura depressione\",\"depressione\",\"disturbi dell'umore\",\"psicologo\",\"psicoterapeuta\",\"sintomi depressione\"],\"articleSection\":[\"Salute e benessere\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/la-depressione-cosa%80%99%c3%a8-quali-sono-i-sintomi-come-curarla\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/la-depressione-cosa%80%99%c3%a8-quali-sono-i-sintomi-come-curarla\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/la-depressione-cosa%80%99%c3%a8-quali-sono-i-sintomi-come-curarla\\\/\",\"name\":\"La depressione: cos\u2019\u00e8, quali sono i sintomi, come curarla. - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2010-07-29T17:37:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/la-depressione-cosa%80%99%c3%a8-quali-sono-i-sintomi-come-curarla\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/la-depressione-cosa%80%99%c3%a8-quali-sono-i-sintomi-come-curarla\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/la-depressione-cosa%80%99%c3%a8-quali-sono-i-sintomi-come-curarla\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La depressione: cos\u2019\u00e8, quali sono i sintomi, come curarla.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La depressione: cos\u2019\u00e8, quali sono i sintomi, come curarla. - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/la-depressione-cosa??\u00e8-quali-sono-i-sintomi-come-curarla\/","og_locale":"it_IT","og_type":"article","og_title":"La depressione: cos\u2019\u00e8, quali sono i sintomi, come curarla. - Article Marketing","og_description":"La depressione: cos\u2019\u00e8, quali sono i sintomi, come curarla.In questa prima parte si descrive cosa sia la depressione, a seguire gli articoli riguardanti sintomi specifici e cura della depressione.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/la-depressione-cosa??\u00e8-quali-sono-i-sintomi-come-curarla\/","og_site_name":"Article Marketing","article_published_time":"2010-07-29T17:37:24+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/la-depressione-cosa%80%99%c3%a8-quali-sono-i-sintomi-come-curarla\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/la-depressione-cosa%80%99%c3%a8-quali-sono-i-sintomi-come-curarla\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"La depressione: cos\u2019\u00e8, quali sono i sintomi, come curarla.","datePublished":"2010-07-29T17:37:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/la-depressione-cosa%80%99%c3%a8-quali-sono-i-sintomi-come-curarla\/"},"wordCount":545,"commentCount":0,"keywords":["cos'\u00e8 depressione","cura depressione","depressione","disturbi dell'umore","psicologo","psicoterapeuta","sintomi depressione"],"articleSection":["Salute e benessere"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/la-depressione-cosa%80%99%c3%a8-quali-sono-i-sintomi-come-curarla\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/la-depressione-cosa%80%99%c3%a8-quali-sono-i-sintomi-come-curarla\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/la-depressione-cosa%80%99%c3%a8-quali-sono-i-sintomi-come-curarla\/","name":"La depressione: cos\u2019\u00e8, quali sono i sintomi, come curarla. - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2010-07-29T17:37:24+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/la-depressione-cosa%80%99%c3%a8-quali-sono-i-sintomi-come-curarla\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/la-depressione-cosa%80%99%c3%a8-quali-sono-i-sintomi-come-curarla\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/la-depressione-cosa%80%99%c3%a8-quali-sono-i-sintomi-come-curarla\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"La depressione: cos\u2019\u00e8, quali sono i sintomi, come curarla."}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/6128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=6128"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/6128\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=6128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=6128"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=6128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}