{"id":7413,"date":"2010-09-17T10:18:48","date_gmt":"2010-09-17T08:18:48","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/stogea-aperte-le-iscrizioni-al-master-in-business-administration-per-profili-tecnici\/"},"modified":"2018-07-10T03:47:32","modified_gmt":"2018-07-10T01:47:32","slug":"stogea-aperte-le-iscrizioni-al-master-in-business-administration-per-profili-tecnici","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/corsi\/stogea-aperte-le-iscrizioni-al-master-in-business-administration-per-profili-tecnici\/","title":{"rendered":"Stogea, aperte le Iscrizioni al Master in Business Administration per Profili Tecnici"},"content":{"rendered":"<p>Aperte le Iscrizioni per accedere al Master in Business Administration per Profili Tecnici che si svolger&agrave; a Roma ed &egrave; ideato per coloro che gi&agrave; lavorano.<br \/>La partecipazione &egrave; riservata solo a 15 partecipanti che dovranno superare una prima valutazione dei loro curriculum ed in seguito un colloquio. E&rsquo; possibile compilare il form sul sito, allegare il curriculum per conoscere la giornata d valutazione. I Destinatari sono coloro che hanno una formazione tecnica ma vogliono sviluppare il loro profilo dal punto di vista dell&rsquo;Organizzazione Aziendale per poter aspirare a posizioni di maggior responsabilit&agrave; all&rsquo;interno delle aziende. Gli Obiettivi del Master sono finalizzati a fornire una visione dell&rsquo;azienda dal punto di vista della professionalit&agrave; delle risprse umane, del marketing, della comunicazione e nella possibilit&agrave; di interfacciarsi con tutti i settori dell&rsquo;azienda. Nel secondo anno sar&agrave; possibile scegliere un percorso di specializzazione su vari settori: dal Project Management alla Logistica Integrata, dalla Direzione delle Risorse Umane al Marketing, Comunicazione e Relazioni Pubbliche. Stogea &egrave; leader nella realizzazione di Master, Corsi e Consulenza per migliorare la cultura d&rsquo;impresa dei partecipanti con lo scopo di creare figure pi&ugrave; capaci e con pi&ugrave; possibilit&agrave; di accedere o di crescere nel mondo del lavoro. Approfondimento: Cos&#8217;&egrave; il Master in Business Administration (Fonte Wikipedia) Il Master in Business Administration (MBA) &egrave; un corso di diploma al quale possono accedere, previa selezione, laureati nelle pi&ugrave; diverse discipline, accumunati per&ograve; dall&#8217;avere un&#8217;attitudine allo studio in campo economico (verificabile attraverso il test GMAT) ed una rilevante esperienza professionale di alcuni anni. Lo scopo dell&#8217;MBA &egrave; fornire ai partecipanti una formazione di general management su tutte le tematiche di gestione di impresa.<\/p>\n<p>L&#8217;MBA &egrave; il master of science in materie economiche e gestionali con la pi&ugrave; lunga tradizione: le prime Management School e MBA compaiono infatti negli Stati Uniti gi&agrave; negli anni &#8217;30.<\/p>\n<p>Solamente negli ultimi vent&#8217;anni sono stati introdotti corsi MBA anche in Italia, come il MIP School of Management del Politecnico di Milano, lo SDA dell&#8217;Universit&agrave; Bocconi, la Scuola di Management dell&#8217;Universit&agrave; Luiss Guido Carli, la Fondazione CUOA di Vicenza. Nel 2008, l&#8217;unico MBA italiano a comparire nella classifica del Financial Times &egrave; stato quello gestito dallo SDA Bocconi.<\/p>\n<p>Tale corso &egrave; organizzato dalle maggiori Business School internazionali ed &egrave; attualmente considerato come il pi&ugrave; alto grado di specializzazione che si possa acquisire in questo campo. Alcune aziende ed organizzazioni internazionali pagano l&#8217;MBA ad alcuni tra i loro migliori dipendenti, sia durante la loro attivit&agrave; lavorativa (MBA part-time) sia durante una pausa (con un contratto di riassunzione finito il corso). In un caso, il dipendente frequenta un master serale oppure assentandosi alcune ore retribuite alla settimana durante l&#8217;orario di lavoro; nell&#8217;altro caso, utilizza il cosiddetto &#8220;anno sabbatico&#8221;, un anno non retribuito che il lavoratore pu&ograve; chiedere una volta nella vita lavorativa per fare qualcosa che ritiene importante per s&eacute;, e che non &egrave; tenuto a giustificare, come viaggi, una laurea per cultura personale o qualcosa di utile per la propria carriera.<\/p>\n<p>Si tratta di un grosso investimento, in particolare per le aziende che decidono di crescere per linee interne, senza &#8220;importare&#8221; i dirigenti da imprese che operano in settori o con prodotti completamente differenti. Dato l&#8217;importo elevato delle rette per un MBA, l&#8217;azienda richiede al dipendente un tempo di 1-2 anni di permanenza minima in azienda (come dirigente) a conclusione del master per recuperare l&#8217;investimento fatto sulla persona. Se il dipendente cerca una migliore posizione lavorativa altrove, &egrave; tenuto a risarcire all&#8217;impresa parte o tutto l&#8217;importo sostenuto.<\/p>\n<p>Molti manager di grandi aziende internazionali hanno conseguito un MBA presso una delle business school: il diploma MBA &egrave; considerato un simbolo di successo e una garanzia di una carriera lavorativa pi&ugrave; che brillante.<\/p>\n<p>I corsi sono focalizzati sia sulle aree strettamente tecniche (principalmente finanza, marketing ed economia) sia sullo sviluppo delle doti personali (come leadership e management) richieste nel mondo corporativo; in generale per&ograve; il programma varia da scuola a scuola anche secondo il tipo di corso prescelto, ma sicuramente parte dell&#8217;apprendimento avviene sempre tramite l&#8217;analisi di casi pratici e innumerevoli attivit&agrave; di gruppo.<\/p>\n<p>Presso le principali scuole di management sono sorte associazioni di ex alunni MBA, che favoriscono lo sviluppo di relazioni culturali e professionali tra i diplomati. Tra le pi&ugrave; note c&#8217;&egrave; l&#8217;AMSDA (Bocconi, Milano), l&#8217;Assomaster (Luiss, Roma), l&#8217;AMIP (Politecnico, Milano).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Presentato da Stogea il Corso MBA per profili tecnici. Il Master si svolger\u00e0 a Roma e sono gi\u00e0 aperte le candidature per coloro che pur avendo una formazione tecnica vogliono ampliare le loro conoscenze aziendali e di management.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[747],"tags":[17626],"class_list":["post-7413","post","type-post","status-publish","format-standard","hentry","category-corsi","tag-master-in-business-administration"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Stogea, aperte le Iscrizioni al Master in Business Administration per Profili Tecnici - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/corsi\/stogea-aperte-le-iscrizioni-al-master-in-business-administration-per-profili-tecnici\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stogea, aperte le Iscrizioni al Master in Business Administration per Profili Tecnici - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Presentato da Stogea il Corso MBA per profili tecnici. Il Master si svolger\u00e0 a Roma e sono gi\u00e0 aperte le candidature per coloro che pur avendo una formazione tecnica vogliono ampliare le loro conoscenze aziendali e di management.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/corsi\/stogea-aperte-le-iscrizioni-al-master-in-business-administration-per-profili-tecnici\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2010-09-17T08:18:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-10T01:47:32+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/istruzione\\\/corsi\\\/stogea-aperte-le-iscrizioni-al-master-in-business-administration-per-profili-tecnici\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/istruzione\\\/corsi\\\/stogea-aperte-le-iscrizioni-al-master-in-business-administration-per-profili-tecnici\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Stogea, aperte le Iscrizioni al Master in Business Administration per Profili Tecnici\",\"datePublished\":\"2010-09-17T08:18:48+00:00\",\"dateModified\":\"2018-07-10T01:47:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/istruzione\\\/corsi\\\/stogea-aperte-le-iscrizioni-al-master-in-business-administration-per-profili-tecnici\\\/\"},\"wordCount\":758,\"commentCount\":0,\"keywords\":[\"master in business administration\"],\"articleSection\":[\"Corsi\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/istruzione\\\/corsi\\\/stogea-aperte-le-iscrizioni-al-master-in-business-administration-per-profili-tecnici\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/istruzione\\\/corsi\\\/stogea-aperte-le-iscrizioni-al-master-in-business-administration-per-profili-tecnici\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/istruzione\\\/corsi\\\/stogea-aperte-le-iscrizioni-al-master-in-business-administration-per-profili-tecnici\\\/\",\"name\":\"Stogea, aperte le Iscrizioni al Master in Business Administration per Profili Tecnici - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2010-09-17T08:18:48+00:00\",\"dateModified\":\"2018-07-10T01:47:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/istruzione\\\/corsi\\\/stogea-aperte-le-iscrizioni-al-master-in-business-administration-per-profili-tecnici\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/istruzione\\\/corsi\\\/stogea-aperte-le-iscrizioni-al-master-in-business-administration-per-profili-tecnici\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/istruzione\\\/corsi\\\/stogea-aperte-le-iscrizioni-al-master-in-business-administration-per-profili-tecnici\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stogea, aperte le Iscrizioni al Master in Business Administration per Profili Tecnici\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stogea, aperte le Iscrizioni al Master in Business Administration per Profili Tecnici - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/corsi\/stogea-aperte-le-iscrizioni-al-master-in-business-administration-per-profili-tecnici\/","og_locale":"it_IT","og_type":"article","og_title":"Stogea, aperte le Iscrizioni al Master in Business Administration per Profili Tecnici - Article Marketing","og_description":"Presentato da Stogea il Corso MBA per profili tecnici. Il Master si svolger\u00e0 a Roma e sono gi\u00e0 aperte le candidature per coloro che pur avendo una formazione tecnica vogliono ampliare le loro conoscenze aziendali e di management.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/corsi\/stogea-aperte-le-iscrizioni-al-master-in-business-administration-per-profili-tecnici\/","og_site_name":"Article Marketing","article_published_time":"2010-09-17T08:18:48+00:00","article_modified_time":"2018-07-10T01:47:32+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/corsi\/stogea-aperte-le-iscrizioni-al-master-in-business-administration-per-profili-tecnici\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/corsi\/stogea-aperte-le-iscrizioni-al-master-in-business-administration-per-profili-tecnici\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Stogea, aperte le Iscrizioni al Master in Business Administration per Profili Tecnici","datePublished":"2010-09-17T08:18:48+00:00","dateModified":"2018-07-10T01:47:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/corsi\/stogea-aperte-le-iscrizioni-al-master-in-business-administration-per-profili-tecnici\/"},"wordCount":758,"commentCount":0,"keywords":["master in business administration"],"articleSection":["Corsi"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/corsi\/stogea-aperte-le-iscrizioni-al-master-in-business-administration-per-profili-tecnici\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/corsi\/stogea-aperte-le-iscrizioni-al-master-in-business-administration-per-profili-tecnici\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/corsi\/stogea-aperte-le-iscrizioni-al-master-in-business-administration-per-profili-tecnici\/","name":"Stogea, aperte le Iscrizioni al Master in Business Administration per Profili Tecnici - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2010-09-17T08:18:48+00:00","dateModified":"2018-07-10T01:47:32+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/corsi\/stogea-aperte-le-iscrizioni-al-master-in-business-administration-per-profili-tecnici\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/corsi\/stogea-aperte-le-iscrizioni-al-master-in-business-administration-per-profili-tecnici\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/istruzione\/corsi\/stogea-aperte-le-iscrizioni-al-master-in-business-administration-per-profili-tecnici\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Stogea, aperte le Iscrizioni al Master in Business Administration per Profili Tecnici"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/7413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=7413"}],"version-history":[{"count":1,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/7413\/revisions"}],"predecessor-version":[{"id":57194,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/7413\/revisions\/57194"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=7413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=7413"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=7413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}