{"id":7521,"date":"2010-09-20T15:55:45","date_gmt":"2010-09-20T13:55:45","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/credito-al-consumo-pi%2525c3%2525b9-chiarezza-e-trasparenza-con-le-nuove-regole-della%252580%252599unione-europea-in-vigore-da-oggi\/"},"modified":"2010-09-20T15:55:45","modified_gmt":"2010-09-20T13:55:45","slug":"credito-al-consumo-pi%2525c3%2525b9-chiarezza-e-trasparenza-con-le-nuove-regole-della%252580%252599unione-europea-in-vigore-da-oggi","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/credito-al-consumo-pi%2525c3%2525b9-chiarezza-e-trasparenza-con-le-nuove-regole-della%252580%252599unione-europea-in-vigore-da-oggi\/","title":{"rendered":"Credito al consumo, pi\u00f9 chiarezza e trasparenza con le nuove regole dell\u2019Unione Europea"},"content":{"rendered":"<p>http:\/\/www.investireinformati.com\/news\/credito-al-consumo-le-nuove-regole-dellunione-europea-vigore-da-oggi\/ <a href=\"\/uploads\/images\/u_4749\/thumb_credito_al_consumo-nuove_regole_ue.gif\" class=\"image\"><img decoding=\"async\" src=\"\/uploads\/images\/u_4749\/thumb_credito_al_consumo-nuove_regole_ue.gif\" border=\"0\" \/><\/a>Oggi entrano in vigore<strong> le nuove regole dell&rsquo;Unione Europea<\/strong> a proposito di credito al consumo. Il decreto legislativo 141 del 13 agosto 2010, che allinea l&rsquo;Italia alla normativa europea sul <strong>credito a consumo <\/strong>(direttiva 2008\/48\/CE), diventa finalmente operativo anche da noi, facendo ordine in un campo con poca <strong>trasparenza<\/strong>. Tra le tante novit&agrave; della riforma, che mira ad una maggiore <strong>chiarezza<\/strong> delle informative degli istituti finanziari, garantendo al consumatore il diritto ad una scelta consapevole, c&rsquo;&egrave; la possibilit&agrave; di ripensarci e recedere dal contratto (gi&agrave; firmato) con una semplice procedura. La nuova legge dovrebbe portare uniformit&agrave; e regole comuni a tutti gli Stati membri dell&rsquo;Unione Europea in tema di finanziamenti. Che cosa cambia dunque per la clientela interessata a richiedere un finanziamento?<br \/> Con le <strong>nuove regole sul credito al consumo<\/strong>, innanzitutto cambiano le <strong>soglie di accesso<\/strong>. Il credito al consumo prima prevedeva un limite di accesso attorno ai 30.000 euro, mentre ora i contratti compresi nella nuova normativa vanno da un minimo di 200 ad un massimo di 75.000 euro.<br \/> Chi ricorre al finanziamento avr&agrave; <strong>diritto di recesso<\/strong>: potr&agrave; recedere dal contratto di finanziamento entro 14 giorni dalla firma senza dover fornire motivazioni o pagare delle penali.<br \/> Inoltre il consumatore potr&agrave; svincolarsi dal contratto anche in caso di <strong>inadempimento del fornitore<\/strong> se, per esempio, il prodotto o servizio non viene consegnato o presenta dei difetti. In questo caso si parla di &ldquo;diritto alla risoluzione del prestito&rdquo;. Il cliente potr&agrave; quindi fermare il pagamento delle rate e ottenere il rimborso di quelle gi&agrave; pagate.<br \/> A questo proposito grande importanza avr&agrave; il collegamento negoziale, ossia il rapporto tra il contratto di acquisto e quello di finanziamento: al decadere del primo decade pertanto anche il secondo.<br \/> Le nuove regole riguardano i prestiti personali, quelli finalizzati all&rsquo;acquisto di un determinato bene, la cessione del quinto dello stipendio e della pensione. Ma &egrave; bene ricordare che, anche se attiva da oggi, la concreta applicazione della legge probabilmente avverr&agrave; nel 2011. Bisogner&agrave; infatti attendere le indicazioni della Banca d&rsquo;Italia, che avr&agrave; tempo 120 giorni per emanare la normativa di dettaglio. Inoltre, gli intermediari finanziari disporranno di altri 90 giorni per recepirla.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oggi entrano in vigore le nuove regole dell\u2019Unione Europea a proposito di credito al consumo. Il decreto legislativo 141 del 13 agosto 2010, che allinea l\u2019Italia alla normativa europea sul credito a consumo (direttiva 2008\/48\/CE), diventa finalmente operativo anche da noi, facendo ordine in un campo con poca trasparenza.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[59],"tags":[],"class_list":["post-7521","post","type-post","status-publish","format-standard","hentry","category-economia-e-lavoro"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Credito al consumo, pi\u00f9 chiarezza e trasparenza con le nuove regole dell\u2019Unione Europea - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/credito-al-consumo-pi%25c3%25b9-chiarezza-e-trasparenza-con-le-nuove-regole-della%2580%2599unione-europea-in-vigore-da-oggi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Credito al consumo, pi\u00f9 chiarezza e trasparenza con le nuove regole dell\u2019Unione Europea - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Oggi entrano in vigore le nuove regole dell\u2019Unione Europea a proposito di credito al consumo. Il decreto legislativo 141 del 13 agosto 2010, che allinea l\u2019Italia alla normativa europea sul credito a consumo (direttiva 2008\/48\/CE), diventa finalmente operativo anche da noi, facendo ordine in un campo con poca trasparenza.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/credito-al-consumo-pi%25c3%25b9-chiarezza-e-trasparenza-con-le-nuove-regole-della%2580%2599unione-europea-in-vigore-da-oggi\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2010-09-20T13:55:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.article-marketing.eu\/uploads\/images\/u_4749\/thumb_credito_al_consumo-nuove_regole_ue.gif\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/credito-al-consumo-pi%2525c3%2525b9-chiarezza-e-trasparenza-con-le-nuove-regole-della%252580%252599unione-europea-in-vigore-da-oggi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/credito-al-consumo-pi%2525c3%2525b9-chiarezza-e-trasparenza-con-le-nuove-regole-della%252580%252599unione-europea-in-vigore-da-oggi\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Credito al consumo, pi\u00f9 chiarezza e trasparenza con le nuove regole dell\u2019Unione Europea\",\"datePublished\":\"2010-09-20T13:55:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/credito-al-consumo-pi%2525c3%2525b9-chiarezza-e-trasparenza-con-le-nuove-regole-della%252580%252599unione-europea-in-vigore-da-oggi\\\/\"},\"wordCount\":392,\"commentCount\":0,\"articleSection\":[\"Economia e lavoro\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/credito-al-consumo-pi%2525c3%2525b9-chiarezza-e-trasparenza-con-le-nuove-regole-della%252580%252599unione-europea-in-vigore-da-oggi\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/credito-al-consumo-pi%2525c3%2525b9-chiarezza-e-trasparenza-con-le-nuove-regole-della%252580%252599unione-europea-in-vigore-da-oggi\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/credito-al-consumo-pi%2525c3%2525b9-chiarezza-e-trasparenza-con-le-nuove-regole-della%252580%252599unione-europea-in-vigore-da-oggi\\\/\",\"name\":\"Credito al consumo, pi\u00f9 chiarezza e trasparenza con le nuove regole dell\u2019Unione Europea - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2010-09-20T13:55:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/credito-al-consumo-pi%2525c3%2525b9-chiarezza-e-trasparenza-con-le-nuove-regole-della%252580%252599unione-europea-in-vigore-da-oggi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/credito-al-consumo-pi%2525c3%2525b9-chiarezza-e-trasparenza-con-le-nuove-regole-della%252580%252599unione-europea-in-vigore-da-oggi\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/credito-al-consumo-pi%2525c3%2525b9-chiarezza-e-trasparenza-con-le-nuove-regole-della%252580%252599unione-europea-in-vigore-da-oggi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Credito al consumo, pi\u00f9 chiarezza e trasparenza con le nuove regole dell\u2019Unione Europea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Credito al consumo, pi\u00f9 chiarezza e trasparenza con le nuove regole dell\u2019Unione Europea - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/credito-al-consumo-pi%25c3%25b9-chiarezza-e-trasparenza-con-le-nuove-regole-della%2580%2599unione-europea-in-vigore-da-oggi\/","og_locale":"it_IT","og_type":"article","og_title":"Credito al consumo, pi\u00f9 chiarezza e trasparenza con le nuove regole dell\u2019Unione Europea - Article Marketing","og_description":"Oggi entrano in vigore le nuove regole dell\u2019Unione Europea a proposito di credito al consumo. Il decreto legislativo 141 del 13 agosto 2010, che allinea l\u2019Italia alla normativa europea sul credito a consumo (direttiva 2008\/48\/CE), diventa finalmente operativo anche da noi, facendo ordine in un campo con poca trasparenza.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/credito-al-consumo-pi%25c3%25b9-chiarezza-e-trasparenza-con-le-nuove-regole-della%2580%2599unione-europea-in-vigore-da-oggi\/","og_site_name":"Article Marketing","article_published_time":"2010-09-20T13:55:45+00:00","og_image":[{"url":"https:\/\/www.article-marketing.eu\/uploads\/images\/u_4749\/thumb_credito_al_consumo-nuove_regole_ue.gif","type":"","width":"","height":""}],"author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/credito-al-consumo-pi%2525c3%2525b9-chiarezza-e-trasparenza-con-le-nuove-regole-della%252580%252599unione-europea-in-vigore-da-oggi\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/credito-al-consumo-pi%2525c3%2525b9-chiarezza-e-trasparenza-con-le-nuove-regole-della%252580%252599unione-europea-in-vigore-da-oggi\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Credito al consumo, pi\u00f9 chiarezza e trasparenza con le nuove regole dell\u2019Unione Europea","datePublished":"2010-09-20T13:55:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/credito-al-consumo-pi%2525c3%2525b9-chiarezza-e-trasparenza-con-le-nuove-regole-della%252580%252599unione-europea-in-vigore-da-oggi\/"},"wordCount":392,"commentCount":0,"articleSection":["Economia e lavoro"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/credito-al-consumo-pi%2525c3%2525b9-chiarezza-e-trasparenza-con-le-nuove-regole-della%252580%252599unione-europea-in-vigore-da-oggi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/credito-al-consumo-pi%2525c3%2525b9-chiarezza-e-trasparenza-con-le-nuove-regole-della%252580%252599unione-europea-in-vigore-da-oggi\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/credito-al-consumo-pi%2525c3%2525b9-chiarezza-e-trasparenza-con-le-nuove-regole-della%252580%252599unione-europea-in-vigore-da-oggi\/","name":"Credito al consumo, pi\u00f9 chiarezza e trasparenza con le nuove regole dell\u2019Unione Europea - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2010-09-20T13:55:45+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/credito-al-consumo-pi%2525c3%2525b9-chiarezza-e-trasparenza-con-le-nuove-regole-della%252580%252599unione-europea-in-vigore-da-oggi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/credito-al-consumo-pi%2525c3%2525b9-chiarezza-e-trasparenza-con-le-nuove-regole-della%252580%252599unione-europea-in-vigore-da-oggi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/credito-al-consumo-pi%2525c3%2525b9-chiarezza-e-trasparenza-con-le-nuove-regole-della%252580%252599unione-europea-in-vigore-da-oggi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Credito al consumo, pi\u00f9 chiarezza e trasparenza con le nuove regole dell\u2019Unione Europea"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/7521","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=7521"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/7521\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=7521"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=7521"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=7521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}