{"id":8653,"date":"2010-10-20T14:55:42","date_gmt":"2010-10-20T12:55:42","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/nemes-a-viscom-dal-21-al-23-ottobre-in-fiera-milano-la%80%99evento-internazionale-dedicato-alla-comunicazione-visiva-a-360_1-2\/"},"modified":"2010-10-20T14:55:42","modified_gmt":"2010-10-20T12:55:42","slug":"nemes-a-viscom-dal-21-al-23-ottobre-in-fiera-milano-la%80%99evento-internazionale-dedicato-alla-comunicazione-visiva-a-360_1-2","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/nemes-a-viscom-dal-21-al-23-ottobre-in-fiera-milano-la%80%99evento-internazionale-dedicato-alla-comunicazione-visiva-a-360_1-2\/","title":{"rendered":"Nemes a Viscom: dal 21 al 23 ottobre in Fiera Milano."},"content":{"rendered":"<p><em>Milano, 21 Ottobre 2010 &ndash; <\/em>Al via la 22&deg; edizione di Viscom Italia, la fiera internazionale di riferimento per la visual communication, in programma dal 21 al 23 ottobre in Fiera Milano Quartiere Rho. <strong>Nemes<\/strong>, azienda di consulenza informatica per la comunicazione e il marketing, presenter&agrave; alcune delle sue pi&ugrave; innovative soluzioni interattive a marchio <strong>Gesto<\/strong>, all&rsquo;interno dell&rsquo;<strong>area Digital Signage<\/strong>, presso il<strong> padiglione P23<\/strong>. <br \/> L&rsquo;offerta Gesto &egrave; molteplice e completa: hardware, software, contenuti e assistenza post-vendita al cliente. L&rsquo;obiettivo &egrave; quello di fornire sempre un servizio flessibile e unico, partendo da dispositivi e sistemi tecnologici all&rsquo;avanguardia e creando soluzioni assolutamente personalizzate per i clienti. Tra le soluzioni pi&ugrave; innovative e recenti, Gesto propone tavoli e monitor touch screen, pavimenti interattivi (Magic Walk), holoprisma e soluzioni RFID (radio frequency identifier). In particolare a Viscom 2010 <strong>Nemes sar&agrave; presente con i suoi innovativi ed eleganti Holoprisma<\/strong> (visionabili in due modelli, small e large) e l&rsquo;interattivit&agrave; <strong>touch screen<\/strong>, tramite un monitor verticale da 40&rsquo;&rsquo;, dotato di tecnologia light touch (per interagire senza pressione) dall&rsquo;interfaccia user friendly e integrabile con la tecnologia RFID (radio frequency identifier). <strong>Gesto &egrave; presente presso l&rsquo;area DIGITAL SIGNAGE, stand P23<\/strong> <a href=\"http:\/\/www.gesto.biz\/\">www.gesto.biz<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Milano, 21 Ottobre 2010 &ndash; Al via la 22&deg; edizione di Viscom Italia, la fiera internazionale di riferimento per la visual communication, in programma dal 21 al 23 ottobre in Fiera Milano Quartiere Rho. Nemes, azienda di consulenza informatica per la comunicazione e il marketing, presenter&agrave; alcune delle sue pi&ugrave; innovative soluzioni interattive a marchio Gesto, all&rsquo;interno dell&rsquo;area Digital Signage, presso il padiglione P23. L&rsquo;offerta Gesto &egrave; molteplice e completa:<\/p>\n<p><a class=\"continue-reading\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/nemes-a-viscom-dal-21-al-23-ottobre-in-fiera-milano-la%80%99evento-internazionale-dedicato-alla-comunicazione-visiva-a-360_1-2\/\">Continue reading&#8230;<\/a><\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[388],"tags":[18659,5303,18657,18660,18658],"class_list":["post-8653","post","type-post","status-publish","format-standard","hentry","category-eventi","tag-holpoprisma","tag-interattivita","tag-nemes","tag-oloprisma","tag-viscom"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nemes a Viscom: dal 21 al 23 ottobre in Fiera Milano. - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/nemes-a-viscom-dal-21-al-23-ottobre-in-fiera-milano-la??evento-internazionale-dedicato-alla-comunicazione-visiva-a-360_1-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nemes a Viscom: dal 21 al 23 ottobre in Fiera Milano. - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Milano, 21 Ottobre 2010 &ndash; Al via la 22&deg; edizione di Viscom Italia, la fiera internazionale di riferimento per la visual communication, in programma dal 21 al 23 ottobre in Fiera Milano Quartiere Rho. Nemes, azienda di consulenza informatica per la comunicazione e il marketing, presenter&agrave; alcune delle sue pi&ugrave; innovative soluzioni interattive a marchio Gesto, all&rsquo;interno dell&rsquo;area Digital Signage, presso il padiglione P23. L&rsquo;offerta Gesto &egrave; molteplice e completa:Continue reading...\" \/>\n<meta property=\"og:url\" content=\"\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2010-10-20T12:55:42+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/nemes-a-viscom-dal-21-al-23-ottobre-in-fiera-milano-la%80%99evento-internazionale-dedicato-alla-comunicazione-visiva-a-360_1-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/nemes-a-viscom-dal-21-al-23-ottobre-in-fiera-milano-la%80%99evento-internazionale-dedicato-alla-comunicazione-visiva-a-360_1-2\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Nemes a Viscom: dal 21 al 23 ottobre in Fiera Milano.\",\"datePublished\":\"2010-10-20T12:55:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/nemes-a-viscom-dal-21-al-23-ottobre-in-fiera-milano-la%80%99evento-internazionale-dedicato-alla-comunicazione-visiva-a-360_1-2\\\/\"},\"wordCount\":220,\"commentCount\":0,\"keywords\":[\"holpoprisma\",\"interattivit\u00e0\",\"nemes\",\"oloprisma\",\"viscom\"],\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/nemes-a-viscom-dal-21-al-23-ottobre-in-fiera-milano-la%80%99evento-internazionale-dedicato-alla-comunicazione-visiva-a-360_1-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/nemes-a-viscom-dal-21-al-23-ottobre-in-fiera-milano-la%80%99evento-internazionale-dedicato-alla-comunicazione-visiva-a-360_1-2\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/nemes-a-viscom-dal-21-al-23-ottobre-in-fiera-milano-la%80%99evento-internazionale-dedicato-alla-comunicazione-visiva-a-360_1-2\\\/\",\"name\":\"Nemes a Viscom: dal 21 al 23 ottobre in Fiera Milano. - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2010-10-20T12:55:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/nemes-a-viscom-dal-21-al-23-ottobre-in-fiera-milano-la%80%99evento-internazionale-dedicato-alla-comunicazione-visiva-a-360_1-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/nemes-a-viscom-dal-21-al-23-ottobre-in-fiera-milano-la%80%99evento-internazionale-dedicato-alla-comunicazione-visiva-a-360_1-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/comunicati-stampa\\\/eventi\\\/nemes-a-viscom-dal-21-al-23-ottobre-in-fiera-milano-la%80%99evento-internazionale-dedicato-alla-comunicazione-visiva-a-360_1-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nemes a Viscom: dal 21 al 23 ottobre in Fiera Milano.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nemes a Viscom: dal 21 al 23 ottobre in Fiera Milano. - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/nemes-a-viscom-dal-21-al-23-ottobre-in-fiera-milano-la??evento-internazionale-dedicato-alla-comunicazione-visiva-a-360_1-2\/","og_locale":"it_IT","og_type":"article","og_title":"Nemes a Viscom: dal 21 al 23 ottobre in Fiera Milano. - Article Marketing","og_description":"Milano, 21 Ottobre 2010 &ndash; Al via la 22&deg; edizione di Viscom Italia, la fiera internazionale di riferimento per la visual communication, in programma dal 21 al 23 ottobre in Fiera Milano Quartiere Rho. Nemes, azienda di consulenza informatica per la comunicazione e il marketing, presenter&agrave; alcune delle sue pi&ugrave; innovative soluzioni interattive a marchio Gesto, all&rsquo;interno dell&rsquo;area Digital Signage, presso il padiglione P23. L&rsquo;offerta Gesto &egrave; molteplice e completa:Continue reading...","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/nemes-a-viscom-dal-21-al-23-ottobre-in-fiera-milano-la??evento-internazionale-dedicato-alla-comunicazione-visiva-a-360_1-2\/","og_site_name":"Article Marketing","article_published_time":"2010-10-20T12:55:42+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/nemes-a-viscom-dal-21-al-23-ottobre-in-fiera-milano-la%80%99evento-internazionale-dedicato-alla-comunicazione-visiva-a-360_1-2\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/nemes-a-viscom-dal-21-al-23-ottobre-in-fiera-milano-la%80%99evento-internazionale-dedicato-alla-comunicazione-visiva-a-360_1-2\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Nemes a Viscom: dal 21 al 23 ottobre in Fiera Milano.","datePublished":"2010-10-20T12:55:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/nemes-a-viscom-dal-21-al-23-ottobre-in-fiera-milano-la%80%99evento-internazionale-dedicato-alla-comunicazione-visiva-a-360_1-2\/"},"wordCount":220,"commentCount":0,"keywords":["holpoprisma","interattivit\u00e0","nemes","oloprisma","viscom"],"articleSection":["Eventi"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/nemes-a-viscom-dal-21-al-23-ottobre-in-fiera-milano-la%80%99evento-internazionale-dedicato-alla-comunicazione-visiva-a-360_1-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/nemes-a-viscom-dal-21-al-23-ottobre-in-fiera-milano-la%80%99evento-internazionale-dedicato-alla-comunicazione-visiva-a-360_1-2\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/nemes-a-viscom-dal-21-al-23-ottobre-in-fiera-milano-la%80%99evento-internazionale-dedicato-alla-comunicazione-visiva-a-360_1-2\/","name":"Nemes a Viscom: dal 21 al 23 ottobre in Fiera Milano. - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2010-10-20T12:55:42+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/nemes-a-viscom-dal-21-al-23-ottobre-in-fiera-milano-la%80%99evento-internazionale-dedicato-alla-comunicazione-visiva-a-360_1-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/nemes-a-viscom-dal-21-al-23-ottobre-in-fiera-milano-la%80%99evento-internazionale-dedicato-alla-comunicazione-visiva-a-360_1-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/comunicati-stampa\/eventi\/nemes-a-viscom-dal-21-al-23-ottobre-in-fiera-milano-la%80%99evento-internazionale-dedicato-alla-comunicazione-visiva-a-360_1-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Nemes a Viscom: dal 21 al 23 ottobre in Fiera Milano."}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/8653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=8653"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/8653\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=8653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=8653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=8653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}