{"id":9013,"date":"2010-10-30T09:19:29","date_gmt":"2010-10-30T07:19:29","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/professioni-calabrese-unai-soddisfatti-per-riconoscimento-ruolo-di-rappresentativitaa%80%99-associazioni-degli-amministratori-immobiliari-2\/"},"modified":"2010-10-30T09:19:29","modified_gmt":"2010-10-30T07:19:29","slug":"professioni-calabrese-unai-soddisfatti-per-riconoscimento-ruolo-di-rappresentativitaa%80%99-associazioni-degli-amministratori-immobiliari-2","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/professioni-calabrese-unai-soddisfatti-per-riconoscimento-ruolo-di-rappresentativitaa%80%99-associazioni-degli-amministratori-immobiliari-2\/","title":{"rendered":"PROFESSIONI: CALABRESE (UNAI), SODDISFATTI PER RICONOSCIMENTO RUOLO DI RAPPRESENTATIVITA\u2019 ASSOCIAZIONI DEGLI AMMINISTRATORI IMMOBILIARI"},"content":{"rendered":"<p>Roma, 30 ottobre 2010 &#8211; &laquo;<strong>Siamo molto soddisfatti per il riconoscimento del ruolo che la nostra associazione ricopre, dal 1968, nell&rsquo;ambito condominiale<\/strong>&raquo;. Cos&igrave; Rosario Calabrese, presidente dell&#8217;UNAI (Unione Nazionale Amministratori d&#8217;immobili), esprime la sua soddisfazione per il ricevimento del Decreto di Annotazione a seguito della conclusione positiva dell&#8217;istruttoria presso il ministero della Giustizia, in attuazione dell&rsquo;art. 26 del DLgs 206\/2007. <br \/>Il Decreto, a firma del ministro Alfano, consegnato ad UNAI, sancisce l&#8217;annotazione, nell&rsquo;apposito registro, tenuto presso il ministero, delle associazioni pi&ugrave; rappresentative, a livello nazionale, delle categorie professionali non riconosciute, ai fini della elaborazione di proposte, in materia di piattaforme comuni, per l&rsquo;esercizio delle attivit&agrave; professionali, cos&igrave; come previsto dalla Direttiva comunitaria 2005\/36\/CE..<br \/>&laquo;Il Decreto di annotazione nel registro ci &egrave; stato consegnato oggi, anche se firmato dal Ministro in data 4 ottobre e bench&eacute; la nostra pratica fu la prima, fra quelle della ns. categoria, ad ottenere parere positivo da parte del Ministero della Giustizia&raquo; sottolinea Calabrese. <br \/>&laquo;Sono contento che la categoria degli amministratori di condominio, con ben tre associazioni annotate, sia stata fra le prime a raggiungere questo importante traguardo, perch&eacute; esso rappresenta un passo fondamentale verso la presa d&rsquo;atto, da parte della opinione pubblica e delle istituzioni, del ruolo determinante assunto dagli amministratori immobiliari nel contesto economico nazionale&raquo;, dichiara Calabrese, &laquo;intanto, appena ce ne sar&agrave; data l&rsquo;opportunit&agrave;, porteremo la nostra voce e il nostro modo di intendere la figura professionale dell&rsquo;amministratore d&rsquo;immobili, nel contesto europeo, dal momento che l&rsquo;annotazione presso il registro tenuto dal Ministero della Giustizia consentir&agrave;, alle realt&agrave; accreditate, di partecipare ai tavoli di trattativa, e alle conferenze di servizi, i cui si proceder&agrave; all&#8217;individuazione delle competenze professionali e delle specificit&agrave; operative nell&rsquo;ambito dell&#8217;Unione Europea. In pratica, nel nostro settore si avr&agrave; la possibilit&agrave; di decidere quali parametri definiscano l&#8217;amministratore d&#8217;immobili in ambito comunitario&raquo;. <br \/>&laquo;Questo importante risultato raggiunto non distoglier&agrave; la nostra attenzione, ed il ns. impegno, dal nostro obiettivo primario che &egrave; il riconoscimento giuridico della categoria&raquo; ha concluso il presidente Calabrese &laquo;l&rsquo;Albo Professionale &egrave;, e resta, il nostro obiettivo primario, sicch&eacute; UNAI continuer&agrave; le sue battaglie sindacali ed il suo impegno per il raggiungimento di questo traguardo. La partecipazione alle Piattaforme Comuni ci consentir&agrave; di far sentire la nostra voce di categoria anche da quella, ed in quella, prestigiosa sede&raquo;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Roma, 30 ottobre 2010 &#8211; \u00abSiamo molto soddisfatti per il riconoscimento del ruolo che la nostra associazione ricopre, dal 1968, nell\u2019ambito condominiale\u00bb. Cos\u00ec Rosario Calabrese, presidente dell&#8217;UNAI (Unione Nazionale Amministratori d&#8217;immobili), esprime la sua soddisfazione per il ricevimento del Decreto di Annotazione a seguito della conclusione positiva dell&#8217;istruttoria presso il ministero della Giustizia, in attuazione dell\u2019art. 26 del DLgs 206\/2007.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[429],"tags":[12253,12250,18984,18983,18982],"class_list":["post-9013","post","type-post","status-publish","format-standard","hentry","category-professionisti","tag-amministratori","tag-condominio","tag-decreto","tag-rosario-calabrese","tag-unai"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PROFESSIONI: CALABRESE (UNAI), SODDISFATTI PER RICONOSCIMENTO RUOLO DI RAPPRESENTATIVITA\u2019 ASSOCIAZIONI DEGLI AMMINISTRATORI IMMOBILIARI - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/professioni-calabrese-unai-soddisfatti-per-riconoscimento-ruolo-di-rappresentativitaa??-associazioni-degli-amministratori-immobiliari-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PROFESSIONI: CALABRESE (UNAI), SODDISFATTI PER RICONOSCIMENTO RUOLO DI RAPPRESENTATIVITA\u2019 ASSOCIAZIONI DEGLI AMMINISTRATORI IMMOBILIARI - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Roma, 30 ottobre 2010 - \u00abSiamo molto soddisfatti per il riconoscimento del ruolo che la nostra associazione ricopre, dal 1968, nell\u2019ambito condominiale\u00bb. Cos\u00ec Rosario Calabrese, presidente dell&#039;UNAI (Unione Nazionale Amministratori d&#039;immobili), esprime la sua soddisfazione per il ricevimento del Decreto di Annotazione a seguito della conclusione positiva dell&#039;istruttoria presso il ministero della Giustizia, in attuazione dell\u2019art. 26 del DLgs 206\/2007.\" \/>\n<meta property=\"og:url\" content=\"\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2010-10-30T07:19:29+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/professioni-calabrese-unai-soddisfatti-per-riconoscimento-ruolo-di-rappresentativitaa%80%99-associazioni-degli-amministratori-immobiliari-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/professioni-calabrese-unai-soddisfatti-per-riconoscimento-ruolo-di-rappresentativitaa%80%99-associazioni-degli-amministratori-immobiliari-2\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"PROFESSIONI: CALABRESE (UNAI), SODDISFATTI PER RICONOSCIMENTO RUOLO DI RAPPRESENTATIVITA\u2019 ASSOCIAZIONI DEGLI AMMINISTRATORI IMMOBILIARI\",\"datePublished\":\"2010-10-30T07:19:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/professioni-calabrese-unai-soddisfatti-per-riconoscimento-ruolo-di-rappresentativitaa%80%99-associazioni-degli-amministratori-immobiliari-2\\\/\"},\"wordCount\":436,\"commentCount\":0,\"keywords\":[\"amministratori\",\"condominio\",\"Decreto\",\"Rosario Calabrese\",\"UNAI\"],\"articleSection\":[\"Professionisti\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/professioni-calabrese-unai-soddisfatti-per-riconoscimento-ruolo-di-rappresentativitaa%80%99-associazioni-degli-amministratori-immobiliari-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/professioni-calabrese-unai-soddisfatti-per-riconoscimento-ruolo-di-rappresentativitaa%80%99-associazioni-degli-amministratori-immobiliari-2\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/professioni-calabrese-unai-soddisfatti-per-riconoscimento-ruolo-di-rappresentativitaa%80%99-associazioni-degli-amministratori-immobiliari-2\\\/\",\"name\":\"PROFESSIONI: CALABRESE (UNAI), SODDISFATTI PER RICONOSCIMENTO RUOLO DI RAPPRESENTATIVITA\u2019 ASSOCIAZIONI DEGLI AMMINISTRATORI IMMOBILIARI - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2010-10-30T07:19:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/professioni-calabrese-unai-soddisfatti-per-riconoscimento-ruolo-di-rappresentativitaa%80%99-associazioni-degli-amministratori-immobiliari-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/professioni-calabrese-unai-soddisfatti-per-riconoscimento-ruolo-di-rappresentativitaa%80%99-associazioni-degli-amministratori-immobiliari-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/economia-e-lavoro\\\/professionisti\\\/professioni-calabrese-unai-soddisfatti-per-riconoscimento-ruolo-di-rappresentativitaa%80%99-associazioni-degli-amministratori-immobiliari-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PROFESSIONI: CALABRESE (UNAI), SODDISFATTI PER RICONOSCIMENTO RUOLO DI RAPPRESENTATIVITA\u2019 ASSOCIAZIONI DEGLI AMMINISTRATORI IMMOBILIARI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PROFESSIONI: CALABRESE (UNAI), SODDISFATTI PER RICONOSCIMENTO RUOLO DI RAPPRESENTATIVITA\u2019 ASSOCIAZIONI DEGLI AMMINISTRATORI IMMOBILIARI - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/professioni-calabrese-unai-soddisfatti-per-riconoscimento-ruolo-di-rappresentativitaa??-associazioni-degli-amministratori-immobiliari-2\/","og_locale":"it_IT","og_type":"article","og_title":"PROFESSIONI: CALABRESE (UNAI), SODDISFATTI PER RICONOSCIMENTO RUOLO DI RAPPRESENTATIVITA\u2019 ASSOCIAZIONI DEGLI AMMINISTRATORI IMMOBILIARI - Article Marketing","og_description":"Roma, 30 ottobre 2010 - \u00abSiamo molto soddisfatti per il riconoscimento del ruolo che la nostra associazione ricopre, dal 1968, nell\u2019ambito condominiale\u00bb. Cos\u00ec Rosario Calabrese, presidente dell'UNAI (Unione Nazionale Amministratori d'immobili), esprime la sua soddisfazione per il ricevimento del Decreto di Annotazione a seguito della conclusione positiva dell'istruttoria presso il ministero della Giustizia, in attuazione dell\u2019art. 26 del DLgs 206\/2007.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/professioni-calabrese-unai-soddisfatti-per-riconoscimento-ruolo-di-rappresentativitaa??-associazioni-degli-amministratori-immobiliari-2\/","og_site_name":"Article Marketing","article_published_time":"2010-10-30T07:19:29+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/professioni-calabrese-unai-soddisfatti-per-riconoscimento-ruolo-di-rappresentativitaa%80%99-associazioni-degli-amministratori-immobiliari-2\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/professioni-calabrese-unai-soddisfatti-per-riconoscimento-ruolo-di-rappresentativitaa%80%99-associazioni-degli-amministratori-immobiliari-2\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"PROFESSIONI: CALABRESE (UNAI), SODDISFATTI PER RICONOSCIMENTO RUOLO DI RAPPRESENTATIVITA\u2019 ASSOCIAZIONI DEGLI AMMINISTRATORI IMMOBILIARI","datePublished":"2010-10-30T07:19:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/professioni-calabrese-unai-soddisfatti-per-riconoscimento-ruolo-di-rappresentativitaa%80%99-associazioni-degli-amministratori-immobiliari-2\/"},"wordCount":436,"commentCount":0,"keywords":["amministratori","condominio","Decreto","Rosario Calabrese","UNAI"],"articleSection":["Professionisti"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/professioni-calabrese-unai-soddisfatti-per-riconoscimento-ruolo-di-rappresentativitaa%80%99-associazioni-degli-amministratori-immobiliari-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/professioni-calabrese-unai-soddisfatti-per-riconoscimento-ruolo-di-rappresentativitaa%80%99-associazioni-degli-amministratori-immobiliari-2\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/professioni-calabrese-unai-soddisfatti-per-riconoscimento-ruolo-di-rappresentativitaa%80%99-associazioni-degli-amministratori-immobiliari-2\/","name":"PROFESSIONI: CALABRESE (UNAI), SODDISFATTI PER RICONOSCIMENTO RUOLO DI RAPPRESENTATIVITA\u2019 ASSOCIAZIONI DEGLI AMMINISTRATORI IMMOBILIARI - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2010-10-30T07:19:29+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/professioni-calabrese-unai-soddisfatti-per-riconoscimento-ruolo-di-rappresentativitaa%80%99-associazioni-degli-amministratori-immobiliari-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/professioni-calabrese-unai-soddisfatti-per-riconoscimento-ruolo-di-rappresentativitaa%80%99-associazioni-degli-amministratori-immobiliari-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/economia-e-lavoro\/professionisti\/professioni-calabrese-unai-soddisfatti-per-riconoscimento-ruolo-di-rappresentativitaa%80%99-associazioni-degli-amministratori-immobiliari-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"PROFESSIONI: CALABRESE (UNAI), SODDISFATTI PER RICONOSCIMENTO RUOLO DI RAPPRESENTATIVITA\u2019 ASSOCIAZIONI DEGLI AMMINISTRATORI IMMOBILIARI"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/9013","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=9013"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/9013\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=9013"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=9013"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=9013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}