{"id":924,"date":"2008-11-20T16:04:40","date_gmt":"2008-11-20T15:04:40","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/lo-snowboard-sul-grande-schermo\/"},"modified":"2008-11-20T16:04:40","modified_gmt":"2008-11-20T15:04:40","slug":"lo-snowboard-sul-grande-schermo","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/sport\/lo-snowboard-sul-grande-schermo\/","title":{"rendered":"Lo snowboard sul grande schermo"},"content":{"rendered":"<p>Nuova Zelanda, Alaska, Canada, Jackson Hole, Park City, Monaco, Tokyo, San Francisco, Mammoth. Ecco i luoghi in cui, in oltre 2 anni di riprese, Travis Rice ha radunato una crew di rider senza precedenti per realizzare quello che Curg Morgan, presidente della casa di produzione Brain Farm, ha definito &#8220;un film di snowboard epico che incontra il Pianeta Terra&#8221;. Continua Morgan: \u201cIl film \u00e8 visulamente stimolante e mette il pubblico davanti al pi\u00f9 progressivo snowboarding della storia affiancando delle immagini di Natura da far venire i brividi.\u201d<\/p>\n<p>300 ore di riprese e 200 ore di elicottero vengono riassunte in 55 minuti di immagini al cardiopalma, accompagnate da una colonna sonora in grado di farti battere la cassa toracica.<\/p>\n<p>TITA \u00e8 il primo <a href=\"http:\/\/www.gsteam.biz\">snowboard<\/a> movie professionale interamente realizzato in HD: telecamere Hi Def, 35mm e Super16 sono in grado di testimoniare alla perfezione l&#8217;intraprendenza di un rider geniale come Travis Rice che, all&#8217;interno di paesaggi mozzafiato, riesce a realizzare nuovi trick (tra cui un double backside rodeo 1080) da riprendere con tecniche di ultima generazione.<\/p>\n<p>\u201cAbbiamo messo in questa produzione tutto quello che era umanamente possibile\u201d ha detto Travis Rice, Pro-Snowboarder di fama mondiale e Co-Proprietario della casa di produzione Brain Farm. \u201cQuiksilver e Red Bull sono salite a bordo e ci hanno aiutato incredibilmente nel raggiungimento di standard tecnici di produzione che valorizzassero ancora pi\u00f9 la progressione sportiva che stavamo inseguendo.\u201d<\/p>\n<p>La protagonista indiscussa di TITA \u00e8 la neve. Non c&#8217;era rider abbastanza talentuoso, pazzo o ispirato che potesse rubarle il primato. Distese di neve bianchissima, immacolata, eterna, soffice, corposa e leggera, ammaliante, imponente e possente, corposa, brillante, liscia. Lasciate sul comodino la sicurezza e la razionalit\u00e0, i fortunati riders si sono riempiti le tasche di incoscienza, spensieratezza, amuleti porta fortuna, concentrato purissimo di follia ed elisir di lunga vita rubati agli sciamani e&#8230;ne avevano bisogno.<\/p>\n<p>Arrivati sul picco della montagna ecco che, con l&#8217;innocenza di un bambino, i pionieri si lanciano sui pendii scoscesi (pendenza variabile da un minimo di 89% a un massimo di 90%). Spesso non toccano nemmeno la neve. Volano. Rimbalzano. Atterrano. Sprofondano. Sfiorano. Da arroganti invasori di luoghi sacri, si trasformano in dolci poeti di suoni, artisti di linee e simmetrie. Nulla sembra essere lasciato al caso, sembrano perfettamente padroni del loro corpo, della loro mente e della loro tavola&#8230;tutto sotto controllo, fino a quando Madama Neve stanca della loro tracotanza decide di mettere in chiaro le regole. Travolti da slavine e valanghe, arrivano in fondo. Qualche macchia rossa rovina quello splendore: il naso non ce l&#8217;ha fatta e i denti&#8230;a che servono? Ma \u00e8 il prezzo da pagare per viaggio in Paradiso. Ora sono pronti per rischiare la pelle di nuovo ad altre latitudini.<\/p>\n<p> Tramonti mozzafiato con colori unici da non essere neppure compresi nell&#8217;iride. La neve, dimostrando tutta la sua magnanimit\u00e0, ha mostrato che dire bianco non \u00e8 sufficiente: bianco latte, bianco panna, bianco ghiaccio, bianco brillante, bianco acceso, bianco sporco, bianco opaco&#8230;ogni sfumatura possibile \u00e8 stata catturata dell&#8217;obiettivo. Vasti orizzonti, cieli ben pi\u00f9 larghi di quelli a cui siamo abituati. Incantevole.<\/p>\n<p>Basta cercare. E a quanto pare la ricerca giunge al termine in Alaska. La meta definitiva. L&#8217;apogeo. Il punto di non ritorno. A quanto dicono, una volta posata la tavola in queste lande, non c&#8217;\u00e8 piu&#8217; via d&#8217;uscita dalle dolci catene di Madama Neve.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Come ci si sente a stare in una sala cinematografica nel centro di Milano con alcuni tra i pi\u00f9 grandi rider d&#8217;Italia e del mondo come Travis Rice, Hampus Mosesson, Giacomo Kratter e Manuel Pietropoli? Incredulit\u00e0.<\/p>\n<p>Cosa si prova a vedere Travis Rice &#038; Co. in azione nei luoghi pi\u00f9 incontaminati della terra in &#8220;That&#8217;s it, That&#8217;s all.&#8221;? Estasi.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[10],"tags":[3189,3188],"class_list":["post-924","post","type-post","status-publish","format-standard","hentry","category-sport","tag-movies","tag-snowboard"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lo snowboard sul grande schermo - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/sport\/lo-snowboard-sul-grande-schermo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lo snowboard sul grande schermo - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Come ci si sente a stare in una sala cinematografica nel centro di Milano con alcuni tra i pi\u00f9 grandi rider d&#039;Italia e del mondo come Travis Rice, Hampus Mosesson, Giacomo Kratter e Manuel Pietropoli? Incredulit\u00e0. Cosa si prova a vedere Travis Rice &amp; Co. in azione nei luoghi pi\u00f9 incontaminati della terra in &quot;That&#039;s it, That&#039;s all.&quot;? Estasi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/sport\/lo-snowboard-sul-grande-schermo\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2008-11-20T15:04:40+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/sport\\\/lo-snowboard-sul-grande-schermo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/sport\\\/lo-snowboard-sul-grande-schermo\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Lo snowboard sul grande schermo\",\"datePublished\":\"2008-11-20T15:04:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/sport\\\/lo-snowboard-sul-grande-schermo\\\/\"},\"wordCount\":549,\"commentCount\":0,\"keywords\":[\"movies\",\"snowboard\"],\"articleSection\":[\"Sport\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/sport\\\/lo-snowboard-sul-grande-schermo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/sport\\\/lo-snowboard-sul-grande-schermo\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/sport\\\/lo-snowboard-sul-grande-schermo\\\/\",\"name\":\"Lo snowboard sul grande schermo - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2008-11-20T15:04:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/sport\\\/lo-snowboard-sul-grande-schermo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/sport\\\/lo-snowboard-sul-grande-schermo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/salute-e-benessere\\\/sport\\\/lo-snowboard-sul-grande-schermo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lo snowboard sul grande schermo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lo snowboard sul grande schermo - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/sport\/lo-snowboard-sul-grande-schermo\/","og_locale":"it_IT","og_type":"article","og_title":"Lo snowboard sul grande schermo - Article Marketing","og_description":"Come ci si sente a stare in una sala cinematografica nel centro di Milano con alcuni tra i pi\u00f9 grandi rider d'Italia e del mondo come Travis Rice, Hampus Mosesson, Giacomo Kratter e Manuel Pietropoli? Incredulit\u00e0. Cosa si prova a vedere Travis Rice & Co. in azione nei luoghi pi\u00f9 incontaminati della terra in \"That's it, That's all.\"? Estasi.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/sport\/lo-snowboard-sul-grande-schermo\/","og_site_name":"Article Marketing","article_published_time":"2008-11-20T15:04:40+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/sport\/lo-snowboard-sul-grande-schermo\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/sport\/lo-snowboard-sul-grande-schermo\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Lo snowboard sul grande schermo","datePublished":"2008-11-20T15:04:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/sport\/lo-snowboard-sul-grande-schermo\/"},"wordCount":549,"commentCount":0,"keywords":["movies","snowboard"],"articleSection":["Sport"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/sport\/lo-snowboard-sul-grande-schermo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/sport\/lo-snowboard-sul-grande-schermo\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/sport\/lo-snowboard-sul-grande-schermo\/","name":"Lo snowboard sul grande schermo - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2008-11-20T15:04:40+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/sport\/lo-snowboard-sul-grande-schermo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/sport\/lo-snowboard-sul-grande-schermo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/salute-e-benessere\/sport\/lo-snowboard-sul-grande-schermo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Lo snowboard sul grande schermo"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=924"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/924\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=924"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=924"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}