{"id":9880,"date":"2010-11-25T10:46:34","date_gmt":"2010-11-25T09:46:34","guid":{"rendered":"http:\/\/www.article-marketing.eu\/comunicati\/senza-categoria\/replica-sistemi-lancia-connect2arc\/"},"modified":"2010-11-25T10:46:34","modified_gmt":"2010-11-25T09:46:34","slug":"replica-sistemi-lancia-connect2arc","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/replica-sistemi-lancia-connect2arc\/","title":{"rendered":"Replica Sistemi lancia CONNECT2ARC"},"content":{"rendered":"<p>25\/11\/2010 Curtatone (MN) &ndash; Secondo quanto stabilito dal Regolamento (CE) n. 684\/2009 del 24\/07\/2009 (GU L n. 197 del 29\/7\/2009 ), dal 1&deg; gennaio 2011 il <strong>DAA<\/strong> cartaceo (<strong>Documento amministrativo di accompagnamento<\/strong>) sar&agrave; sostituito dal <strong>DAA telematico (e-DA)<\/strong> e tutti i prodotti soggetti ad accisa in regime sospensivo in ambito Comunitario dovranno essere autorizzati dal servizio telematico dell&#8217;Agenzia delle Dogane. Il Reg. n. 684\/2009, oltre a disciplinare le varie casistiche e gli operatori interessati nelle transazioni di prodotti in sospensione di accisa, detta le modalit&agrave; e le caratteristiche del documento elettronico (E-DA) e riporta le caratteristiche dei campi, nonch&eacute; le condizioni, le regole e le tabelle utili alla costruzione del tracciato record che costituisce il documento elettronico E-DA.<\/p>\n<p>In risposta alle nuove esigenze informatiche che ne sono scaturite, <strong>Replica Sistemi<\/strong> ha sviluppato <strong>Connect2ARC<\/strong>, il modulo che consente di gestire in modo semplice ed immediato la ricezione telematica dei <strong>DAA<\/strong> all&rsquo;<strong>Agenzia delle Dogane<\/strong>. <\/p>\n<p>Il sistema consente una concreta riduzione dei tempi e degli errori legati alle complesse procedure necessarie per adempiere al nuovo modo operativo richiesto.<br \/><strong>Maurizio Gallesi<\/strong>, <em>DFDDogana Project Manager Replica Sistemi<\/em>, spiega: &#8220;Senza Connect2ARC l&#8217;operatore deve collegarsi al sito web dell&#8217;Agenzia delle Dogane, scaricare il file xml relativo all&#8217;ARC di ciascun prodotto, inserire le credenziali di accesso, inserire il codice del deposito, navigare tra i men&ugrave;, inserire i filtri di ricerca, premere il link per scaricare il file confermare il salvataggio&#8230; Operazioni manuali e molto lunghe con conseguenti perdite di tempo e di denaro, soprattutto nei depositi che hanno molti DAA in ingresso. <strong>Con Connect2ARC all&#8217;operatore basta un click <\/strong>per recuperare i dati necessari dal portale dell&rsquo;Agenzia delle Dogane e svolgere in automatico le operazioni &#8221; E&#8217; una <strong>soluzione autoinstallante<\/strong> ed integrabile con il verticale <strong>DFDDogana<\/strong> o il proprio applicativo ERP in modalit&agrave; Client. &ldquo;La soluzione &egrave; subito disponibile per tutte le aziende che gestiscono un magazzino doganale. &#8211; afferma <strong>Ferruccio Montresor<\/strong>, General Manager Replica Sistemi &#8211; In questa fase di lancio, nei mesi di novembre e dicembre, abbiamo previsto un&#8217;offerta lancio promozionale davvero interessante che i nostri clienti e i prospect stanno valutando con interesse perch&egrave; consente loro di risparmiare tempi e costi con un investimento davvero conveniente.&#8221; <strong>Claudio Caprari<\/strong>, <em>Vice President Replica Sistemi<\/em>, esprime soddisfatto: &ldquo;<em>Questo nuovo modulo conferma il nostro costante impegno nello sviluppo di applicazioni software innovative, che concretamente rispondano alle esigenze dei nostri clienti che operano nel mondo della logistica e dei trasporti<\/em>&#8220;. Sul sito web di Replica Sistemi &egrave; disponibile anche una video-demo cliccando sul link: <a href=\"http:\/\/www.replica.it\/it\/doc-s-38-203-1225-77-1.aspx\">http:\/\/www.replica.it\/it\/doc-s-38-203-1225-77-1.aspx<\/a> Per informazioni tecniche e commerciali pi&ugrave; dettagliate &egrave; possibile contattare Replica Sistemi al numero di telefono +39 0376 346411 begin_of_the_skype_highlighting +39 0376 346411 end_of_the_skype_highlighting &#8211; o inviare una mail all&#8217;indirizzo michele.galletto@replica.it. *** <em>Replica Sistemi &egrave; una societ&agrave; specializzata nella progettazione e nell&rsquo;implementazione di applicazioni software integrate tra loro e interfacciate con le pi&ugrave; evolute tecnologie Voice, RFID e Geolocalizzazione Satellitare. In particolare sviluppa soluzioni per la logistica (WMS &ndash; Warehouse Management Systems \/ TMS &#8211; Transportation Management System) e per il controllo della supply chain seguendo il modello delle medie aziende italiane di successo: alta qualit&agrave;, grande specializzazione, passione, creativit&agrave;.<\/em> <em>&Egrave; un&rsquo;azienda finanziariamente solida con un portafoglio clienti in continua espansione, scelta da oltre 1.000 aziende in Italia e all&rsquo;estero per la professionalit&agrave; e l&rsquo;eccellente assistenza garantita nello spazio e nel tempo. Grazie al suo giovane e motivato Staff di persone, Replica Sistemi &egrave; in grado di supportare tutte le aziende che strategicamente internazionalizzano all&#8217;estero la propria attivit&agrave; e che necessitano di soluzioni innovative.<\/em> <em>Fanno parte di Replica Sistemi anche le aziende Replica Development, che garantisce il continuo sviluppo e aggiornamento dell&rsquo;ERP ERGO, e RECAP, partner Microsoft Dynamics NAV, che ha avviato un processo strategico per consentire una perfetta integrazione dei prodotti Replica Sistemi con l&#8217;ERP Dynamics Nav.<\/em> <em>Replica Sistemi condivide con i propri Clienti e Partners: Esperienza, Know How, Affidabilit&agrave;. Per oltre trent&rsquo;anni, sono state implementate applicazioni di logistica e sistemi gestionali. Il suo Staff Tecnico vanta la conoscenza e la pratica necessaria per organizzare i flussi informativi nei diversi settori e segmenti di mercato. I<\/em> <em>l costante dialogo con tutti gli stakeholders permette di capire ed anticipare le richieste del mercato e di migliorare i prodotti in modo continuativo.<\/em> <em>Replica Sistemi &egrave; un punto di riferimento solido, coerente e competente per tutti coloro che si affidano alle sue soluzioni.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Replica Sistemi lancia CONNECT2ARC, il modulo informatico che consente di gestire in modo semplice ed immediato la ricezione telematica dei DAA dall\u2019Agenzia delle Dogane.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[123],"tags":[19763,19764,15047,19765,19766,2521,19767],"class_list":["post-9880","post","type-post","status-publish","format-standard","hentry","category-software","tag-agenzia-delle-dogane","tag-daa-elettronico","tag-replica-sistemi","tag-software-gestione-logistica-magazzino-doganale","tag-spedizioni-internazionali","tag-supply-chain","tag-trasporto-merci-extra-cee"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Replica Sistemi lancia CONNECT2ARC - Article Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/replica-sistemi-lancia-connect2arc\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Replica Sistemi lancia CONNECT2ARC - Article Marketing\" \/>\n<meta property=\"og:description\" content=\"Replica Sistemi lancia CONNECT2ARC, il modulo informatico che consente di gestire in modo semplice ed immediato la ricezione telematica dei DAA dall\u2019Agenzia delle Dogane.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/replica-sistemi-lancia-connect2arc\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2010-11-25T09:46:34+00:00\" \/>\n<meta name=\"author\" content=\"Redazione Comunicati Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Comunicati Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/replica-sistemi-lancia-connect2arc\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/replica-sistemi-lancia-connect2arc\\\/\"},\"author\":{\"name\":\"Redazione Comunicati Stampa\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"headline\":\"Replica Sistemi lancia CONNECT2ARC\",\"datePublished\":\"2010-11-25T09:46:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/replica-sistemi-lancia-connect2arc\\\/\"},\"wordCount\":758,\"commentCount\":0,\"keywords\":[\"Agenzia delle Dogane\",\"DAA elettronico\",\"Replica Sistemi\",\"software gestione logistica magazzino doganale\",\"spedizioni internazionali\",\"supply chain\",\"trasporto merci extra CEE\"],\"articleSection\":[\"Software\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/replica-sistemi-lancia-connect2arc\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/replica-sistemi-lancia-connect2arc\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/replica-sistemi-lancia-connect2arc\\\/\",\"name\":\"Replica Sistemi lancia CONNECT2ARC - Article Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\"},\"datePublished\":\"2010-11-25T09:46:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/replica-sistemi-lancia-connect2arc\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/replica-sistemi-lancia-connect2arc\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/computer\\\/software\\\/replica-sistemi-lancia-connect2arc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Replica Sistemi lancia CONNECT2ARC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/#\\\/schema\\\/person\\\/44372e4d4d0fa797b18e03ed1ace9017\",\"name\":\"Redazione Comunicati Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g\",\"caption\":\"Redazione Comunicati Stampa\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicati\\\/author\\\/redazione-comunicati-stampa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Replica Sistemi lancia CONNECT2ARC - Article Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/replica-sistemi-lancia-connect2arc\/","og_locale":"it_IT","og_type":"article","og_title":"Replica Sistemi lancia CONNECT2ARC - Article Marketing","og_description":"Replica Sistemi lancia CONNECT2ARC, il modulo informatico che consente di gestire in modo semplice ed immediato la ricezione telematica dei DAA dall\u2019Agenzia delle Dogane.","og_url":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/replica-sistemi-lancia-connect2arc\/","og_site_name":"Article Marketing","article_published_time":"2010-11-25T09:46:34+00:00","author":"Redazione Comunicati Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione Comunicati Stampa","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/replica-sistemi-lancia-connect2arc\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/replica-sistemi-lancia-connect2arc\/"},"author":{"name":"Redazione Comunicati Stampa","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"headline":"Replica Sistemi lancia CONNECT2ARC","datePublished":"2010-11-25T09:46:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/replica-sistemi-lancia-connect2arc\/"},"wordCount":758,"commentCount":0,"keywords":["Agenzia delle Dogane","DAA elettronico","Replica Sistemi","software gestione logistica magazzino doganale","spedizioni internazionali","supply chain","trasporto merci extra CEE"],"articleSection":["Software"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/replica-sistemi-lancia-connect2arc\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/replica-sistemi-lancia-connect2arc\/","url":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/replica-sistemi-lancia-connect2arc\/","name":"Replica Sistemi lancia CONNECT2ARC - Article Marketing","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website"},"datePublished":"2010-11-25T09:46:34+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/replica-sistemi-lancia-connect2arc\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/replica-sistemi-lancia-connect2arc\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicati\/computer\/software\/replica-sistemi-lancia-connect2arc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Replica Sistemi lancia CONNECT2ARC"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#website","url":"https:\/\/www.article-marketing.eu\/comunicati\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicati\/#\/schema\/person\/44372e4d4d0fa797b18e03ed1ace9017","name":"Redazione Comunicati Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50e5c6421d3072f42e7ace803501602c60d75233d34e29fd05feb91c8760b792?s=96&d=mm&r=g","caption":"Redazione Comunicati Stampa"},"url":"https:\/\/www.article-marketing.eu\/comunicati\/author\/redazione-comunicati-stampa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/9880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=9880"}],"version-history":[{"count":0,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/posts\/9880\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=9880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=9880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=9880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}