{"id":32436,"date":"2026-05-08T21:01:30","date_gmt":"2026-05-08T19:01:30","guid":{"rendered":"https:\/\/www.article-marketing.eu\/comunicatistampa\/?p=32436"},"modified":"2026-05-08T21:01:30","modified_gmt":"2026-05-08T19:01:30","slug":"denaro-che-si-sposta-con-la-geopolitica-gli-usa-tirano-molto-di-meno","status":"publish","type":"post","link":"https:\/\/www.article-marketing.eu\/comunicatistampa\/denaro-che-si-sposta-con-la-geopolitica-gli-usa-tirano-molto-di-meno\/","title":{"rendered":"Denaro che si sposta con la\u00a0Geopolitica: gli USA tirano molto di meno"},"content":{"rendered":"<p>Con lo scoppio del <strong>conflitto in Medio Oriente lo scenario sui mercati \u00e8 cambiato<\/strong>. Il mercato dei capitali si adegua al periodo incerto, <strong>ridisegnando l&#8217;allocazione del denaro<\/strong> attraverso le varie asset class e i diversi territori. Le dinamiche pi\u00f9 evidenti si possono osservare riguardano la maggiore cautela verso gli USA, che tirano decisamente meno che in passato.<\/p>\n<h2>Gli spostamenti dei flussi di denaro<\/h2>\n<p><img decoding=\"async\" style=\"float: right; height: 162px; margin: 11px; width: 309px;\" src=\"https:\/\/economia-impresa.info\/wp-content\/uploads\/2024\/04\/denaro_militare_spesa1-630x330.jpg\" alt=\"denaro\" \/>Il modo migliore per cogliere certi cambiamenti \u00e8 guardare i numeri. Da essi emerge che c&#8217;\u00e8 <strong>un forte recupero da parte dei mercati emergenti e asiatici<\/strong>, a forte di una maggiore cautela verso il tradizionale primato di Wall Street. <strong>I flussi di denaro verso gli Stati Uniti si stanno riducendo<\/strong>, e i mercati a stelle e strisce hanno faticato ad attirare nuova liquidit\u00e0.<\/p>\n<p>Basta pensare che se lo scorso anno, su 100 dollari di denaro investiti ben 45 erano diretti verso gli USA, mentre in questo primo spicchio di anno tale quota si ridotta a 26. Tale crollo <strong>segna la fine del dominio assoluto americano<\/strong> che era cominciato dopo la grande <a href=\"https:\/\/economia-impresa.info\/crisi-finanziaria-2007-2009-spiegata-passo-per-passo\/\" target=\"_blank\" rel=\"noopener\">crisi finanziaria del 2008-2009<\/a>.<\/p>\n<h2>I guadagni dei mercati asiatici ed emergenti<\/h2>\n<p>Il contesto internazionale sta <strong>spingendo i mercati asiatici e quelli emergenti<\/strong>. La finanza globale infatti ha premiato questi mercati con guadagni che oscillano tra il 14% e il 20%. Il motivo di questa rotazione dei capitali non \u00e8 soltanto <strong>la ricerca di un miglior rendimento<\/strong>, ma anche <strong>la migliore gestione del rischio<\/strong>. A causa delle tensioni internazionali, molte nazioni stanno cercando di <strong>ridurre la propria esposizione al Dollaro<\/strong>.<\/p>\n<p>Questo trend ad esempio \u00e8 uno dei fattori che sostiene la corsa dell&#8217;oro, dal momento che le banche centrali stanno aumentando le proprie riserve auree da diverso tempo. Allo stesso tempo cominciano a sentirsi i primi scricchiolii nell&#8217;entusiasmo che ha accompagnato la corsa dei magnifici 7 dell&#8217;intelligenza artificiale negli ultimi trimestre.<\/p>\n<h2>La variabile guerra<\/h2>\n<p>\u00c8 chiaro che questo scenario rappresenta una tendenza che il mondo della finanza sta vivendo negli ultimi tempi. Ma gli <a href=\"https:\/\/www.universoforex.it\/news\/2004\/indicatori_di_momentum_migliori_i_piu_utilizzati_e_l_039_errore_da_non_commettere.html\" target=\"_blank\" rel=\"noopener\">indicatori di momentum<\/a> per loro stessa definizione possono cambiare rotta rapidamente. Lo shock legato alla <strong>guerra in Medio Oriente potrebbe di nuovo modificare la rotta dei mercati<\/strong>. Abbiamo visto ad esempio un ritorno di fiamma per il dollaro nella sua veste di bene rifugio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con lo scoppio del conflitto in Medio Oriente lo scenario sui mercati \u00e8 cambiato. Il mercato dei capitali si adegua al periodo incerto, ridisegnando l&#8217;allocazione del denaro attraverso le varie asset class e i diversi territori. Le dinamiche pi\u00f9 evidenti si possono osservare riguardano la maggiore cautela verso gli USA, che tirano decisamente meno che in passato. Gli spostamenti dei flussi di denaro Il modo migliore per cogliere certi cambiamenti<\/p>\n<p><a class=\"continue-reading\" href=\"https:\/\/www.article-marketing.eu\/comunicatistampa\/denaro-che-si-sposta-con-la-geopolitica-gli-usa-tirano-molto-di-meno\/\">Continue reading&#8230;<\/a><\/p>\n","protected":false},"author":7116,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[386],"tags":[11334,864,10657],"class_list":["post-32436","post","type-post","status-publish","format-standard","hentry","category-economia-e-lavoro","tag-crisi-finanziaria-del-2008-2009","tag-denaro","tag-indicatori-di-momentum"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Denaro che si sposta con la\u00a0Geopolitica: gli USA tirano molto di meno<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.article-marketing.eu\/comunicatistampa\/denaro-che-si-sposta-con-la-geopolitica-gli-usa-tirano-molto-di-meno\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Denaro che si sposta con la\u00a0Geopolitica: gli USA tirano molto di meno\" \/>\n<meta property=\"og:description\" content=\"Con lo scoppio del conflitto in Medio Oriente lo scenario sui mercati \u00e8 cambiato. Il mercato dei capitali si adegua al periodo incerto, ridisegnando l&#8217;allocazione del denaro attraverso le varie asset class e i diversi territori. Le dinamiche pi\u00f9 evidenti si possono osservare riguardano la maggiore cautela verso gli USA, che tirano decisamente meno che in passato. Gli spostamenti dei flussi di denaro Il modo migliore per cogliere certi cambiamentiContinue reading...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.article-marketing.eu\/comunicatistampa\/denaro-che-si-sposta-con-la-geopolitica-gli-usa-tirano-molto-di-meno\/\" \/>\n<meta property=\"og:site_name\" content=\"Article Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-08T19:01:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/economia-impresa.info\/wp-content\/uploads\/2024\/04\/denaro_militare_spesa1-630x330.jpg\" \/>\n<meta name=\"author\" content=\"heliricci\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"heliricci\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicatistampa\\\/denaro-che-si-sposta-con-la-geopolitica-gli-usa-tirano-molto-di-meno\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicatistampa\\\/denaro-che-si-sposta-con-la-geopolitica-gli-usa-tirano-molto-di-meno\\\/\"},\"author\":{\"name\":\"heliricci\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/eb0d46093829ff5c8faf8fc7703db387\"},\"headline\":\"Denaro che si sposta con la\u00a0Geopolitica: gli USA tirano molto di meno\",\"datePublished\":\"2026-05-08T19:01:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicatistampa\\\/denaro-che-si-sposta-con-la-geopolitica-gli-usa-tirano-molto-di-meno\\\/\"},\"wordCount\":373,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicatistampa\\\/denaro-che-si-sposta-con-la-geopolitica-gli-usa-tirano-molto-di-meno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/economia-impresa.info\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/denaro_militare_spesa1-630x330.jpg\",\"keywords\":[\"crisi finanziaria del 2008-2009\",\"denaro\",\"indicatori di momentum\"],\"articleSection\":[\"Economia e lavoro\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicatistampa\\\/denaro-che-si-sposta-con-la-geopolitica-gli-usa-tirano-molto-di-meno\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicatistampa\\\/denaro-che-si-sposta-con-la-geopolitica-gli-usa-tirano-molto-di-meno\\\/\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicatistampa\\\/denaro-che-si-sposta-con-la-geopolitica-gli-usa-tirano-molto-di-meno\\\/\",\"name\":\"Denaro che si sposta con la\u00a0Geopolitica: gli USA tirano molto di meno\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicatistampa\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicatistampa\\\/denaro-che-si-sposta-con-la-geopolitica-gli-usa-tirano-molto-di-meno\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicatistampa\\\/denaro-che-si-sposta-con-la-geopolitica-gli-usa-tirano-molto-di-meno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/economia-impresa.info\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/denaro_militare_spesa1-630x330.jpg\",\"datePublished\":\"2026-05-08T19:01:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/eb0d46093829ff5c8faf8fc7703db387\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicatistampa\\\/denaro-che-si-sposta-con-la-geopolitica-gli-usa-tirano-molto-di-meno\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.article-marketing.eu\\\/comunicatistampa\\\/denaro-che-si-sposta-con-la-geopolitica-gli-usa-tirano-molto-di-meno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicatistampa\\\/denaro-che-si-sposta-con-la-geopolitica-gli-usa-tirano-molto-di-meno\\\/#primaryimage\",\"url\":\"https:\\\/\\\/economia-impresa.info\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/denaro_militare_spesa1-630x330.jpg\",\"contentUrl\":\"https:\\\/\\\/economia-impresa.info\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/denaro_militare_spesa1-630x330.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicatistampa\\\/denaro-che-si-sposta-con-la-geopolitica-gli-usa-tirano-molto-di-meno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicatistampa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Denaro che si sposta con la\u00a0Geopolitica: gli USA tirano molto di meno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicatistampa\\\/#website\",\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicatistampa\\\/\",\"name\":\"Article Marketing\",\"description\":\"article marketing &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicatistampa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/eb0d46093829ff5c8faf8fc7703db387\",\"name\":\"heliricci\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c6d7bd728cdc2edbc0952c2d33ef684ae63b49979e1912fdf2804320fb36a0d6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c6d7bd728cdc2edbc0952c2d33ef684ae63b49979e1912fdf2804320fb36a0d6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c6d7bd728cdc2edbc0952c2d33ef684ae63b49979e1912fdf2804320fb36a0d6?s=96&d=mm&r=g\",\"caption\":\"heliricci\"},\"url\":\"https:\\\/\\\/www.article-marketing.eu\\\/comunicatistampa\\\/author\\\/heliricci\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Denaro che si sposta con la\u00a0Geopolitica: gli USA tirano molto di meno","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.article-marketing.eu\/comunicatistampa\/denaro-che-si-sposta-con-la-geopolitica-gli-usa-tirano-molto-di-meno\/","og_locale":"it_IT","og_type":"article","og_title":"Denaro che si sposta con la\u00a0Geopolitica: gli USA tirano molto di meno","og_description":"Con lo scoppio del conflitto in Medio Oriente lo scenario sui mercati \u00e8 cambiato. Il mercato dei capitali si adegua al periodo incerto, ridisegnando l&#8217;allocazione del denaro attraverso le varie asset class e i diversi territori. Le dinamiche pi\u00f9 evidenti si possono osservare riguardano la maggiore cautela verso gli USA, che tirano decisamente meno che in passato. Gli spostamenti dei flussi di denaro Il modo migliore per cogliere certi cambiamentiContinue reading...","og_url":"https:\/\/www.article-marketing.eu\/comunicatistampa\/denaro-che-si-sposta-con-la-geopolitica-gli-usa-tirano-molto-di-meno\/","og_site_name":"Article Marketing","article_published_time":"2026-05-08T19:01:30+00:00","og_image":[{"url":"https:\/\/economia-impresa.info\/wp-content\/uploads\/2024\/04\/denaro_militare_spesa1-630x330.jpg","type":"","width":"","height":""}],"author":"heliricci","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"heliricci","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.article-marketing.eu\/comunicatistampa\/denaro-che-si-sposta-con-la-geopolitica-gli-usa-tirano-molto-di-meno\/#article","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicatistampa\/denaro-che-si-sposta-con-la-geopolitica-gli-usa-tirano-molto-di-meno\/"},"author":{"name":"heliricci","@id":"https:\/\/www.article-marketing.eu\/comunicatistampa\/#\/schema\/person\/eb0d46093829ff5c8faf8fc7703db387"},"headline":"Denaro che si sposta con la\u00a0Geopolitica: gli USA tirano molto di meno","datePublished":"2026-05-08T19:01:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicatistampa\/denaro-che-si-sposta-con-la-geopolitica-gli-usa-tirano-molto-di-meno\/"},"wordCount":373,"commentCount":0,"image":{"@id":"https:\/\/www.article-marketing.eu\/comunicatistampa\/denaro-che-si-sposta-con-la-geopolitica-gli-usa-tirano-molto-di-meno\/#primaryimage"},"thumbnailUrl":"https:\/\/economia-impresa.info\/wp-content\/uploads\/2024\/04\/denaro_militare_spesa1-630x330.jpg","keywords":["crisi finanziaria del 2008-2009","denaro","indicatori di momentum"],"articleSection":["Economia e lavoro"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.article-marketing.eu\/comunicatistampa\/denaro-che-si-sposta-con-la-geopolitica-gli-usa-tirano-molto-di-meno\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.article-marketing.eu\/comunicatistampa\/denaro-che-si-sposta-con-la-geopolitica-gli-usa-tirano-molto-di-meno\/","url":"https:\/\/www.article-marketing.eu\/comunicatistampa\/denaro-che-si-sposta-con-la-geopolitica-gli-usa-tirano-molto-di-meno\/","name":"Denaro che si sposta con la\u00a0Geopolitica: gli USA tirano molto di meno","isPartOf":{"@id":"https:\/\/www.article-marketing.eu\/comunicatistampa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.article-marketing.eu\/comunicatistampa\/denaro-che-si-sposta-con-la-geopolitica-gli-usa-tirano-molto-di-meno\/#primaryimage"},"image":{"@id":"https:\/\/www.article-marketing.eu\/comunicatistampa\/denaro-che-si-sposta-con-la-geopolitica-gli-usa-tirano-molto-di-meno\/#primaryimage"},"thumbnailUrl":"https:\/\/economia-impresa.info\/wp-content\/uploads\/2024\/04\/denaro_militare_spesa1-630x330.jpg","datePublished":"2026-05-08T19:01:30+00:00","author":{"@id":"https:\/\/www.article-marketing.eu\/comunicatistampa\/#\/schema\/person\/eb0d46093829ff5c8faf8fc7703db387"},"breadcrumb":{"@id":"https:\/\/www.article-marketing.eu\/comunicatistampa\/denaro-che-si-sposta-con-la-geopolitica-gli-usa-tirano-molto-di-meno\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.article-marketing.eu\/comunicatistampa\/denaro-che-si-sposta-con-la-geopolitica-gli-usa-tirano-molto-di-meno\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.article-marketing.eu\/comunicatistampa\/denaro-che-si-sposta-con-la-geopolitica-gli-usa-tirano-molto-di-meno\/#primaryimage","url":"https:\/\/economia-impresa.info\/wp-content\/uploads\/2024\/04\/denaro_militare_spesa1-630x330.jpg","contentUrl":"https:\/\/economia-impresa.info\/wp-content\/uploads\/2024\/04\/denaro_militare_spesa1-630x330.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.article-marketing.eu\/comunicatistampa\/denaro-che-si-sposta-con-la-geopolitica-gli-usa-tirano-molto-di-meno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.article-marketing.eu\/comunicatistampa\/"},{"@type":"ListItem","position":2,"name":"Denaro che si sposta con la\u00a0Geopolitica: gli USA tirano molto di meno"}]},{"@type":"WebSite","@id":"https:\/\/www.article-marketing.eu\/comunicatistampa\/#website","url":"https:\/\/www.article-marketing.eu\/comunicatistampa\/","name":"Article Marketing","description":"article marketing &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.article-marketing.eu\/comunicatistampa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.article-marketing.eu\/comunicatistampa\/#\/schema\/person\/eb0d46093829ff5c8faf8fc7703db387","name":"heliricci","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c6d7bd728cdc2edbc0952c2d33ef684ae63b49979e1912fdf2804320fb36a0d6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c6d7bd728cdc2edbc0952c2d33ef684ae63b49979e1912fdf2804320fb36a0d6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c6d7bd728cdc2edbc0952c2d33ef684ae63b49979e1912fdf2804320fb36a0d6?s=96&d=mm&r=g","caption":"heliricci"},"url":"https:\/\/www.article-marketing.eu\/comunicatistampa\/author\/heliricci\/"}]}},"_links":{"self":[{"href":"https:\/\/www.article-marketing.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/32436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.article-marketing.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.article-marketing.eu\/comunicatistampa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicatistampa\/wp-json\/wp\/v2\/users\/7116"}],"replies":[{"embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicatistampa\/wp-json\/wp\/v2\/comments?post=32436"}],"version-history":[{"count":2,"href":"https:\/\/www.article-marketing.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/32436\/revisions"}],"predecessor-version":[{"id":32486,"href":"https:\/\/www.article-marketing.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/32436\/revisions\/32486"}],"wp:attachment":[{"href":"https:\/\/www.article-marketing.eu\/comunicatistampa\/wp-json\/wp\/v2\/media?parent=32436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicatistampa\/wp-json\/wp\/v2\/categories?post=32436"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.article-marketing.eu\/comunicatistampa\/wp-json\/wp\/v2\/tags?post=32436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}